{"id":11360,"date":"2013-01-31T17:07:15","date_gmt":"2013-01-31T17:07:15","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=11360"},"modified":"2020-02-14T12:34:15","modified_gmt":"2020-02-14T11:34:15","slug":"live-demonstration-der-lunar-simulation","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/live-demonstration-der-lunar-simulation-1011360\/","title":{"rendered":"Live-Demonstration der Lunar Simulation"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"ProfitBricks stellt skalierbare IT-Ressourcen, einfache Konfigurations- und Verwaltungsm\u00f6glichkeiten sowie 24\/7-Betreuung durch erfahrene Systemadministratoren zur Verf\u00fcgung. \" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/01\/postie-media267-150x150.jpg\" width=\"115\" height=\"115\" \/><\/p> <p>Aus der Wolke zum Mond<\/p> <p>&#8211; Part-Time Scientists stellen auf der Campus Party Brasil, der weltweit gr\u00f6\u00dften Live-Veranstaltung der digitalen Community, ihre Lunar Simulationsumgebung vor<br \/> &#8211; Cloud-Technologie von ProfitBricks erm\u00f6glicht Berechnungen f\u00fcr die Darstellung der Mondoberfl\u00e4che mit echten H\u00f6hendaten auf der Basis echter Fotos<br \/> &#8211; Weiterer wichtiger Meilenstein f\u00fcr das Ziel der jungen Wissenschaftler ist es, 2014 eine \u00fcberwiegend privat finanzierte unbemannte Mondmission zu starten<\/p> <p><!--more-->Das Wissenschaftler- und Vision\u00e4r-Netzwerk Part-Time Scientists demonstriert auf der diesj\u00e4hrigen Campus Party Brasil vom 28. Januar bis 3. Februar in Sao Paulo seine Lunar Simulationsumgebung. Sie wird auf der Basis bestehenden Bildmaterials vom Mond dessen Oberfl\u00e4che mit echten H\u00f6hendaten in einer Aufl\u00f6sung von bis zu 1,5 Metern pro Pixel simulieren. Die daf\u00fcr notwendigen komplexen physikalischen Berechnungen erfolgen in NVIDIA-Grafikprozessor-Einheiten (GPU) mithilfe der Cloud-Computing Technologie von ProfitBricks.<\/p> <p>Die Campus Party gilt mit 250.000 Teilnehmern als weltweit gr\u00f6\u00dftes Event f\u00fcr Innovation, Wissenschaft, Kreativit\u00e4t und digitale Unterhaltung. Gleichzeitig ist es eines der wenigen physischen Treffen der digitalen Community, der gro\u00dfen Unternehmen und der \u00f6ffentlichen Verwaltung.<\/p> <p>Part-Time Scientists ist der deutsche Google-Lunar-X-PRIZE Teilnehmer mit dem Ziel, eine zu neunzig Prozent privat finanzierte Mondmission durchzuf\u00fchren. Der von Part-Time Scientists entwickelte Mondrover Asimov soll im Fr\u00fchjahr 2014 autonom die Mondoberfl\u00e4che erkunden. Die Simulation der gesamten Mondoberfl\u00e4che ist daf\u00fcr ein wesentlicher Meilenstein, um die webbasierte Steuerung des Rover zu erm\u00f6glichen. Die Simulation l\u00e4sst sich \u00fcber das Internet steuern. Das hat den Vorteil, dass man Simulation und Benutzer trennen kann. Sowohl Programme wie die k\u00fcnftigen Fahrer des Rover k\u00f6nnen so die Oberfl\u00e4che des Erdtrabanten buchst\u00e4blich &#8222;erfahren&#8220; und selbst komplexe, l\u00e4ngere Missionen vorab durchspielen.<\/p> <p>Die Simulationen werden in einem virtuellen Rechenzentrum mit der Technologie von ProfitBricks gerechnet, die als Infrastructure as a Service (IaaS) aufgesetzt ist. &#8222;Wir ben\u00f6tigten eine flexible Serverinfrastruktur, die leicht zu verwalten ist und uns erlaubt, schnell und einfach Dienste f\u00fcr unser st\u00e4ndig wachsendes Team bereitzustellen&#8220;, erl\u00e4utert Robert Boehme von Part-Time Scientists die Entscheidung f\u00fcr ProfitBricks. &#8222;Vom Intranet \u00fcber Dokumente- und Quellcodeverwaltung bis hin zu unserem Web-Auftritt bietet uns ProfitBricks hierf\u00fcr die schnellste und unkomplizierteste L\u00f6sung.&#8220;<\/p> <p>Am 30. Januar 2013 um 17:00 Uhr MEZ (14:00 Uhr Ortszeit) hat das Team von Part-Time Scientists im Rahmen eines Vortrags vor ca. 5.000 Zuh\u00f6rern mit einer Live-\u00dcbertragung die neue GPU-basierte Lunar Simulationsumgebung vorgestellt. Unter den G\u00e4sten war auch der zweite Mann auf dem Mond, Buzz Aldrin.<\/p> <p>Die Live-Demonstration der Lunar Simulation fand auf einer entsprechend gehosteten GPU-Workstation von ProfitBricks statt.<\/p> <p>\u00dcber Part-Time Scientists<br \/> Die Part-Time-Scientists GmbH wurde am 04.03.2010 gegr\u00fcndet. Unter dem Namen &#8222;Part-Time Scientists&#8220; nimmt das mittlerweile rund 100-k\u00f6pfige Team seit dem 24. Juni 2009 offiziell am mit insgesamt 30 Millionen US-Dollar dotierten Google Lunar X-Prize teil. Weitere Informationen unter www.part-time-scientists.com und www.facebook.com\/PartTimeScientists.<\/p> <p>\u00dcber ProfitBricks<br \/> ProfitBricks GmbH wurde Ende 2010 von Achim Wei\u00df und Andreas Gauger, zwei Pionieren der Hosting-Branche, gegr\u00fcndet und besch\u00e4ftigt derzeit rund 115 Mitarbeiter aus 20 Nationen. Das Angebot: ProfitBricks stellt skalierbare IT-Ressourcen, einfache Konfigurations- und Verwaltungsm\u00f6glichkeiten sowie 24\/7-Betreuung durch erfahrene Systemadministratoren zur Verf\u00fcgung. Die Kunden zahlen minutengenau, d.h. nur f\u00fcr tats\u00e4chlich in Anspruch genommene Leistungen. ProfitBricks Dienste und Rechenzentren unterliegen den strengen deutschen Datenschutzbestimmungen und Sicherheitsrichtlinien. Weitere Informationen unter www.profitbricks.com.<\/p> <p>Ansprechpartner f\u00fcr weitere Informationen und Bildmaterial:<br \/> Part-Time-Scientists GmbH<br \/> Kaulsdorfer Str 13A<br \/> 12621 Berlin<\/p> <p>Allgemeiner Kontakt:<br \/> Robert B\u00f6hme<br \/> Tel.: 030 64836739<br \/> Mobil: 0174 4541268<\/p> <p>Pressekontakt:<br \/> Sven Wehlan<br \/> Mobil: 0174 9433608<\/p> <p>ProfitBricks GmbH<br \/> Petra-Maria Grohs<br \/> Vice President Sales, Marketing, HR<br \/> Greifswalder Str. 207<br \/> D -10405 Berlin<br \/> +49 (0)30 939 34 340<br \/> press@profitbricks.com<\/p> <p>Kontakt:<br \/> ProfitBricks GmbH<br \/> Petra-Maria Grohs<br \/> Greifswalder Stra\u00dfe 207<br \/> 10405 Berlin<br \/> +49 (0)30 939 34 340<br \/> press@profitbricks.com<br \/> http:\/\/www.profitbricks.com<\/p>","protected":false},"excerpt":{"rendered":"<p>Aus der Wolke zum Mond &#8211; Part-Time Scientists stellen auf der Campus Party Brasil, der weltweit gr\u00f6\u00dften Live-Veranstaltung der digitalen Community, ihre Lunar Simulationsumgebung vor &#8211; Cloud-Technologie von ProfitBricks erm\u00f6glicht Berechnungen f\u00fcr die Darstellung der Mondoberfl\u00e4che mit echten H\u00f6hendaten auf der Basis echter Fotos &#8211; Weiterer wichtiger Meilenstein f\u00fcr das Ziel der jungen Wissenschaftler ist<\/p>\n","protected":false},"author":1,"featured_media":152847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[134],"class_list":["post-11360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technik","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/11360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=11360"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/11360\/revisions"}],"predecessor-version":[{"id":266555,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/11360\/revisions\/266555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152847"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=11360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=11360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=11360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}