{"id":11861,"date":"2013-02-04T08:54:51","date_gmt":"2013-02-04T08:54:51","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=11861"},"modified":"2013-02-05T15:03:30","modified_gmt":"2013-02-05T14:03:30","slug":"zeichen-in-sachen-umweltschutz","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/zeichen-in-sachen-umweltschutz-1011861\/","title":{"rendered":"Zeichen in Sachen Umweltschutz"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Die BAMAKA ist die gr\u00f6\u00dfte Einkaufsgesellschaft der deutschen Bauwirtschaft.\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/02\/postie-media149-150x150.jpg\" width=\"122\" height=\"122\" \/>Neue Initiative f\u00fcr die Umwelt:<\/p> <p>Zimmerer und Energie-Netzwerk C.A.R.M.E.N. nutzen gemeinsame Synergien &#8211; Klimaholzw\u00fcrfel in Straubing vorgestellt<br \/> Bayerns Zimmerer starten das neue Jahr mit einer weiteren Initiative f\u00fcr die Umwelt. Am Montag, den 4. Februar 2013 tritt der Landesinnungsverband des Bayerischen Zimmererhandwerks dem Verein C.A.R.M.E.N in Straubing bei. &#8222;C.A.R.M.E.N. ist das Centrale- Agrar-Rohstoff-Marketing- und Energie-Netzwerk e.V., wurde 1992 als Koordinierungsstelle f\u00fcr Nachwachsende Rohstoffe in Straubing gegr\u00fcndet, also der perfekte Partner f\u00fcr uns&#8220;, so Bayerns Zimmerer-Pr\u00e4sident Peter Aicher. <!--more-->Durch diesen Beitritt des Landesinnungsverbandes des Bayerischen Zimmererhandwerks profitieren beide Seiten: &#8222;C.A.R.M.E.N. erweitert sein Netzwerk um \u00fcber 1.400 Zimmerei- und Holzbaubetriebe und wir bekommen eine Plattform f\u00fcr den Holzbau&#8220;, so Aicher.<\/p> <p>Der gemeinn\u00fctzige Verein C.A.R.M.E.N. ist mit seinen 70 Mitgliedern aus allen Teilen der Wertsch\u00f6pfungskette nachwachsender Rohstoffe deutschlandweit eine gefragte Anlaufstelle f\u00fcr Informationen zur industriellen und energetischen Nutzung von Biomasse und den Themenfeldern Windenergie, Solarenergie, Geothermie, Wasserkraft sowie Energie- und Ressourceneinsparung. Beh\u00f6rden, Wissenschaft, Wirtschaft, Landwirtschaft und Verbraucher werden von dem Verein gleicherma\u00dfen beraten.<\/p> <p>Bei der feierlichen Beitrittsunterzeichnung hat Zimmerer-Pr\u00e4sident Peter Aicher symbolisch den Klima-Holzw\u00fcrfel an Helmut Brunner, Staatsminister f\u00fcr Ern\u00e4hrung, Landwirtschaft und Forsten, \u00fcbergeben. Der W\u00fcrfel hat eine Kantenl\u00e4nge von 1m und steht damit f\u00fcr 1 m3 Holz. Und er ist f\u00fcr Peter Aicher das Symbol f\u00fcr Umweltschutz. &#8222;Ein einziger Kubikmeter Holz setzt 300 Kubikmeter Sauerstoff frei und liefert so die Grundlage f\u00fcr das Leben auf der Welt. Und er symbolisiert die Menge Holz, die in jeder Sekunde in Bayerns W\u00e4ldern nachw\u00e4chst und damit eine Tonne Kohlendioxid bindet.&#8220;<\/p> <p>Mit dem Beitritt zur Bayerischen Klima-Allianz hat der Landesinnungsverband des Bayerischen Zimmererhandwerks bereits im vergangenen Jahr ein Zeichen in Sachen Umweltschutz gesetzt. Rund um das Thema Klimaschutz und Energieeffizienz dreht sich auch alles auf der Bayerischen Klimawoche. Diese findet in diesem Jahr vom 21. bis zum 28. April 2013 zum sechsten Mal an zahlreichen Orten Bayerns statt. Den Auftakt findet dieses Jahr im Rahmen der &#8222;Energie f\u00fcr alle Woche&#8220; in Pfaffenhofen a. d. Ilm statt.<\/p> <p>Bildrechte: Foto: Bayerisches Staatsministerium f\u00fcr Ern\u00e4hrung, Landwirtschaft und Forsten<\/p> <p>Seit 1947 vertritt der Landesinnungsverband des Bayerischen Zimmererhandwerks die Interessen der angeschlossenen Innungen, Fachgruppen und Mitgliedsbetriebe in vielf\u00e4ltiger Weise.<\/p> <p>Kontakt:<br \/> Landesinnungsverband des Bayerischen Zimmererhandwerks<br \/> Habla<br \/> Eisenacher Stra\u00dfe 17<br \/> 80804 M\u00fcnchen<br \/> 089 &#8211; 3 60 85-1 00<br \/> ahabla@zimmerer-bayern.com<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.zimmerer-bayern.com\/index.php\" title=\"Zentralverband Deutsches Baugewerbe (ZDB) in Berlin\" >http:\/\/www.zimmerer-bayern.com\/index.php<\/a><\/p> <p>Pressekontakt:<br \/> mbw<br \/> J\u00f6rg Gruner<br \/> Max Josephstra\u00dfe 5<br \/> 80333 M\u00fcnchen<br \/> 089 55 178 398<br \/> joerg.gruner@mbw-team.de<br \/> http:\/\/www.mbw-team.de\/<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Neue Initiative f\u00fcr die Umwelt: Zimmerer und Energie-Netzwerk C.A.R.M.E.N. nutzen gemeinsame Synergien &#8211; Klimaholzw\u00fcrfel in Straubing vorgestellt Bayerns Zimmerer starten das neue Jahr mit einer weiteren Initiative f\u00fcr die Umwelt. Am Montag, den 4. Februar 2013 tritt der Landesinnungsverband des Bayerischen Zimmererhandwerks dem Verein C.A.R.M.E.N in Straubing bei. &#8222;C.A.R.M.E.N. ist das Centrale- Agrar-Rohstoff-Marketing- und Energie-Netzwerk<\/p>\n","protected":false},"author":1,"featured_media":152862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[134],"class_list":["post-11861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-umwelt-klima-energie","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/11861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=11861"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/11861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152862"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=11861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=11861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=11861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}