{"id":1201,"date":"2011-05-31T10:27:03","date_gmt":"2011-05-31T09:27:03","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=1201"},"modified":"2015-06-13T11:46:50","modified_gmt":"2015-06-13T10:46:50","slug":"buchveroeffentlichung-sterben","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/buchveroeffentlichung-sterben-101201\/","title":{"rendered":"Voller Respekt f\u00fcr das Leben, das Sterben und das Danach"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><\/td> <\/tr> <\/tbody> <\/table> <p>Wie ist das Sterben? Was erwartet mich, wenn ich tot bin? Gibt es ein Jenseits? Diesen Fragen hat sich der Autor Ingolf Ludmann-Schneider in seinem Erstlingswerk gewidmet, um herauszufinden, was uns nach dem irdischen Leben erwarten k\u00f6nnte.<br \/> Mithilfe der Tierkommunikation gelang es ihm, Kontakt zu Tieren, Pflanzen und dem Universum aufzunehmen und die Fragen, die uns Menschen bewegen und \u00e4ngstigen, zu stellen. Die erhaltenen Antworten hat er, ohne die Absicht diese Aussagen als verbindlich darzustellen, in seinem Buch aufgezeichnet.<br \/> <!--more-->Der Autor arbeitet seit vielen Jahren als Altenpfleger und Sterbebegleiter. Er kennt das Sterben. Auch seine eigene Geschichte ist gepr\u00e4gt von Verlust &#8211; dem seiner leiblichen Mutter, die ihn aus gesundheitlichen Gr\u00fcnden in ein Kinderheim geben musste und auch durch den fr\u00fchen Tod seines Bruders. Als Alkoholiker sah er sich selbst oftmals am Rande des Lebens, k\u00e4mpfte sich aber aus eigener Kraft aus diesem Teufelskreis heraus und ist heute seit 10 Jahren \u201etrocken\u201c. Geblieben ist ihm die Frage: \u201eWo gehen wir eigentlich hin, wenn wir sterben?\u201c Diese Frage konnte ihm beantwortet werden: Mithilfe der Tierkommunikation lernte er mit verstorbenen Tieren, sp\u00e4ter auch mit Menschen, Pflanzen und dem Universum, Kontakt aufzunehmen.<br \/> In seinem Buch schreibt er die beeindruckenden Antworten der befragten Lebensformen und die Berichte \u00fcber eigene Erfahrungen mit dem Sterben nieder. Sie bewegen den Leser, daf\u00fcr Respekt zu haben \u2013 Respekt vor dem Leben, Respekt vor dem Sterben und den Sterbenden. Eine leicht zu lesende und wundersch\u00f6n erz\u00e4hlte Erfahrung, die Angst davor nimmt, einen Angeh\u00f6rigen oder ein Tier auf dem letzen Weg zu begleiten, die auch die Angst vor dem eigenen letzen Weg nimmt.<br \/> Es ist ein sehr einf\u00fchlsames Buch, das voller Respekt \u00fcber das Leben, das Sterben und das Danach erz\u00e4hlt.<br \/> Zum Autor:<br \/> Ingolf Ludmann-Schneider wurde am 1968 in Berlin geboren. Schon seit seiner Kindheit ist das Leben des Autors gepr\u00e4gt von Verlust, Schmerz und Tod. Da seine leibliche Mutter schwer krank war, entschloss sie sich schweren Herzens, ihn wegzugeben. So wuchs er in einem Kinderheim in der ehemaligen DDR auf, bis ihm Adoptiveltern ein gl\u00fcckliches und beh\u00fctetes Zuhause gaben.<br \/> In einer th\u00fcringischen Kleinstadt aufgewachsen, katholisch erzogen und mit vielen offenen Fragen im Kopf, f\u00fchrte ihn sein Weg in den Orden der Franziskaner, dem er auch heute noch tief verbunden ist. Er wollte Missionar werden, doch das war in der DDR nicht m\u00f6glich. So floh er in den neunziger Jahren \u00fcber Prag in die Bundesrepublik. Dort angekommen, lehnte der Orden ab, ihn aufzunehmen.<br \/> Als er Ende der neunziger Jahre sein Coming Out bekannt gab, musste er oftmals Vorurteile und Diskriminierungen erfahren, die ihn in die Alkoholsucht trieben. Nach Jahren zwischen Sucht und Gelegenheitsjobs, halfen ihm sein starker Wille, die Familie und Freunde einen Ausweg zu finden. Mittlerweile ist er seit 10 Jahren \u201etrocken\u201c. Tief gepr\u00e4gt hat ihn auch der fr\u00fche Tod seines Bruders \u2013 er wurde nur einige Wochen alt.<br \/> Geblieben ist ein tiefer Respekt gegen\u00fcber dem Leben und die Frage: \u201eWo gehen wir eigentlich hin, wenn wir sterben?\u201c. Diese Frage konnte ihm beantwortet werden: Mithilfe der Tierkommunikation lernte er mit verstorbenen Tieren, sp\u00e4ter auch mit Menschen, Pflanzen und dem Universum, Kontakt aufzunehmen. Diese Gespr\u00e4che hat er, auf vielfachen Wunsch von Bekannten, Freunden und Angeh\u00f6rigen, jetzt in seinem Erstlingswerk \u201e Sterben, Tod und Jenseits\u201c zusammengefasst.<br \/> Das Buch erscheint am 23.06.2011 in der Buchlader &#8211; Edition Pax et Bonum, deren Herausgeber Ingolf Ludmann-Schneider ist.<br \/> Ingolf Ludmann-Schneider<br \/> Sterben, Tod und Jenseits<br \/> Gedanken der Tiere, Pflanzen, Menschen und des Universums<br \/> 180 Seiten, Softcover , 19 x 13,5 cm, mit zahlreichen Abbildungen<br \/> VKP: 14,50 \u20ac<br \/> ISBN 9783941809079<br \/> ET: 23.06.2011<br \/> www.buch-sterben-tod-jenseits.de<br \/> Pressekontakt:<br \/> Ingolf Ludmann-Schneider<br \/> Paretzer Str.2<br \/> 10713 Berlin<br \/> Tel: 030-822 38 30<br \/> E-Mail: info@pax-et-bonum.net<br \/> www.buch-sterben-tod-jenseits.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Wie ist das Sterben? Was erwartet mich, wenn ich tot bin? Gibt es ein Jenseits? Diesen Fragen hat sich der Autor Ingolf Ludmann-Schneider in seinem Erstlingswerk gewidmet, um herauszufinden, was uns nach dem irdischen Leben erwarten k\u00f6nnte. Mithilfe der Tierkommunikation gelang es ihm, Kontakt zu Tieren, Pflanzen und dem Universum aufzunehmen und die Fragen, die<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[],"class_list":["post-1201","post","type-post","status-publish","format-standard","hentry","category-kultur-kunst-literatur"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/1201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=1201"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/1201\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=1201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=1201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=1201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}