{"id":14448,"date":"2013-02-13T10:29:38","date_gmt":"2013-02-13T10:29:38","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=14448"},"modified":"2013-02-13T16:27:59","modified_gmt":"2013-02-13T15:27:59","slug":"vom-faustkeil-bis-zum-streitwagen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/vom-faustkeil-bis-zum-streitwagen-1014448\/","title":{"rendered":"Vom Faustkeil bis zum Streitwagen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Peter W.F. Heller, 1948 in Berlin geboren, promovierter Arch\u00e4ologe, studierte Wirtschafts-, Religions- und Altertumswissenschaften. \" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/02\/postie-media1124-150x150.jpg\" width=\"128\" height=\"128\" \/>Die Macht der Pharaonen &#8211; Waffen und Milit\u00e4r im alten \u00c4gypten<\/p> <p>Aktuell auf der Leipziger Buchmesse: Arch\u00e4ologe Dr. Peter W.F. Heller ver\u00f6ffentlich ein hochinteressantes Buch \u00fcber Waffen und Milit\u00e4r im alten \u00c4gypten.<br \/> Dr. Peter W.F. Heller untersucht in diesem popul\u00e4rwissenschaftlichen Werk spannend und unterhaltsam das alt\u00e4gyptische Waffen- und Milit\u00e4rwesen. In angemessener Balance zwischen Allgemeinverst\u00e4ndlichkeit und wissenschaftlicher Korrektheit erschlie\u00dft er den Lesern einen Teil der geheimnisvollen Welt der Pharaonen.<br \/> <!--more-->Der Autor beschreibt die Entwicklung der \u00e4gyptischen Waffen vom Faustkeil bis zur mobilen Kampfplattform, dem Streitwagen, und den Weg von der Jagdgemeinschaft bis zum stehenden Heer. Womit machten sich die Pharaonen zu Siegern und womit wurden sie besiegt? Was war das Geheimnis des \u00e4gyptischen Streitwagens? Und welche Rolle spielte das sagenumwobene Sichelschwert?<br \/> Mit diesem Werk gibt Heller erneut einen tiefen Einblick in die facettenreiche Geschichte \u00c4gyptens. Und nicht immer erweist sich am Ende als Wahrheit, was man anfangs glaubt zu sehen.<br \/> Der Autor weiterer popul\u00e4rwissenschaftlicher Werke geht auf Mythen, Feldherren, Eroberer und Kriegsg\u00f6tter ein, um schlie\u00dflich auch die Bedeutung \u00e4gyptischer Namen n\u00e4her zu erl\u00e4utern. Vervollst\u00e4ndigt wird das Werk durch zahlreiche Illustrationen.<\/p> <p>Peter W.F. Heller, 1948 in Berlin geboren, promovierter Arch\u00e4ologe, studierte Wirtschafts-, Religions- und Altertumswissenschaften. Viele Jahre war er erfolgreich als Marketing- und Werbefachmann in deutschen und internationalen Unternehmen t\u00e4tig. Sp\u00e4ter entwickelte und baute er L\u00f6sungen f\u00fcr die elektrosmogfreie Elektroinstallation. Seit Mitte der Neunzigerjahre ist er als freier Arch\u00e4ologe aktiv.<br \/> P. W. F. Heller lebt und arbeitet heute wechselweise in Deutschland, Spanien und China.<\/p> <p>Peter W.F. Heller: &#8222;Die Macht der Pharaonen. Waffen und Milit\u00e4r im alten \u00c4gypten&#8220;<br \/> ISBN 978-3-95488-159-8, 1. Auflage 2013, Engelsdorfer Verlag, Paperback, 473 Seiten, zahlr. sw. Abb., 16,00 EUR<\/p> <p>Den Engelsdorfer Verlag finden Sie auf der Leipziger Buchmesse vom 14. bis 17. M\u00e4rz 2013 in Halle 3 am Stand E308. Mehr unter http:\/\/www.engelsdorfer.verlag.de<br \/> Rezensionsexemplare k\u00f6nnen Medienvertreter direkt beim Verlag unter info@engelsdorfer-verlag.de bestellen!<\/p> <p>Im Jahr 2004 wurde der Engelsdorfer Verlag in Leipzig neu gegr\u00fcndet. Firmeninhaber ist der Schriftsteller Tino Hemmann. Der Verlag ver\u00f6ffentlicht B\u00fccher und eBooks in vielen Genres der Unterhaltung in Klein- und Gro\u00dfauflagen. Er betreibt eine eigene, hochmoderne Digitaldruckerei, um bedarfsgerecht und kosteng\u00fcnstig Printausgaben herstellen zu k\u00f6nnen. Zudem ist er einer der wenigen deutschen Verlage, die noch konzentriert Lyrik und Lyrik\u00fcbersetzungen anbieten. Eines der eingetragenen Warenzeichen des Engelsdorfer Verlages ist die Engelsdorfer Lyrikbibliothek &#8222;LyBi&#8220;. Ende 2012 ver\u00f6ffentlichten \u00fcber 1.600 Vertrags-Autoren aus 26 Nationen im Engelsdorfer Verlag B\u00fccher in allen g\u00e4ngigen Genres. Sitz des Verlages ist in einem Gewerbegebiet unmittelbar an der BAB 14 im Nordwesten der Stadt Leipzig. Seit 2006 wird zirka jede zweite Neuerscheinung auch als eBook ver\u00f6ffentlicht.<\/p> <p>Kontakt:<br \/> Engelsdorfer Verlag<br \/> Hemmann Tino<br \/> Schongauerstra\u00dfe 25<br \/> 04329 Leipzig<br \/> 0341 2711870<br \/> info@engelsdorfer-verlag.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.engelsdorfer-verlag.de\" title=\"Die ver\u00f6ffentlichten Genres reichen vom Roman, Thriller, Krimi, Kinderbuch und romanhafter Biografie bis hin zu Lyrik, Prosa und Kunstb\u00e4nden und wissenschaftlichen B\u00fcchern. \" >http:\/\/www.engelsdorfer-verlag.de<\/a><\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Macht der Pharaonen &#8211; Waffen und Milit\u00e4r im alten \u00c4gypten Aktuell auf der Leipziger Buchmesse: Arch\u00e4ologe Dr. Peter W.F. Heller ver\u00f6ffentlich ein hochinteressantes Buch \u00fcber Waffen und Milit\u00e4r im alten \u00c4gypten. Dr. Peter W.F. Heller untersucht in diesem popul\u00e4rwissenschaftlichen Werk spannend und unterhaltsam das alt\u00e4gyptische Waffen- und Milit\u00e4rwesen. In angemessener Balance zwischen Allgemeinverst\u00e4ndlichkeit und<\/p>\n","protected":false},"author":1,"featured_media":152850,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[130],"tags":[134],"class_list":["post-14448","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archaeologie-geschichte-geographie","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/14448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=14448"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/14448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152850"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=14448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=14448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=14448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}