{"id":14691,"date":"2013-02-13T17:21:03","date_gmt":"2013-02-13T17:21:03","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=14691"},"modified":"2013-02-15T15:26:19","modified_gmt":"2013-02-15T14:26:19","slug":"prinzip-der-optimierten-mischkost","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/prinzip-der-optimierten-mischkost-1014691\/","title":{"rendered":"Prinzip der optimierten Mischkost"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Die Ern\u00e4hrungspyramide f\u00fcr Kleinkinder\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/02\/postie-media1209-150x150.jpg\" width=\"108\" height=\"108\" \/>Kleinkindern\u00e4hrung in Deutschland<\/p> <p>Vom ersten bis zum dritten Lebensjahr entwickeln sich Kinder besonders schnell. Die Ern\u00e4hrung in dieser Zeit ist deshalb sehr wichtig f\u00fcr ein gesundes Wachstum. Verzehrsstudien zeigen jedoch, dass die Kleinkindern\u00e4hrung in Deutschland nicht optimal ist. Mangelnde Expertenempfehlungen und Schwierigkeiten bei der Zubereitung einer auf die Bed\u00fcrfnisse von Kleinkindern abgestimmten Kost verunsichern viele Eltern. Spezielle Kleinkindlebensmittel f\u00fcr Kinder von 1 bis 3 Jahren k\u00f6nnen Orientierung geben und einen Beitrag zu einer ausgewogenen Ern\u00e4hrung leisten.<br \/> <!--more-->Kleinkinder sind keine kleinen Erwachsenen. Um sich gesund zu entwickeln, brauchen sie eine auf ihre Bed\u00fcrfnisse ausgerichtete, optimale N\u00e4hrstoffversorgung. W\u00e4hrend f\u00fcr die ersten zw\u00f6lf Lebensmonate detaillierte Empfehlungen vorliegen, fehlt es in der Altersgruppe der 1- bis 3-J\u00e4hrigen an ausgereiften Konzepten. Ern\u00e4hrungsexperten des Forschungsinstituts f\u00fcr Kinderern\u00e4hrung (FKE) verweisen auf eine frisch zubereitete &#8222;optimierte Mischkost&#8220;. Dieses Ern\u00e4hrungskonzept, das f\u00fcr Kinder- und Jugendliche entwickelt wurde, sieht neben reichlich zuckerfreien Getr\u00e4nken und pflanzlichen Lebensmitteln, m\u00e4\u00dfig tierische, wenig fettreiche Lebensmittel und S\u00fc\u00dfwaren vor. Im Alltag ist die optimierte Mischkost aufgrund von Zeitmangel oft nicht umsetzbar. Die Folge: Orientierungslosigkeit f\u00fchrt in vielen Familien dazu, dass Kleinkinder schon viel zu fr\u00fch eine f\u00fcr sie unausgewogene Erwachsenenkost oder nicht altersgerechte Kinderprodukte zu sich nehmen.<\/p> <p>Wegweiser Alterskennzeichnung<\/p> <p>Die Ratlosigkeit von M\u00fcttern und V\u00e4tern beginnt meist schon am Supermarktregal, wo die Auswahl an Lebensmitteln f\u00fcr Babys und Kleinkinder gro\u00df ist. Viele scheinbar an Kleinkinder gerichtete Produkte sind bunt verpackt &#8211; doch wann ist tats\u00e4chlich welches Produkt geeignet? Professor Dr. med. Martin Wabitsch, Ern\u00e4hrungsexperte und Facharzt f\u00fcr Kinder- und Jugendmedizin am Uniklinikum Ulm, r\u00e4t: &#8222;Besonders wichtig ist zun\u00e4chst die klare Trennung zwischen den Produktkategorien Milchnahrung und Beikost f\u00fcr S\u00e4uglinge, Kleinkindlebensmittel und Kinderlebensmittel. Kleinkinder sind keine Babys mehr, ben\u00f6tigen aber dennoch eine an N\u00e4hrstoffen ausgewogene Kost. Eine Orientierungshilfe, die Eltern deshalb beim Einkauf beachten sollten, sind die Alterskennzeichnungen &#8222;ab 1. Jahr&#8220; oder &#8222;ab 2 Jahren&#8220;, die kleinkindergeeignete Lebensmittel kennzeichnen. Insbesondere ist auch darauf zu achten, dass der Zuckergehalt den Empfehlungen der &#8222;optimierten Mischkost&#8220; entsprechen.&#8220;<\/p> <p>Kleinkindlebensmittel als Baustein einer ausgewogenen und bedarfsgerechten Ern\u00e4hrung<\/p> <p>Aktuelle Befragungen* zeigen, dass rund 80 Prozent der Eltern ihren Kindern zuhause aber auch unterwegs regelm\u00e4\u00dfig Kleinkindlebensmittel geben. Gleichzeitig sind sich aber nur wenige von ihnen \u00fcber den Mehrwert der Produkte bewusst. Als Baustein einer gesunden Ern\u00e4hrung leisten Kleinkindlebensmittel einen wertvollen Beitrag zur Erg\u00e4nzung von frisch zubereiteten Speisen nach dem Prinzip der optimierten Mischkost. Studien wie die des franz\u00f6sischen SFAE** zeigen, dass die N\u00e4hrstoffaufnahme so gezielt gef\u00f6rdert werden kann. Professor Dr. med. Wabitsch r\u00e4t hierzu: &#8222;Vor allem f\u00fcr eine ausreichende Versorgung mit Vitamin D und Jod sind besondere Konzepte erforderlich, da diese N\u00e4hrstoffe oft nicht in ausreichender Menge \u00fcber normale Lebensmittel aufgenommen werden. Kleinkindlebensmittel, insbesondere Kindermilch, k\u00f6nnen hier die N\u00e4hrstoffversorgung verbessern und m\u00f6gliche Imbalancen ausgleichen.&#8220; Doch nicht nur in ihrer N\u00e4hrstoffzusammensetzung unterscheiden sich Kleinkindlebensmittel von Lebensmitteln des allgemeinen Verzehrs. Optimale Portionsgr\u00f6\u00dfen, die richtige Menge an Gew\u00fcrzen, der Verzicht auf Geschmacksverst\u00e4rker und \u00fcberfl\u00fcssige Farbstoffe sind auf den Bedarf der Kleinen abgestimmt. Ein weiterer wichtiger Aspekt: Kleinkindgeeignete Produkte werden nach h\u00f6chsten Qualit\u00e4tsstandards produziert. Eine Tatsache, die gerade verunsicherten Eltern beim bewussten Griff zu Kleinkindlebensmitteln ein gutes und sicheres Gef\u00fchl geben kann.<\/p> <p>Bundesverband der Hersteller von Lebensmitteln f\u00fcr eine besondere Ern\u00e4hrung<\/p> <p>Kontakt<br \/> Di\u00e4tverband<br \/> Eva Pauli<br \/> Godesberger Allee 142 &#8211; 148<br \/> 53175 Bonn<br \/> 06151 &#8211; 159120<br \/> info@bauchgefuehl.com<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.diaetverband.de\" title=\"Bundesverband der Hersteller von Lebensmitteln\" >http:\/\/www.diaetverband.de<\/a><\/p> <p>Pressekontakt:<br \/> Agentur bauchgef\u00fchl<br \/> Eva Pauli<br \/> Dolivostra\u00dfe 9<br \/> 64293 Darmstadt<br \/> 06151 &#8211; 159120<br \/> info@bauchgefuehl.com<br \/> http:\/\/www.bauchgefuehl.com<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Kleinkindern\u00e4hrung in Deutschland Vom ersten bis zum dritten Lebensjahr entwickeln sich Kinder besonders schnell. Die Ern\u00e4hrung in dieser Zeit ist deshalb sehr wichtig f\u00fcr ein gesundes Wachstum. Verzehrsstudien zeigen jedoch, dass die Kleinkindern\u00e4hrung in Deutschland nicht optimal ist. Mangelnde Expertenempfehlungen und Schwierigkeiten bei der Zubereitung einer auf die Bed\u00fcrfnisse von Kleinkindern abgestimmten Kost verunsichern viele<\/p>\n","protected":false},"author":1,"featured_media":152857,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[134],"class_list":["post-14691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernaehrung-wellness-gesundheit","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/14691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=14691"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/14691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152857"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=14691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=14691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=14691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}