{"id":18422,"date":"2013-02-28T16:49:06","date_gmt":"2013-02-28T16:49:06","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=18422"},"modified":"2013-03-01T15:47:07","modified_gmt":"2013-03-01T14:47:07","slug":"erneuter-angriff-auf-die-bezeichnung-bio-mineralwasser-auch-mit-einer-anderen-begruendung-unmoeglich","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/erneuter-angriff-auf-die-bezeichnung-bio-mineralwasser-auch-mit-einer-anderen-begruendung-unmoeglich-1018422\/","title":{"rendered":"Erneuter Angriff auf die Bezeichnung Bio-Mineralwasser auch mit einer anderen Begr\u00fcndung unm\u00f6glich"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"unter welchen Bedingungen ist die Qualit\u00e4ts-Bezeichnung \u201aBio-Mineralwasser\u2018 zul\u00e4ssig?\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/02\/postie-media2606-150x150.jpg\" width=\"134\" height=\"134\" \/>BGH begr\u00fcndet Bio-Mineralwasser-Urteil<\/p> <p>*** Urteil in Sammlung wichtiger Grundsatzurteile aufgenommen<br \/> *** Besondere Reinheit und umweltfreundliche Herstellung sind DIE Bio-Kriterien<br \/> *** Richtlinienzertifizierung durch Verband als Voraussetzung<br \/> *** BGH st\u00e4rkt Rolle der Bio-Anbauverb\u00e4nde<\/p> <p><!--more-->Der Bundesgerichtshof hat jetzt die schriftliche Begr\u00fcndung zu seinem Urteil vom 13.09.2012 ver\u00f6ffentlicht, unter welchen Bedingungen die Qualit\u00e4ts-Bezeichnung &#8218;Bio-Mineralwasser&#8216; zul\u00e4ssig ist:<\/p> <p>Bio-Mineralwasser muss laut dem BGH-Urteil drei Kriterien erf\u00fcllen:<br \/> 1. Bio-Mineralwasser muss weitestgehend frei von R\u00fcckst\u00e4nden und Schadstoffen sein und damit deutlich reiner als herk\u00f6mmliches Mineralwasser.<br \/> 2. Bio-Mineralwasser muss umweltfreundlich hergestellt und abgef\u00fcllt werden &#8211; f\u00fcr herk\u00f6mmliches Mineralwasser gibt es keine Vorschriften.<br \/> 3. Die Zertifizierung muss durch einen Verband nach sinnvollen und angemessenen Kriterien erfolgen.<\/p> <p>Die Urteilsbegr\u00fcndung basiert auf dem Bio-Verst\u00e4ndnis von Verbrauchern und unterstreicht damit wesentliche Argumente der Biomineralwasser-Richtlinien der Qualit\u00e4tsgemeinschaft Biomineralwasser e.V.. Das Gericht sieht signifikante Unterschiede zwischen Bio-Mineralwasser und herk\u00f6mmlichem Mineralwasser; das mit der Bezeichnung verbundene Zertifizierungssystem und der umfangreiche Kriterienkatalog garantieren den Verbrauchern diese Besonderheiten.<\/p> <p>Der BGH hat das Urteil in seine Sammlung wichtiger Grundsatzurteile aufgenommen. Die umfangreiche Argumentation macht einen erneuten Angriff auf die Bezeichnung Bio-Mineralwasser auch mit einer anderen Begr\u00fcndung unm\u00f6glich.<\/p> <p>Die Auflage der Vorinstanz, das verwendete Bio-Mineralwasser-Siegel so zu modifizieren, dass eine Verwechslung mit dem offiziellen EU-Biosiegel f\u00fcr den Verbraucher ausgeschlossen ist, erf\u00fcllt Lammsbr\u00e4u bereits seit Februar 2012. Das &#8218;BioKristall&#8216; der Neumarkter Lammsbr\u00e4u ist damit das erste rechtm\u00e4\u00dfig zertifizierte Bio-Mineralwasser Deutschlands.<\/p> <p>Susanne Horn, Generalbevollm\u00e4chtigte der Neumarkter Lammsbr\u00e4u:<br \/> &#8211; Zur Urteilsbegr\u00fcndung: &#8222;Was Bio-Branchen-Kenner schon lange wussten, best\u00e4tigt jetzt der BGH: Verbraucher verbinden mit &#8218;Bio&#8216; nicht nur weniger Schadstoffe, sondern auch eine umweltfreundliche Gewinnung &#8211; Bio-Siegel m\u00fcssen dies gew\u00e4hrleisten k\u00f6nnen. Dass der BGH das Konzept der Qualit\u00e4tsgemeinschaft Biomineralwasser e.V. im Bereich Mineralwasser hierf\u00fcr zum Standard erkl\u00e4rt, unterstreicht die Ernsthaftigkeit der pr\u00e4zise definierten Richtlinien noch einmal und minimiert das Risiko von &#8218;Bio-Mineralwasser-Light&#8216;-Nachahmern.&#8220;<br \/> &#8211; Zur Bedeutung f\u00fcr Verbraucher: &#8222;R\u00fcckst\u00e4nde sind inzwischen allgegenw\u00e4rtig. Verl\u00e4ssliche Verbands-Zertifizierungen wie das Bio-Mineralwasser-Siegel helfen Verbrauchern, m\u00fcndige Einkaufsentscheidungen zu treffen.&#8220;<br \/> &#8211; Zur Bedeutung f\u00fcr die Bio-Branche: &#8222;Ehrliche Bio-Konzepte in der Tradition der Bio-Anbauverb\u00e4nde haben Zukunft, und zwar auch au\u00dferhalb der EG-Bio-Verordnung.&#8220;<br \/> &#8211; Zur Bedeutung f\u00fcr die Mineralbrunnen-Branche: &#8222;Der Schutz unserer wichtigsten Ressource, dem Wasser, verlangt das Engagement aller. Wir freuen uns daher auf Mitstreiter, die ihre sehr gute Bio-Qualit\u00e4t k\u00fcnftig ebenfalls gegen\u00fcber den Verbrauchern dokumentieren und sich auch \u00f6ffentlich f\u00fcr das wichtigste Lebens-Mittel einsetzen.&#8220;<br \/> &#8211; Zur Bedeutung f\u00fcr &#8218;BioKristall&#8216;: &#8222;Die gewonnene Rechtssicherheit erleichtert uns den Vertrieb; jetzt gibt es im Handel keine Argumente mehr, das erste Bio-Mineralwasser Deutschlands, unser &#8218;BioKristall&#8216;, nicht zu listen.&#8220;<\/p> <p>Zur Chronologie der juristischen Auseinandersetzung:<\/p> <p>&#8211; Oktober 2009: Neumarkter Lammsbr\u00e4u bringt unter dem Namen &#8218;BioKristall&#8216; das erste deutsche Bio-Mineralwasser auf den Markt.<br \/> &#8211; M\u00e4rz 2010: Die private Interessensgemeinschaft &#8222;Wettbewerbszentrale&#8220;, hinter der der Verband Deutscher Mineralbrunnen steht, reicht eine Unterlassungsklage beim Landgericht N\u00fcrnberg ein, um die Qualit\u00e4ts-Auszeichnung &#8218;Bio-Mineralwasser&#8216; verbieten zu lassen.<br \/> &#8211; 19. Januar 2011: Das Landgericht N\u00fcrnberg gibt in erster Instanz der Klage statt (AZ 3 O 819\/10).<br \/> &#8211; M\u00e4rz 2011: Lammsbr\u00e4u geht gegen das Urteil in Revision.<br \/> &#8211; 15. November 2011: Das Oberlandesgericht N\u00fcrnberg-F\u00fcrth gibt der Neumarkter Lammsbr\u00e4u Recht und weist die urspr\u00fcngliche Klage der Wettbewerbszentrale weitestgehend ab (AZ 3 U 354\/11).<br \/> &#8211; Dezember 2011: Die Wettbewerbszentrale geht gegen das Urteil in Revision.<br \/> &#8211; 13. September 2012: Der Bundesgerichtshof weist den Revisionsantrag als ungerechtfertigt ab (AZ I ZR 230\/11).<\/p> <p>Zu Vorgeschichte und Hintergrund:<\/p> <p>Zwei zentrale Entwicklungen der letzten Jahre beeinflussen zunehmend das Verbraucherverhalten:<br \/> &#8211; Die Verbraucher m\u00fcssen t\u00e4glich aus einem gro\u00dfen Angebot von Trink- und Mineralw\u00e4ssern ausw\u00e4hlen; diese W\u00e4sser weisen gro\u00dfe Preisunterschiede und zum Teil gro\u00dfe Unterschiede in der Wasser- und Produktqualit\u00e4t auf, ohne dass dies f\u00fcr den Verbraucher transparent ist. Die Qualit\u00e4tsunterschiede r\u00fchren u.a. daher, dass Schadstoffbelastung und Umweltverschmutzung leider auch vor den Mineralquellen keinen Halt machen. Diese Stoffe m\u00fcssen jedoch nicht auf den Etiketten ausgewiesen werden.<br \/> &#8211; Immer mehr Endkonsumenten w\u00fcnschen f\u00fcr ihre Kaufentscheidung pr\u00e4zise Informationen \u00fcber die Produktions- und Distributionsbedingungen der angebotenen Waren; beim Mineralwasser z\u00e4hlen dazu beispielsweise auch Ma\u00dfnahmen zur Verringerung der Klimagasbelastung.<\/p> <p>Die Neumarkter Lammsbr\u00e4u, deren Produkte sich mit strengen Qualit\u00e4tsanforderungen auf dem Bio-Getr\u00e4nkemarkt eine hohe Reputation erworben haben, setzt sich im Interesse einer wachsenden Zahl kritischer Verbraucher f\u00fcr eine europaweite Bio-Qualit\u00e4tsstufe bei Mineralwasser ein: Ein Bio-Mineralwasser muss f\u00fcr die ganze Familie sicher sein. Es muss strengen Qualit\u00e4tsstandards gen\u00fcgen, damit es t\u00e4glich in unbegrenzter Menge getrunken werden kann. Dabei stehen drei \u00f6kologische Qualit\u00e4tsbereiche im Vordergrund:<br \/> &#8211; Zusammensetzung des Wassers (Produktsicherheit, Schadstoffminimierung),<br \/> &#8211; ein schonender und auf Nachhaltigkeit ausgerichteter Umgang mit der Mineralquelle und ihrer Umgebung,<br \/> &#8211; ressourcenschonende Herstellung und Vertrieb: Verpackung in umweltfreundliche und sichere Gebinde, Verringerung Klimagasaussto\u00df, etc.<br \/> Die Qualit\u00e4tsgemeinschaft Biomineralwasser e.V. hat schon 2009 in diesen drei Bereichen rund 50 pr\u00e4zise Qualit\u00e4tskriterien definiert, die ein Bio-Mineralwasser erf\u00fcllen muss. Die Kriterien sind strenger gefasst als es die bestehenden Regelwerke f\u00fcr Mineralwasser und auch f\u00fcr Quellwasser vorsehen. Eine kontinuierliche \u00dcberpr\u00fcfung der Kriterien durch ein unabh\u00e4ngiges Zertifizierungsinstitut bildet dabei die Grundlage f\u00fcr das Siegel &#8222;Bio-Mineralwasser&#8220;.<\/p> <p>\u00dcber die Neumarkter Lammsbr\u00e4u:<br \/> Neumarkter Lammsbr\u00e4u &#8211; das ist der Inbegriff f\u00fcr feine \u00f6kologische Biere und Bio-Erfrischungsgetr\u00e4nke. Schon vor 30 Jahren stellte Dr. Franz Ehrnsperger, Inhaber der Traditionsbrauerei, die Weichen f\u00fcr ein durchg\u00e4ngiges nachhaltiges Unternehmenskonzept, das seinesgleichen sucht. Die Neumarkter Lammsbr\u00e4u ist die erste Brauerei, die ihr gesamtes Sortiment auf 100% Bio umgestellt hat. Die Rohstoffe stammen aus kontrolliert \u00f6kologischem Anbau aus der Region. Rund um Neumarkt in der Oberpfalz werden dadurch 4.000 ha \u00f6kologisch bewirtschaftet. F\u00fcr die Genie\u00dfer eines Lammsbr\u00e4u-Getr\u00e4nkes bedeutet das: Voller Geschmack, reinster Genuss und die Gewissheit, mit jedem Schluck einen Beitrag zum Umweltschutz zu leisten.<\/p> <p>Bei der weltweit f\u00fchrenden Bio-Brauerei produzieren 104 Mitarbeiter rund 70.000 hl Bier pro Jahr, sowie rund 75.000 hl alkoholfreie Getr\u00e4nke (Bio-Mineralwasser und eine breite Palette von \u00d6ko-Fruchtsaftgetr\u00e4nken). Mit aktuell 19 verschiedenen Sorten bietet die Lammsbr\u00e4u allen Biobierfreunden das breiteste Sortiment des Marktes an, darunter auch Innovationen wie das Alkoholfreie Weizenbier, dessen gesundheitsf\u00f6rdernde Eigenschaften wissenschaftlich best\u00e4tig sind, und glutenfreie Spezialit\u00e4ten.<\/p> <p>Die Neumarkter Lammsbr\u00e4u wurde erstmals 1628 urkundlich erw\u00e4hnt und befindet sich seit rund 200 Jahren im Besitz der Familie Ehrnsperger.<\/p> <p>Mehr \u00fcber die Bio-Bier-Pioniere erfahren Sie unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.lammsbraeu.de\" title=\"Bio-Getr\u00e4nke f\u00fcr jeden Geschmack - aus nat\u00fcrlichen Zutaten mit bester Qualit\u00e4t.\" >www.lammsbraeu.de<\/a>.<\/p> <p>Kontakt<br \/> Neumarkter Lammsbr\u00e4u Gebr\u00fcder Ehrnsperger e.K<br \/> Kathrin Moosburger (Marketing)<br \/> Amberger Stra\u00dfe 1<br \/> 92318 Neumarkt i.d.OPf.<br \/> 09181 404-0<br \/> k.moosburger@lammsbraeu.de<br \/> http:\/\/www.lammsbraeu.de<\/p> <p>Pressekontakt:<br \/> Thomas Pfaff Kommunikation<br \/> Dr. Antonia Green<br \/> H\u00f6chlstr. 2<br \/> 81675 M\u00fcnchen<br \/> 089 992496-51<br \/> kontakt@pfaff-kommunikation.de<br \/> http:\/\/pfaff-kommunikation.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>BGH begr\u00fcndet Bio-Mineralwasser-Urteil *** Urteil in Sammlung wichtiger Grundsatzurteile aufgenommen *** Besondere Reinheit und umweltfreundliche Herstellung sind DIE Bio-Kriterien *** Richtlinienzertifizierung durch Verband als Voraussetzung *** BGH st\u00e4rkt Rolle der Bio-Anbauverb\u00e4nde<\/p>\n","protected":false},"author":1,"featured_media":152917,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[134],"class_list":["post-18422","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recht-steuern","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/18422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=18422"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/18422\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152917"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=18422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=18422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=18422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}