{"id":1933,"date":"2012-01-11T18:10:44","date_gmt":"2012-01-11T17:10:44","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=1933"},"modified":"2012-03-01T07:35:36","modified_gmt":"2012-03-01T06:35:36","slug":"windparks-windenergieanlagen-windraeder","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/windparks-windenergieanlagen-windraeder-101933\/","title":{"rendered":"Windparks-Windenergieanlagen-Windr\u00e4der"},"content":{"rendered":"<p>Unter einem Windpark versteht man die r\u00e4umliche Ansammlung und Anordnung von Windenergieanlagen, d.h. zumeist Windr\u00e4der. W\u00e4hrend baurechtliche Bestimmungen in dicht besiedelten Regionen nur die Errichtung einzelner Windr\u00e4der in gr\u00f6\u00dferen Abst\u00e4nden zulassen, sind Windparks zumeist in d\u00fcnn besiedelten und windreichen Gebieten anzutreffen. Windparks werden nicht nur im Binnenland, sondern h\u00e4ufig auch vor der K\u00fcste auf See als Offshore-Anlage gebaut. <!--more-->Grunds\u00e4tzlich ist eine Ansammlung ab drei Windr\u00e4dern bereits als Windpark definiert, es gibt aber auch Anlagen mit \u00fcber Hundert Windenergieanlagen. Zu unterscheiden sind drei verschiedene Arten von Windparks. Erstens kann ein \u201egewachsener\u201c Park aus mehreren nacheinander erbauten Anlagen bestehen. Zweitens gibt es geplante Windparks, die innerhalb eines einheitlichen Bauvorhabens errichtet wurden. Drittens werden von Beh\u00f6rden Fl\u00e4chen als Windparks ausgewiesen, um den Bau von Windenergieanlagen dort zu f\u00f6rdern und zu konzentrieren.<\/p> <p>&nbsp;<\/p> <p><strong>Genehmigungsverfahren<\/strong><\/p> <p>Laut Beschluss des Bundesverwaltungsgerichts von 2004 muss zur Errichtung eines Windparks, zuvor ein Genehmigungsverfahren durchlaufen werden. Dieses erfolgt auf der Grundlage des Bundes-Immissionsschutzgesetzes, w\u00e4hrend f\u00fcr einzelne Windr\u00e4der nur eine einfache Baugenehmigung erforderlich ist. Einige Detailfragen des Genehmigungsverfahrens sind durch Landesgesetze geregelt, wodurch sich Unterschiede von Bundesland zu Bundesland ergeben. Unterschiedlich geregelt ist vor allem der Mindestabstand, den die Anlagen zur n\u00e4chstgelegenen Wohnbebauung aufweisen m\u00fcssen.<\/p> <p>&nbsp;<\/p> <p><strong>Errichtung und Wartung<\/strong><\/p> <p>Windparks sind, im Vergleich zu einzelnen Windenergieanlagen, zumeist nicht ohne Gro\u00dfinvestoren zu planen und zu bauen. Ihre Errichtung und Wartung weist aber gegen\u00fcber vereinzelten Anlagen Vorteile in Sachen Wirtschaftlichkeit auf. Die Infrastruktur f\u00fcr den Bau, wie z.B. Kr\u00e4ne, Wege, Zugmaschinen, Anlagen, kann f\u00fcr mehrere Windr\u00e4der flexibel genutzt werden. So werden Umr\u00fcstungs- und Transportkosten gespart. Die Wartung kann zentral und lokal konzentriert erfolgen. Es werden Fahrtkosten gespart und die Reaktionszeiten auf St\u00f6rungen werden verk\u00fcrzt.<\/p> <p>&nbsp;<\/p> <p><strong>Vorteile und Probleme beim Betrieb von Windparks<\/strong><\/p> <p>Normalerweise werden Formen erneuerbarer Energien dezentral ins Energienetz eingeleitet, wodurch relativ hohe Kosten entstehen. Bei Windparks ist das anders. Sie k\u00f6nnen wie ein geschlossenes Kraftwerk behandelt werden, und ihre Energieleistung kann zentral und somit g\u00fcnstiger ins Energienetz eingespeist werden. Auch die Leistung der Windenergieanlagen kann bei Parks besser und vor allem zentral gesteuert werden, so dass die tats\u00e4chliche Einspeisungsleistung gut absch\u00e4tzbar ist. Trotzdem kann es zu unterschiedlichen Leistungen einzelner Anlagen kommen, wenn beispielsweise innerhalb eines Windparks unterschiedliche Windgeschwindigkeiten herrschen oder es durch das Ph\u00e4nomen des Windschattens zu einer aerodynamischen Abschattung kommt. Ein noch ungel\u00f6stes Problem ist die regional ungleiche Einspeisung von Windenergie, denn sie wird aufgrund nat\u00fcrlicher Bedingungen in Norddeutschland ungleich h\u00e4ufiger genutzt als in S\u00fcddeutschland. Um die Kapazit\u00e4ten der Windparks f\u00fcr ganz Deutschland zu nutzen, m\u00fcsste das Fernleitungsnetz und Speicherkraftwerke aufgebaut werden.<\/p> <p>&nbsp;<\/p> <p><a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/de.wikipedia.org\/wiki\/Windpark\" title=\"Ein Windpark ist eine r\u00e4umliche Ansammlung von Windenergieanlagen (WEA). Er entsteht durch das vermehrte Aufstellen dieser Anlagen in windreichen Regionen. Windparks lassen sich in folgende Arten einteilen:\" target=\"_blank\"><strong>Beispiele erfolgreicher Windparks<\/strong><\/a><\/p> <p>Vor der K\u00fcste Cuxhavens befindet sich ein Testgel\u00e4nde f\u00fcr Offshore-Windparks, aus dem neue Erkenntnisse f\u00fcr zuk\u00fcnftige Projekte gewonnen werden. Deutschlands erster Windpark wurde 1987 an der Nordseek\u00fcste Schleswig-Holsteins im Kaiser Wilhelm Koog in Betrieb genommen. In Gr\u00f6\u00dfe und Energieleistung wird er vom geplanten Windpark \u201eBaltic 2\u201c in der Ostsee voraussichtlich \u00fcbertroffen werden. Zurzeit befindet sich der gr\u00f6\u00dfte Offshorewindpark vor der Nordseek\u00fcste Englands. Der Park Thanet liefert eine Gesamtleistung von 300 Megawatt. Der gr\u00f6\u00dfte Binnenland-Windpark Europas steht in Rum\u00e4nien. Die \u201eDobrogea Wind Farm\u201c liefert mit 240 Anlagen eine Spitzenleistung von bis zu 600 Megawatt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Unter einem Windpark versteht man die r\u00e4umliche Ansammlung und Anordnung von Windenergieanlagen, d.h. zumeist Windr\u00e4der. W\u00e4hrend baurechtliche Bestimmungen in dicht besiedelten Regionen nur die Errichtung einzelner Windr\u00e4der in gr\u00f6\u00dferen Abst\u00e4nden zulassen, sind Windparks zumeist in d\u00fcnn besiedelten und windreichen Gebieten anzutreffen. Windparks werden nicht nur im Binnenland, sondern h\u00e4ufig auch vor der K\u00fcste auf See<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[],"class_list":["post-1933","post","type-post","status-publish","format-standard","hentry","category-umwelt-klima-energie"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/1933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=1933"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/1933\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=1933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=1933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=1933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}