{"id":19700,"date":"2013-03-11T12:16:54","date_gmt":"2013-03-11T12:16:54","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=19700"},"modified":"2013-03-12T15:10:07","modified_gmt":"2013-03-12T14:10:07","slug":"das-bad-der-zukunft","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/das-bad-der-zukunft-1019700\/","title":{"rendered":"Das Bad der Zukunft"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"\u00dcberraschende Resultate der Forsastudie\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/03\/postie-media485-150x150.jpg\" width=\"150\" height=\"150\" \/>Schneller erneuern<\/p> <p>Deutsche dr\u00fccken im Bad selbst aufs Renovierungstempo \/ Aktuelle forsa-Studie \/ \u00dcberraschende Resultate \/ Bad als R\u00fcckzugsort: gegen Urlaub und Garten gut behauptet \/ Staatliche Umbau-F\u00f6rderung: breites Meinungsspektrum \/ Programme als &#8222;effizientes Modul&#8220;<\/p> <p>Wenn die Bundesb\u00fcrger ihr eigenes Votum auch in die Tat umsetzen, werden Deutschlands B\u00e4der k\u00fcnftig erheblich schneller als bisher von Grund auf erneuert. Diese Konsequenz ergibt sich aus einer aktuellen Repr\u00e4sentativstudie, die das forsa-Institut zur Branchenmesse &#8222;ISH&#8220; f\u00fcr die Vereinigung Deutsche Sanit\u00e4rwirtschaft (VDS) durchf\u00fchrte. <!--more-->Danach sprechen sich 42 % der Bev\u00f6lkerung f\u00fcr eine umfassende Renovierung bereits nach sp\u00e4testens 10 Jahren aus. Ein knappes Drittel davon h\u00e4lt sie sogar schon nach 5 Jahren f\u00fcr angebracht. Weitere 19 % trugen sich, wie es hei\u00dft, in der Kategorie &#8222;nach 11 bis 15 Jahren&#8220; ein. Zum Vergleich: Laut einer Erhebung der Gesellschaft f\u00fcr Konsumforschung (GfK) sind noch nicht renovierte B\u00e4der in Privathaushalten gegenw\u00e4rtig fast zwei Jahrzehnte alt. Bricht jetzt die \u00c4ra wesentlich k\u00fcrzerer Zyklen an?<\/p> <p>Jedenfalls bewertet Jens J. Wischmann das Resultat als &#8222;gro\u00dfe positive \u00dcberraschung&#8220;. Es best\u00e4tigt nach Meinung des Gesch\u00e4ftsf\u00fchrers des Branchen-Dachverbandes zumindest das stark gestiegene Interesse der Bundesb\u00fcrger an individuell geplanten und ausgestatteten sowie kompetent realisierten B\u00e4dern. Schon das schaffe eine &#8222;ausgezeichnete Kommunikations- und Arbeitsbasis&#8220; f\u00fcr den Profi-Verbund aus Industrie, Fachgro\u00dfhandel und Fachhandwerk.<\/p> <p>Zudem liefere die f\u00fcr rund 67 Mio. Deutsche ab 18 Jahre repr\u00e4sentative Untersuchung auch bei der &#8222;Renovierungsfrage&#8220; aufschlussreiche Einzelanalysen. So sei die Quote derer, die im Osten der Republik f\u00fcr eine Modernisierung nach sp\u00e4testens 10 Jahren pl\u00e4dieren, mit 66 % &#8222;extrem hoch&#8220; (Westdeutschland: 38 %). Gleiches gelte f\u00fcr die 18- bis 29-J\u00e4hrigen (63 %) und &#8211; in geringerem Ma\u00dfe &#8211; f\u00fcr die 30- bis 44-J\u00e4hrigen (47 %). Am Ende der Skala rangiere hier mit &#8222;nur&#8220; 32 % die Generation &#8222;60plus&#8220;. Durch gezielte Informationskampagnen wie dem nationalen &#8222;Tag des Bades&#8220; am 14. September 2013 und einer neuen Aktion zum Thema &#8222;Barrierefreie B\u00e4der&#8220; wollen die Sanit\u00e4rspezialisten deshalb u. a. \u00e4ltere Menschen intensiver aufkl\u00e4ren.<\/p> <p>Gesch\u00e4tzter &#8222;Mikrokosmos&#8220;<\/p> <p>Dar\u00fcber hinaus ermittelten die Berliner Sozialforscher, welche Rolle das Bad f\u00fcr die B\u00fcrger in Zukunft als eine Art &#8222;R\u00fcckzugsort&#8220; von der zunehmenden Alltagshektik spielt. F\u00fcr etwa die H\u00e4lfte der Bev\u00f6lkerung wird es in dieser Funktion wichtiger. 18 % stimmen dem &#8222;voll und ganz&#8220; und weitere 29 % &#8222;eher&#8220; zu. &#8222;Damit schneidet der private Mikrokosmos &#8222;Bad&#8220; selbst gegen\u00fcber popul\u00e4ren Entspannungsalternativen wie Urlaub oder Garten sehr gut ab&#8220;, freut sich Wischmann.<\/p> <p>Das treffe besonders h\u00e4ufig auf 30- bis 44-J\u00e4hrige (56 %), Erwerbst\u00e4tige (51 %) und Frauen (50 %) zu. Ferner meldet forsa folgende Tendenz: Je mehr Personen im Haushalt leben bzw. je h\u00f6her das monatliche Haushaltsnettoeinkommen ist, desto h\u00e4ufiger wird der &#8222;R\u00fcckzugsort&#8220;-Charakter des Bades bejaht. Die andere H\u00e4lfte der Deutschen stehe ihm derzeit noch reserviert bzw. ablehnend gegen\u00fcber. &#8222;Das muss aber keineswegs so bleiben&#8220;, relativiert der VDS-Sprecher den Status quo.<\/p> <p>Faktisches Patt<\/p> <p>Im dritten Kapitel der Studie ging es um die eventuelle Absicht der Befragten, ihr jetziges Bad so umzubauen, dass es in allen Lebensphasen und damit auch im Alter uneingeschr\u00e4nkt nutzbar ist. Die Interviewer wollten wissen, welche Bedeutung dann eine staatliche finanzielle F\u00f6rderung z. B. durch Zusch\u00fcsse oder zinsg\u00fcnstige Darlehen f\u00fcr die (Investitions-)Entscheidung hat. Die Quintessenz: Auch hier teilt sich die Bev\u00f6lkerung in zwei gleich gro\u00dfe Lager. W\u00e4hrend 48 % derartige Anreize als &#8222;sehr wichtig&#8220; bzw. &#8222;wichtig&#8220; einstufen, bezeichnen sie 50 % als &#8222;weniger wichtig&#8220; bzw. &#8222;unwichtig&#8220;. Gravierende Abweichungen von dem Gesamtvotum kristallisierten sich laut Wischmann in den unterschiedlichen Analysegruppen (Region, Geschlecht, Alter, Erwerbst\u00e4tigkeit, Haushaltsgr\u00f6\u00dfe und -nettoeinkommen) im Prinzip nicht heraus. Das Pendel schlage abgesehen von einer Ausnahme maximal um jeweils 4 Prozentpunkte nach beiden Seiten aus.<\/p> <p>Per saldo lasse sich jedoch sagen, dass eine sinnvolle staatliche Flankierung durchaus geeignet sei, zum Abbau des erheblichen Defizits an barrierefreien B\u00e4dern konkret beizutragen. Entsprechende Programme des Bundes und der L\u00e4nder k\u00f6nnen daher gerade mit Blick auf den demografischen Wandel bzw. dessen Bew\u00e4ltigung im Bausektor ein &#8222;effizientes Modul&#8220; sein, erkl\u00e4rt die Dachorganisation der Sanit\u00e4rwirtschaft.<\/p> <p>Bildunterschrift<\/p> <p>Wenn die Bundesb\u00fcrger ihr eigenes Votum auch in die Tat umsetzen, werden Deutschlands B\u00e4der k\u00fcnftig erheblich schneller als bisher von Grund auf erneuert. Diese Konsequenz ergibt sich aus einer aktuellen Repr\u00e4sentativstudie, die das forsa-Institut f\u00fcr die Vereinigung Deutsche Sanit\u00e4rwirtschaft (VDS) durchf\u00fchrte. Danach sprechen sich z. B. 42 % der Bev\u00f6lkerung f\u00fcr eine umfassende Renovierung bereits nach sp\u00e4testens 10 Jahren aus.<br \/> Grafik: Vereinigung Deutsche Sanit\u00e4rwirtschaft (VDS) Bild 3110<\/p> <p>Bildrechte: Vereinigung Deutsche Sanit\u00e4rwirtschaft (VDS)<\/p> <p>Dachverband der Sanit\u00e4rwirtschaft<\/p> <p>Kontakt<br \/> Vereinigung Deutsche Sanit\u00e4rwirtschaft e.V. (VDS)<br \/> Jens Wischmann<br \/> Rheinweg 24<br \/> 53113 Bonn<br \/> 0228 92399930<br \/> info@sanitaerwirtschaft.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.sanitaerwirtschaft.de\" title=\"Vereinigung Deutsche Sanit\u00e4rwirtschaft e.V.\" >http:\/\/www.sanitaerwirtschaft.de<\/a><\/p> <p>Pressekontakt:<br \/> Linnigpublic Agentur f\u00fcr \u00d6ffentlichkeitsarbeit<br \/> Frank Linnig<br \/> Fritz-von-Unruh-Str. 1<br \/> 56077 Koblenz<br \/> 0261 3038390<br \/> koblenz@linnigpublic.de<br \/> http:\/\/www.linnigpublic.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Schneller erneuern Deutsche dr\u00fccken im Bad selbst aufs Renovierungstempo \/ Aktuelle forsa-Studie \/ \u00dcberraschende Resultate \/ Bad als R\u00fcckzugsort: gegen Urlaub und Garten gut behauptet \/ Staatliche Umbau-F\u00f6rderung: breites Meinungsspektrum \/ Programme als &#8222;effizientes Modul&#8220; Wenn die Bundesb\u00fcrger ihr eigenes Votum auch in die Tat umsetzen, werden Deutschlands B\u00e4der k\u00fcnftig erheblich schneller als bisher von<\/p>\n","protected":false},"author":1,"featured_media":152951,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110],"tags":[134],"class_list":["post-19700","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-handwerk","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/19700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=19700"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/19700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152951"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=19700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=19700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=19700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}