{"id":20371,"date":"2013-03-14T16:04:28","date_gmt":"2013-03-14T16:04:28","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=20371"},"modified":"2013-03-15T12:59:57","modified_gmt":"2013-03-15T11:59:57","slug":"positives-bild-von-fernstudienabsolventen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/positives-bild-von-fernstudienabsolventen-1020371\/","title":{"rendered":"Positives Bild von Fernstudienabsolventen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Die Studie zeigt_ Personaler wollen berufliche Qualifikationen\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/03\/postie-media752-150x150.jpg\" width=\"150\" height=\"150\" \/>forsa-Studie 2013: Praxisbezug des Studiums entscheidet \u00fcber Karrierechancen<\/p> <p>Repr\u00e4sentative forsa-Umfrage im Auftrag der Euro-FH belegt: Personalchefs fordern praxisnahe Studieng\u00e4nge und sind von alternativen Karrierewegen \u00fcberzeugt.<br \/> Hamburg. F\u00fcr einen gelungenen Karrierestart kommt es nicht allein auf fundiertes Fachwissen und gute Noten an. Die Ergebnisse der aktuellen forsa-Umfrage im Auftrag der Europ\u00e4ischen Fernhochschule Hamburg machen deutlich: Es z\u00e4hlt vor allem die Praxisn\u00e4he im Studium. \u00dcber 90 Prozent der 300 befragten Personalentscheider in Unternehmen mit mehr als 150 Mitarbeitern nennen den Praxisbezug des absolvierten Studiengangs als das entscheidende Kriterium bei der Beurteilung von Studienabschl\u00fcssen ihrer Bewerber. Fast ebenso viele (88 Prozent) sehen in der Verzahnung von Studium und Beruf den Schl\u00fcssel zum Erfolg.<\/p> <p><!--more-->Ein berufsbegleitendes Fernstudium erf\u00fcllt diese hohen Anforderungen der Personalchefs an die akademische Laufbahn ideal und erm\u00f6glicht gleichzeitig, von den Synergien aus Theorie und Praxis zu profitieren. &#8222;Insbesondere Berufst\u00e4tigen er\u00f6ffnet das moderne Fernstudium vielversprechende Chancen. Parallel zum Job k\u00f6nnen sie einen akademischen Abschluss erlangen und sich so auf hohem Niveau f\u00fcr weitere Karriereschritte qualifizieren&#8220;, erkl\u00e4rt Prof. Dr. Jens-Mogens Holm, Pr\u00e4sident der Euro-FH. F\u00fcr 87 Prozent der befragten Personaler gilt die Belastbarkeit, die Fernstudienabsolventen durch das zeitgleiche Meistern von Studium und Job unter Beweis gestellt haben, als klarer Pluspunkt. \u00dcber 90 Prozent der Befragten nennen dar\u00fcber hinaus deren Selbstdisziplin und Leistungsbereitschaft als besonders wertvolle Eigenschaften. 87 Prozent sind zudem \u00fcberzeugt, dass Fernstudierende ein besonders praxisbezogenes Fachwissen mitbringen und mehr als drei Viertel der Personalchefs sch\u00e4tzen die bereits erworbene Berufserfahrung.<\/p> <p>Klares Signal: Personaler bef\u00fcrworten st\u00e4rkere Anerkennung beruflicher Qualifikationen<\/p> <p>&#8222;Das positive Bild, das Personalchefs von Fernstudienabsolventen haben, zeigt eindeutig, dass die Wirtschaft nicht l\u00e4nger an dem einen, klassischen Bildungsweg festh\u00e4lt &#8211; vielmehr gibt es eine breite Anerkennung alternativer Karrierewege&#8220;, stellt Prof. Dr. Holm fest. Einen wesentlichen Teil tr\u00e4gt hierzu auch die Modernisierung des Bildungssystems bei, die unter anderem den Zugang zum Hochschulstudium ohne Abitur erm\u00f6glicht. \u00dcber den Nutzen dieser Entwicklung f\u00fcr Unternehmen und Mitarbeiter sind sich Deutschlands Arbeitgeber einig: 85 Prozent der Personalentscheider begr\u00fc\u00dfen die hiermit verbesserte Chancengleichheit sowie die vielf\u00e4ltigeren Karrierewege. 83 Prozent sind der Meinung, dass berufliche Erfahrungen und Qualifikationen so zunehmend gew\u00fcrdigt werden. Weitere drei Viertel beurteilen die schnelle und gezielte Ausbildung von Fach- und F\u00fchrungskr\u00e4ften, die durch die Flexibilisierung des Bildungssystems ebenfalls gew\u00e4hrleistet wird, als besonders positiven Effekt.<\/p> <p>Ein individuelles Beratungsgespr\u00e4ch \u00fcber die M\u00f6glichkeiten eines berufsbegleitenden Fernstudiums bietet die Studienberatung der Euro-FH telefonisch unter 0800\/33 44 377 (geb\u00fchrenfrei) an. Ausf\u00fchrliche Informationen zum Studium gibt es au\u00dferdem unter www.Euro-FH.de.<\/p> <p>\u00dcber die forsa-Studie im Auftrag der Euro-FH<\/p> <p>Bereits zum achten Mal f\u00fchrte das Marktforschungsinstitut forsa im Januar 2013 im Auftrag der Europ\u00e4ischen Fernhochschule Hamburg (Euro-FH) und des ILS Institut f\u00fcr Lernsysteme eine Umfrage unter Arbeitgebern in Deutschland zu verschiedenen Aspekten der berufsbegleitenden Weiterbildung durch. Im Rahmen der repr\u00e4sentativen Studie wurden 300 Personalverantwortliche in Unternehmen mit mehr als 150 Mitarbeitern befragt. Schwerpunkte der Studie sind unter anderem die Akzeptanz neuer Hochschulentwicklungen in der Wirtschaft, die Bewertung von Fernstudien in der Mitarbeiterqualifikation sowie die Bedeutung von Formalqualifikationen und kontinuierlicher Weiterbildung f\u00fcr die Karriere. Die Studie wird seit 2006 durchgef\u00fchrt &#8211; 2009 wurde sie f\u00fcr ihren Beitrag zur Verbraucherinformation mit dem Publikationspreis des Fach-verbandes Forum DistancE-Learning ausgezeichnet.<\/p> <p>Die forsa-Studie inklusive vieler Auswertungen und Grafiken steht ab sofort zum Download auf www.Euro-FH.de (Schwerpunkt: Hochschule und Fernstudium) und www.ils.de (Schwerpunkt: privates Weiterbildungsengagement) bereit.<\/p> <p>Bildrechte: forsa\/Euro-FH\/ILS 2013<\/p> <p>\u00dcber die Euro-FH<\/p> <p>Die Europ\u00e4ische Fernhochschule Hamburg ist Deutschlands bekannteste private Fernhochschule (forsa 2013). F\u00fcr ihr innovatives und flexibles Studienkonzept, das optimal auf die Belange berufsbegleitend Studierender ausgerichtet ist, wurde sie mehrfach ausgezeichnet. Rund 5.500 Studierende sind in den Studieng\u00e4ngen Europ\u00e4ische Betriebswirtschaftslehre (B.A.), Wirtschaftsrecht (LL.B.), Logistikmanagement (B.Sc.), Betriebswirtschaft &amp; Wirtschaftspsychologie (B.A.), Finance und Management (B.Sc.) sowie Business Coaching &amp; Change Management (M.A.), Wirtschaftspsychologie (M.Sc.), dem General Management MBA und dem Marketing MBA eingeschrieben. Die Studieng\u00e4nge sind FIBAA-akkreditiert und international ausgerichtet sowie \u00e4u\u00dferst praxisnah. Das Angebot der Euro-FH umfasst zudem Hochschulkurse aus den Bereichen Wirtschaft, Recht, Sprachen, Logistik und Soft Skills.<\/p> <p>Die Euro-FH ist Teil der Stuttgarter Klett Gruppe. Mit ihren 59 Unternehmen an 40 Standorten in 17 L\u00e4ndern ist die Klett Gruppe das f\u00fchrende Bildungsunternehmen in Deutschland. Die ca. 2.760 Mitarbeiter in den Unternehmen der Gruppe erwirtschafteten im Jahr 2011 einen Umsatz von rund 457 Millionen Euro. Weitere Informationen finden Sie im Internet unter klett-gruppe.de.<\/p> <p>Kontakt<br \/> Europ\u00e4ische Fernhochschule Hamburg c\/o Laub &amp; Partner<br \/> Sabrina Felsky<br \/> Kedenburgstra\u00dfe 44<br \/> 22041 Hamburg<br \/> 040\/656972-17<br \/> sabrina.felsky@laub-pr.com<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.Euro-FH.de\" title=\"Per Fernstudium an der Euro-FH zum Bachelor, Master &amp; MBA!\" >http:\/\/www.Euro-FH.de<\/a><\/p> <p>Pressekontakt:<br \/> Euro-FH Pressestelle c\/o Laub &amp; Partner<br \/> Sabrina Felsky<br \/> Kedenburgstra\u00dfe 44<br \/> 22041 Hamburg<br \/> 040\/656972-17<br \/> sabrina.felsky@laub-pr.com<br \/> http:\/\/www.laub-pr.com<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>forsa-Studie 2013: Praxisbezug des Studiums entscheidet \u00fcber Karrierechancen Repr\u00e4sentative forsa-Umfrage im Auftrag der Euro-FH belegt: Personalchefs fordern praxisnahe Studieng\u00e4nge und sind von alternativen Karrierewegen \u00fcberzeugt. Hamburg. F\u00fcr einen gelungenen Karrierestart kommt es nicht allein auf fundiertes Fachwissen und gute Noten an. Die Ergebnisse der aktuellen forsa-Umfrage im Auftrag der Europ\u00e4ischen Fernhochschule Hamburg machen deutlich: Es<\/p>\n","protected":false},"author":1,"featured_media":152924,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[134],"class_list":["post-20371","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-karriere-beruf-bildung","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/20371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=20371"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/20371\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152924"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=20371"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=20371"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=20371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}