{"id":23791,"date":"2013-04-10T08:01:37","date_gmt":"2013-04-10T08:01:37","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=23791"},"modified":"2014-08-22T12:29:27","modified_gmt":"2014-08-22T11:29:27","slug":"schonfrist-fuer-allergiker-vorbei","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/schonfrist-fuer-allergiker-vorbei-1023791\/","title":{"rendered":"Schonfrist f\u00fcr Allergiker vorbei"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Klinikdirektor und Allergologe Prof. Dr. med. Eckard Hamelmann\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/04\/postie-media464-150x150.jpg\" width=\"142\" height=\"142\" \/>Kinder-Allergologen warnen vor Notfall-Welle im April<\/p> <p>Universit\u00e4tskinderklinik Bochum er\u00f6ffnet &#8222;Schwerpunktjahr Allergologie&#8220;: Familienforum und Akademie informieren Eltern, Therapeuten und Mediziner \u00fcber M\u00f6glichkeiten der modernen Allergie-Medizin &#8211; H\u00f6hepunkt ist der 8. Deutsche Allergiekongress im September zum Thema &#8222;Allergie und Umwelt&#8220;<\/p> <p>Niesattacken, tr\u00e4nende Augen, Juckreiz, Kopfschmerzen: Auf eine sehr aggressive Allergie-Welle und die Zunahme von Notfallpatienten mit Atemnot richtet sich die Universit\u00e4tskinderklinik (http:\/\/www.kinderklinik-bochum.de) in Bochum ein. <!--more-->&#8222;Wenn die Natur in den n\u00e4chsten Tagen nach \u00fcberlangem Winterschlaf mit gro\u00dfer Kraft erwacht, beginnt f\u00fcr viele allergiekranke Kinder und Jugendliche eine schlimme Leidenszeit,&#8220; sagte der Klinikdirektor und Allergologe Prof. Dr. med. Eckard Hamelmann (http:\/\/http:\/\/www.leading-medicine-guide.com\/Kinderallergologie-Prof-Dr-med-Eckard-H-Hamelmann-Kliniken-der-Ruhr-Universitaet-Bochum,-St-Josef-und-St-Elisabeth-Hospital-gGmbH-Bochum) bei der Vorstellung der Programmreihe &#8222;Schwerpunktjahr Allergologie&#8220;, die die Klinik 2013 gemeinsam mit ihren Partnern speziell f\u00fcr Eltern, Mediziner und Therapeuten aufgelegt hat.<\/p> <p>Allergien, Asthma und Neurodermitis (atopisches Ekzem) haben sich zu Volkskrankheiten entwickelt, von denen bereits bis zu 25 Prozent der Kinder und Jugendlichen in Deutschland betroffen sind. Das sind allein in Nordrhein-Westfalen rund 650.000 M\u00e4dchen und Jungen. Viele von ihnen reagieren allergisch auf Bl\u00fctenstaub und Gr\u00e4sersamen. Prof. Eckard Hamelmann, Sprecher des Allergie Centrums Ruhr (ACR): (http:\/\/www.allergie-centrum-ruhr.de) &#8222;Normalerweise kitzeln Hasel, Erle und Birke schon ab Januar in der Nase. Schnee, K\u00e4lte und jetzt der Regen gew\u00e4hren Allergikern in diesem Jahr eine Schonfrist. Sobald es jedoch richtig warm und sonnig ist, werden B\u00e4ume, Str\u00e4ucher und Gr\u00e4ser ihre Pollen und Samen geradezu explosionsartig verteilen. Deshalb rechnen wir in den n\u00e4chsten Wochen verst\u00e4rkt mit Notfall-Patienten, die wegen Atemnot oder anderen schweren allergischen Symptomen unsere Hilfe ben\u00f6tigen.&#8220;<\/p> <p>Diese witterungsbedingte Dramatik konnten die Organisatoren des Schwerpunktjahres nicht vorausahnen, als sie im Herbst das Veranstaltungsprogramm f\u00fcr 2013 planten. Wie schon beim &#8222;Schwerpunktjahr Ern\u00e4hrung&#8220; 2012 ziehen alle Akteure an einem Strang: die Universit\u00e4tskinderklinik, die Stiftung Kinderzentrum Ruhrgebiet (http:\/\/www.kiz-ruhr.de) , das Familienforum, die Akademie Kinderzentrum Ruhrgebiet und das Allergie Centrum Ruhr (ACR), zu dem sich vier Kliniken, eine Forschungseinrichtung der RUB und das Institut f\u00fcr Pr\u00e4vention und Arbeitsmedizin (IPA) zusammengeschlossen haben. Iris von der Lippe, Gesch\u00e4ftsf\u00fchrerin der Stiftung Kinderzentrum Ruhrgebiet: &#8222;Bis zum Herbst werden wir in zahlreichen Veranstaltungen, Vortr\u00e4gen, Patientenvorlesungen und Weiterbildungsseminaren Eltern, Therapeuten und Mediziner mit neuen Erkenntnissen zur Diagnose, Therapie und Pr\u00e4vention bei allergischen Erkrankungen im Kinder- und Jugendalter vertraut machen.&#8220;<\/p> <p>Auch wenn bisher nicht vollst\u00e4ndig gekl\u00e4rt ist, warum das kindliche Immunsystem immer h\u00e4ufiger Bl\u00fctenpollen, Hausstaub, Tierhaare oder Nahrungsmittel so stark wie ansonsten Krankheitserreger bek\u00e4mpft, sind Erkrankte und ihre Eltern den Angriffen der Allergene nicht hilflos ausgeliefert. Asthmaschulungen, Verhaltenstrainings bei allergischem (anaphylaktischem) Schock, Ern\u00e4hrungsberatung oder Anleitungen f\u00fcr den Umgang mit der belastenden Erkrankung im famili\u00e4ren Alltag und in der Schule geben im Schwerpunktjahr praktische Orientierung. Ein ausf\u00fchrliches Programmheft, das in einer Auflage von 6.000 Exemplaren in Bochum und den Nachbarst\u00e4dten verteilt wird, informiert \u00fcber die genauen Inhalte und Termine der einzelnen Veranstaltungen.<\/p> <p>Nicht nur Eltern und Therapeuten, auch die Spitzenmedizin blickt 2013 nach Bochum, wenn es um das Thema Allergie geht. H\u00f6hepunkt des Schwerpunktjahres ist der 8. Deutsche Allergiekongress (http:\/\/www.allergie-kongress.de) , der vom 5. bis 7. September alle drei gro\u00dfen allergologischen Fachgesellschaften &#8211; den \u00c4rztebund Deutscher Allergologen (\u00c4DA), die Deutsche Gesellschaft f\u00fcr Allergologie und Klinische Immunologie (DgAKi) und die Gesellschaft f\u00fcr P\u00e4diatrische Allergologie (gPA) &#8211; in den RuhrCongress und die benachbarte Universit\u00e4tskinderklinik f\u00fchrt. Die Veranstaltung, zu der rund 1.400 Teilnehmerinnen und Teilnehmer aus dem gesamten Bundesgebiet erwartet werden, findet unter der Kongresspr\u00e4sidentschaft von Klinikdirektor Prof. Dr. Eckard Hamelmann und Prof. Dr. Monika Raulf-Heimsoth, Leiterin der Abteilung Allergologie\/Immunologie am Institut f\u00fcr Pr\u00e4vention und Arbeitsmedizin der Ruhr-Universit\u00e4t Bochum (IPA), nach einem neuen Konzept statt.<\/p> <p>Der Kongress selbst steht unter dem Motto &#8222;Allergie und Umwelt&#8220; und weist auf die besondere Bedeutung von Umweltfaktoren f\u00fcr die Entstehung und Auspr\u00e4gung allergischer Erkrankungen hin. Prof. Dr. Eckard Hamelmann: &#8222;Das Kongressthema nimmt damit Bezug auf die besonderen Probleme unserer Region.&#8220; Das dreit\u00e4gige Programm bietet Fort- und Weiterbildung im gesamten Spektrum der Allergologie. Neu ist die AllergoArena, in der f\u00fchrende Mediziner das Pro und Contra allergologischer Fragestellungen diskutieren und anschlie\u00dfend das Plenum mit Hilfe einer Ted-Befragung \u00fcber das Ergebnis abstimmen lassen. Schirmherrin des 8. Deutschen Allergiekongresses ist NRW-Gesundheitsministerin Barbara Steffens.<\/p> <p>Bildrechte: Klinik f\u00fcr Kinder- und Jugendmedizin der Ruhr-Univ<\/p> <p>Klinik f\u00fcr Kinder- und Jugendmedizin der Ruhr-Universit\u00e4t Bochum im St. Josef- und St. Elisabeth-Hospital<\/p> <p>Kontakt<br \/> Klinik f\u00fcr Kinder- und Jugendmedizin der Ruhr-Universit\u00e4t Bochum<br \/> Prof. Dr. med. Eckard Hamelmann<br \/> Alexandrinenstra\u00dfe 5<br \/> 44791 Bochum<br \/> 0234 5092610<br \/> e.hamelmann@klinikum-bochum.de<br \/> http:\/\/www.kinderklinik-bochum.de<\/p> <p>Pressekontakt:<br \/> JournalistenB\u00fcro Herne GmbH<br \/> Susanne Sch\u00fcbel<br \/> Stra\u00dfburger Str. 32<br \/> 44623 Herne<br \/> 492323994960<br \/> info@jb-herne.de<br \/> http:\/\/www.jb-herne.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Kinder-Allergologen warnen vor Notfall-Welle im April Universit\u00e4tskinderklinik Bochum er\u00f6ffnet &#8222;Schwerpunktjahr Allergologie&#8220;: Familienforum und Akademie informieren Eltern, Therapeuten und Mediziner \u00fcber M\u00f6glichkeiten der modernen Allergie-Medizin &#8211; H\u00f6hepunkt ist der 8. Deutsche Allergiekongress im September zum Thema &#8222;Allergie und Umwelt&#8220; Niesattacken, tr\u00e4nende Augen, Juckreiz, Kopfschmerzen: Auf eine sehr aggressive Allergie-Welle und die Zunahme von Notfallpatienten mit Atemnot<\/p>\n","protected":false},"author":1,"featured_media":152985,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[123],"tags":[134],"class_list":["post-23791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familie-jugend-erziehung","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/23791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=23791"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/23791\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152985"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=23791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=23791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=23791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}