{"id":23859,"date":"2013-04-10T11:58:48","date_gmt":"2013-04-10T11:58:48","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=23859"},"modified":"2013-04-11T16:43:37","modified_gmt":"2013-04-11T15:43:37","slug":"politisches-gerangel-um-sexuellen-missbrauch","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/politisches-gerangel-um-sexuellen-missbrauch-1023859\/","title":{"rendered":"Politisches Gerangel um sexuellen Missbrauch"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-24148\" title=\"Kampagne \u201eKein Raum f\u00fcr Missbrauch\u201c\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/04\/Screenshot_91.jpg\" width=\"96\" height=\"125\" \/>Runder Tisch Kindesmissbrauch &#8211; Schutz und Unterst\u00fctzung fehlen<\/p> <p>Der Runde Tisch &#8222;Sexueller Missbrauch&#8220; fordert seit anderthalb Jahren die Entsch\u00e4digung der Betroffenen und die finanzielle Absicherung von Fachberatungsstellen und Therapiepl\u00e4tzen. Bund, L\u00e4nder und Kommunen schieben sich gegenseitig die Verantwortung zu &#8211; auf Kosten der Opfer. GPTG e.V. nennt dies skandal\u00f6s und fordert dringend Abhilfe.<\/p> <p><!--more-->Die Forderungen des Runden Tisches vom 30.11.2011 zur Verbesserung der Situation von sexueller Gewalt Betroffener wurden bisher so gut wie nicht umgesetzt, wie Jochen Strau\u00df, der Vorstand des Vereins Gesellschaft f\u00fcr Psychotraumatologie, Traumatherapie und Gewaltforschung (GPTG), kritisiert: &#8222;Der schleppende Umsetzungsprozess, die Verw\u00e4sserung der Anliegen durch politische Instanzen und die Bundespsychotherapeutenkammer erweckten den Eindruck, es sei den politisch zust\u00e4ndigen Ministern und Ministerinnen eher darum gegangen, das Thema sexuelle Gewalt medienwirksam zur eigenen Inszenierung zu nutzen denn den Betroffenen wirklich Hilfe zu teil werden zu lassen.<\/p> <p>So verabschiedete etwa der Bundestag in Berlin am 14.03.2013 die Neuregelung, dass zivilrechtliche Schadensanspr\u00fcche k\u00fcnftig erst nach 30 Jahren verj\u00e4hren. Zugleich setzte jedoch die FDP durch, die Verj\u00e4hrungsfristen im Strafrecht von zehn bzw. zwanzig Jahren beizubehalten. Schadensersatzforderungen der Betroffenen liefen mangels strafrechtlicher Verfolgung der Taten damit ins Leere. Dies sei f\u00fcr die Betroffenen &#8222;ein Schlag ins Gesicht.&#8220;<\/p> <p>Die Empfehlungen des Abschlussberichtes von Frau Dr. Bergmann, der unabh\u00e4ngigen Beauftragten der Bundesregierung zur Aufarbeitung sexuellen Kindesmissbrauchs, weist aus der Perspektive der Fachverb\u00e4nde zwar in die richtige Richtung, denn dort werde die Not der Betroffenen nicht nur anerkannt, sondern erstmals werden konkrete Mittel und Wege zur Versorgung und Behandlung genannt. Allerdings d\u00fcrften diese dann nicht Opfer politischer Rank\u00fcne werden. GPTG-Vorstand Strau\u00df: &#8222;Hier besteht die Gefahr, dass sich die Betroffenen neuerlich, diesmal durch politische Instanzen, &#8222;missbraucht&#8220; f\u00fchlen, und das politische Signal gesendet wird, dass Kinder- und Opferschutz und -hilfe f\u00fcr die politisch Handelnden ein vernachl\u00e4ssigbares Randthema sind. Auch f\u00fcr die Menschen, die derzeit und k\u00fcnftig Opfer von Gewalt und sexueller Ausbeutung sind und werden, hie\u00dfe dies, dass unsere Gesellschaft ihnen den notwendigen Schutz und die Unterst\u00fctzung verweigert.&#8220;<\/p> <p>Die Gesellschaft f\u00fcr Psychotraumatologie, Traumatherapie und Gewaltforschung gemeinn\u00fctziger Verein, kurz GPTG e.V., ist eine Fachgesellschaft die 2010 in Berlin gegr\u00fcndet wurde. Deren Mitglieder befassen sich voranging damit, die Versorgung von traumatisierten Menschen zu verbessern.<\/p> <p>Kontakt<br \/> Gesellschaft f\u00fcr Psychotraumatologie, Traumatherapie und Gewaltforschung gemeinn\u00fctziger e.V.<br \/> Manuela Stamm<br \/> Carmerstra\u00dfe 10<br \/> 10623 Berlin<br \/> +49 (30) 6098 7748<br \/> office@gptg.eu<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.gptg.eu\" title=\"gemeinn\u00fctzige Gesellschaft f\u00fcr Psychotraumatologie, Traumatherapie und Gewaltforschung (GPTG e.V.)\" >http:\/\/www.gptg.eu<\/a><\/p> <p>Pressekontakt:<br \/> Dipl.-Psych.<br \/> Strau\u00df Jochen-Wolf<br \/> Geibelstra\u00dfe 8<br \/> 60385 Frankfurt am Main<br \/> +49 (69) 24795136<br \/> info@jochen-strauss.de<br \/> http:\/\/www.jochen-strauss.de<\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Runder Tisch Kindesmissbrauch &#8211; Schutz und Unterst\u00fctzung fehlen Der Runde Tisch &#8222;Sexueller Missbrauch&#8220; fordert seit anderthalb Jahren die Entsch\u00e4digung der Betroffenen und die finanzielle Absicherung von Fachberatungsstellen und Therapiepl\u00e4tzen. Bund, L\u00e4nder und Kommunen schieben sich gegenseitig die Verantwortung zu &#8211; auf Kosten der Opfer. GPTG e.V. nennt dies skandal\u00f6s und fordert dringend Abhilfe.<\/p>\n","protected":false},"author":1,"featured_media":24148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[134],"class_list":["post-23859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik-administratives","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/23859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=23859"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/23859\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=23859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=23859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=23859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}