{"id":25293,"date":"2013-04-19T11:26:55","date_gmt":"2013-04-19T11:26:55","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=25293"},"modified":"2016-09-24T09:21:29","modified_gmt":"2016-09-24T08:21:29","slug":"dynamische-entwicklung-des-stadtteils-koepenik","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/dynamische-entwicklung-des-stadtteils-koepenik-1025293\/","title":{"rendered":"Dynamische Entwicklung des Stadtteils K\u00f6penik"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-25780\" title=\"Wohnprojekt Regattastra\u00dfe in Berlin-K\u00f6penick\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/04\/Screenshot_92.jpg\" width=\"203\" height=\"118\" \/>Neue Entwicklungsachse<\/p> <p>K\u00f6penick und der gesamte Berliner S\u00fcdostraum entwickeln sich dynamisch<\/p> <p>Seit einigen Jahren w\u00e4chst die Berliner Wirtschaft st\u00e4rker als im Bundesdurchschnitt &#8211; und besonders dynamisch verl\u00e4uft die Entwicklung im S\u00fcdosten der Hauptstadt. &#8222;Im Korridor zwischen Innenstadt und zuk\u00fcnftigem Flughafen&#8220;, h\u00e4lt der Berliner Senat in seinem Planwerk S\u00fcdostraum fest, &#8222;entsteht aus Quartieren alter Industrie, ehemaligen Grenzgebieten und Brachfl\u00e4chen ein bedeutender Zukunftsraum der Stadt.&#8220; Davon profitiert insbesondere der Bezirk Treptow-K\u00f6penick mit seinen Ortsteilen K\u00f6penick und Gr\u00fcnau.<\/p> <p><!--more-->Obwohl noch nicht feststeht, wann der neue Hauptstadtflughafen in Sch\u00f6nefeld seinen Betrieb aufnehmen wird, sind die positiven Auswirkungen des Airports Willy Brandt bereits jetzt un\u00fcbersehbar. &#8222;Der Gro\u00dfflughafen wird Berlin ver\u00e4ndern und die Gewichte der Stadtentwicklung verschieben&#8220;, ist Florian Mausbach \u00fcberzeugt, Stadtplaner und ehemaliger Pr\u00e4sident des Bundesamtes f\u00fcr Bauwesen und Raumordnung. Und der Fachbereich Stadtplanung des Bezirks Treptow-K\u00f6penick bekr\u00e4ftigt in seinem regionalen Entwicklungskonzept f\u00fcr Berlin-S\u00fcdost: &#8222;Entlang des so genannten Airportkorridors zwischen Flughafen und Innenstadt konzentriert sich derzeit die wirtschaftliche, aber auch infrastrukturelle Entwicklung Berlin.&#8220; Dieser Korridor erstreckt sich vom Flughafen \u00fcber Adlershof, die Altstadt K\u00f6penick und Obersch\u00f6neweide bis zum Hauptbahnhof in der Innenstadt.<\/p> <p>Bestes Beispiel f\u00fcr den Aufw\u00e4rtstrend im Bezirk Treptow-K\u00f6penick ist der Technologie- und Wissenschaftspark Adlershof. Auf dem einstigen Gel\u00e4nde der Akademie der Wissenschaften der DDR entwickelte sich nach der Wende ein Hightech- und Forschungsstandort, der insbesondere durch die Verzahnung von Wirtschaft und Wissenschaft als internationales Vorzeigebeispiel eines prosperierenden Technologieparks gilt. Ende 2012 waren in Adlershof 954 Unternehmen und 17 wissenschaftliche Einrichtungen (darunter sechs naturwissenschaftliche Institute der Humboldt-Universit\u00e4t) ans\u00e4ssig. Diese besch\u00e4ftigten insgesamt rund 15.000 Mitarbeiter und erzielten einen Umsatz von 1,68 Milliarden Euro, was einem Plus von 4,4 Prozent gegen\u00fcber 2011 entspricht.<\/p> <p>Eine andere wissenschaftliche Institution, n\u00e4mlich die Hochschule f\u00fcr Technik und Wirtschaft (HTW), treibt die Entwicklung des ebenfalls zu Treptow-K\u00f6penick geh\u00f6renden Ortsteils Obersch\u00f6neweide voran. Die HTW hat ihren Sitz im ehemaligen Kabelwerk Oberspree, das zum Imperium des AEG-Gr\u00fcnders Emil Rathenau geh\u00f6rte. Nicht weit davon entfernt bietet der Innovationspark Wuhlheide weitere Ansiedlungsm\u00f6glichkeiten f\u00fcr Unternehmen aus technologischen Wachstumsbranchen.<\/p> <p>Dabei kommt dem Wirtschaftsstandort K\u00f6penick die ausgezeichnete Verkehrserschlie\u00dfung zugute. Vor allem die A 113 erm\u00f6glicht eine exzellente Anbindung sowohl an die Innenstadt als auch an den Airport. Zuk\u00fcnftig wird es au\u00dferdem die Tangentialverbindung Ost Autofahrern erm\u00f6glichen, die Autobahn und damit den Hauptstadtflughafen noch schneller zu erreichen.<\/p> <p>Der wirtschaftliche Aufschwung wirkt sich auch auf die Nachfrage nach Wohnungen aus. Einen &#8222;regelrechten Boom&#8220; erwartet Christian Geromeaber des Maklerunternehmens Allgemeine Immobilien-B\u00f6rse. &#8222;Erfahrungen an anderen Flugh\u00e4fen zeigen, dass die Wohnungsnachfrage rapide steigt, sobald dort der Betrieb aufgenommen wird.&#8220; Der erfahrene Makler ist deshalb \u00fcberzeugt: K\u00f6penick wird in besonderem Ma\u00dfe von der bevorstehenden Er\u00f6ffnung des Flughafens profitieren.<\/p> <p>BUWOG:<br \/> Die BUWOG-Gruppe, eine Gesellschaft der b\u00f6rsennotierten IMMOFINANZ AG, ist mit einem<br \/> Bestand von mehr als 32.000 Miet- und Eigentumswohnungen, davon \u00fcber 2.300 in<br \/> Deutschland, \u00d6sterreichs f\u00fchrendes privates Wohnungsunternehmen. Mit einem j\u00e4hrlichen<br \/> Neubauvolumen in Wien und Berlin von jeweils 500 bis 700 Wohnungen ist sie einer der<br \/> aktivsten Wohnbautr\u00e4ger und Immobilienentwickler in den beiden Hauptst\u00e4dten. Derzeit sind<br \/> rund 5.000 Wohnungen in Wien und Berlin in Vorbereitung bzw. in Bau. Gemeinsam mit der<br \/> Hausverwaltungstochter BUWOG FM verwaltet die Gruppe 1.900 Wohn-, B\u00fcro-,<br \/> Einzelhandels- und Hotelobjekte mit insgesamt 3,8 Mio. m\u00b2 Nutzfl\u00e4che und ist damit auch<br \/> das f\u00fchrende private Hausverwaltungsunternehmen \u00d6sterreichs.<br \/> BUWOG Meermann<br \/> Der Immobilienentwickler BUWOG Meermann wurde von der BUWOG im Mai 2012<br \/> erworben. Das Unternehmen ist auf dem Berliner Markt aktiv und ist ein auf die Entwicklung<br \/> hochwertiger Wohnimmobilien spezialisiertes Immobilienentwicklungsunternehmen.<\/p> <p>Kontakt<br \/> BUWOG &#8211; Meermann GmbH<br \/> Barbara Lipka<br \/> Am Kupfergraben 4\/4a<br \/> 10117 Berlin<br \/> 0049 30 338 539 1900<br \/> Barbara.Lipka@buwog-meermann.de<br \/> http:\/\/www.buwog-meermann.de<\/p> <p>Pressekontakt:<br \/> st\u00f6be mehnert. Agentur f\u00fcr Kommunikation<br \/> Dorothee St\u00f6be<br \/> Charlottenstra\u00dfe 13<br \/> 10969 Berlin<br \/> 0049 30 816 16 03 30<br \/> presse@stoebemehnert.de<br \/> http:\/\/www.stoebemehnert.de<\/p> <p>&nbsp;<\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Neue Entwicklungsachse K\u00f6penick und der gesamte Berliner S\u00fcdostraum entwickeln sich dynamisch Seit einigen Jahren w\u00e4chst die Berliner Wirtschaft st\u00e4rker als im Bundesdurchschnitt &#8211; und besonders dynamisch verl\u00e4uft die Entwicklung im S\u00fcdosten der Hauptstadt. &#8222;Im Korridor zwischen Innenstadt und zuk\u00fcnftigem Flughafen&#8220;, h\u00e4lt der Berliner Senat in seinem Planwerk S\u00fcdostraum fest, &#8222;entsteht aus Quartieren alter Industrie, ehemaligen<\/p>\n","protected":false},"author":1,"featured_media":25780,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[134],"class_list":["post-25293","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bauen-wohnen-garten","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/25293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=25293"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/25293\/revisions"}],"predecessor-version":[{"id":247872,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/25293\/revisions\/247872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=25293"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=25293"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=25293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}