{"id":25956,"date":"2013-04-24T14:38:06","date_gmt":"2013-04-24T14:38:06","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=25956"},"modified":"2013-04-26T14:27:33","modified_gmt":"2013-04-26T13:27:33","slug":"forderung-verlaengerung-der-eu-zuckermarktverordnung-bis-2020","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/forderung-verlaengerung-der-eu-zuckermarktverordnung-bis-2020-1025956\/","title":{"rendered":"Forderung: Verl\u00e4ngerung der EU-Zuckermarktverordnung bis 2020"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-26334\" title=\"Verein der Zuckerindustrie kl\u00e4rt auf\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/04\/Screenshot_31.jpg\" width=\"179\" height=\"138\" \/>EU-Zuckermarktordnung verringert Importabh\u00e4ngigkeit<\/p> <p>Berlin &#8211; Die Preise am Weltmarkt f\u00fcr Zucker waren in den vergangenen Jahren starken Schwankungen unterworfen. Allerdings haben die Mechanismen der europ\u00e4ischen Zuckermarktordnung entscheidend dazu beigetragen, die Auswirkungen dieser Schwankungen auf den heimischen Markt zu d\u00e4mpfen, betonte Dr. Hans-J\u00f6rg Gebhard, Vorsitzender der Wirtschaftlichen Vereinigung Zucker (http:\/\/www.zuckerverbaende.de\/) , im Rahmen eines Parlamentarischen Fr\u00fchst\u00fccks in Berlin. Vor diesem Hintergrund bekr\u00e4ftigte Dr. Gebhard die Forderung des Verbandes an die europ\u00e4ischen Gesetzgebungsorgane, die Zuckermarktordnung bis mindestens 2020 zu verl\u00e4ngern.<\/p> <p><!--more-->Die weltweite Nachfrage nach Zucker ist in den vergangenen Jahren stetig gestiegen. Hauptgrund ist das weltweite Bev\u00f6lkerungswachstum. Gleichzeitig haben extreme Witterungsverh\u00e4ltnisse und Verwerfungen der weltweiten Finanzm\u00e4rkte wiederholt zu gro\u00dfen Erzeugungsschwankungen in wichtigen Erzeugerl\u00e4ndern gef\u00fchrt. Die auf dem Markt verf\u00fcgbaren Zuckermengen konnten die Nachfrage in der Folge kaum decken, so dass der Weltmarktpreis zum Jahreswechsel 2010\/2011 neue Rekordh\u00f6hen erreichte. Diese Zusammenh\u00e4nge erl\u00e4uterte bei dem Parlamentarischen Fr\u00fchst\u00fcck Dr. Peter Baron, Executive Director bei der International Sugar Organization, dem Zusammenschluss von 89 Zucker ex- und importierenden Staaten.<\/p> <p>Mit der Zuckermarktreform von 2006 wurde der Selbstversorgungsgrad der EU bei Zucker von 115 auf 85 Prozent reduziert, die Union ist damit zum Netto-Importeur geworden. Gleichzeitig wurde der EU-Zuckermarkt st\u00e4rker an den Weltmarkt gekoppelt.<\/p> <p>Vor diesem Hintergrund betonte Dr. Gebhard, dass die europ\u00e4ischen Erzeuger mehr Zeit brauchen, um ihre Wettbewerbsf\u00e4higkeit weiter zu verbessern und den Entwicklungen an den internationalen Agrarm\u00e4rkten gewachsen zu sein. Zudem produzieren die europ\u00e4ischen Zuckererzeuger zu deutlich h\u00f6heren Umwelt- und Sozialstandards als in vielen anderen Regionen der Welt. Wer eine nachhaltige Zuckererzeugung wolle, d\u00fcrfe dies nicht einfach ignorieren.<\/p> <p>Die Wirtschaftliche Vereinigung Zucker (WVZ) vertritt die wirtschaftspolitischen Interessen der deutschen Zuckerwirtschaft auf nationaler, europ\u00e4ischer und internationaler Ebene. Sie ist zentraler Ansprechpartner in allen Fragen des Zuckermarktes und der Zuckerpolitik.<\/p> <p>Kontakt<br \/> Wirtschaftliche Vereinigung Zucker e.V.<br \/> Eva Sawadski<br \/> Am Hofgarten 8<br \/> 53113 Bonn<br \/> 0228 2285-124<br \/> sawadski@zuckerverbaende.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.zuckerverbaende.de\" title=\"Wirtschaftliche Vereinigung Zucker\" >http:\/\/www.zuckerverbaende.de<\/a><\/p> <p>Pressekontakt:<br \/> genius gmbh \u2013 wissenschaft und kommunikation<br \/> Christiane Freitag<br \/> Robert-Bosch-Str. 7<br \/> 64293 Darmstadt<br \/> 06151 872-4045<br \/> christiane.freitag@genius.de<br \/> http:\/\/www.genius.de<\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>EU-Zuckermarktordnung verringert Importabh\u00e4ngigkeit Berlin &#8211; Die Preise am Weltmarkt f\u00fcr Zucker waren in den vergangenen Jahren starken Schwankungen unterworfen. Allerdings haben die Mechanismen der europ\u00e4ischen Zuckermarktordnung entscheidend dazu beigetragen, die Auswirkungen dieser Schwankungen auf den heimischen Markt zu d\u00e4mpfen, betonte Dr. Hans-J\u00f6rg Gebhard, Vorsitzender der Wirtschaftlichen Vereinigung Zucker (http:\/\/www.zuckerverbaende.de\/) , im Rahmen eines Parlamentarischen Fr\u00fchst\u00fccks<\/p>\n","protected":false},"author":1,"featured_media":26334,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[134],"class_list":["post-25956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politik-administratives","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/25956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=25956"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/25956\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=25956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=25956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=25956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}