{"id":26617,"date":"2013-04-29T12:06:09","date_gmt":"2013-04-29T12:06:09","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=26617"},"modified":"2013-04-29T15:14:25","modified_gmt":"2013-04-29T14:14:25","slug":"studie-97-verschiedene-gene-werden-durch-yoga-reguliert","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/studie-97-verschiedene-gene-werden-durch-yoga-reguliert-1026617\/","title":{"rendered":"Studie: 97 verschiedene Gene werden durch Yoga reguliert"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-26684\" title=\"Yoga-Programm f\u00fchrt kurzer Zeit zu Auswirkungen auf genetischer Ebene\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/04\/Screenshot_93.jpg\" width=\"261\" height=\"136\" \/>Neues Forschungsergebnis zeigt Wirksamkeit von Yoga auf die DNA<\/p> <p>Eine Studie, die vor einigen Tagen von Forschern der Universit\u00e4t Oslo ver\u00f6ffentlicht wurde hat gezeigt, dass ein umfassendes Yoga-Programm in kurzer Zeit zu Auswirkungen auf genetischer Ebene f\u00fchrt.<\/p> <p>In der Studie analysierten die Forscher 10 Personen, die entweder ein Yoga-Programm bestehend aus Yoga\u00fcbungen, Atemtechniken mit Sudarshan Kriya und Meditation absolvierten, so wie es bei der Art of Living (http:\/\/www.artofliving.org) unterrichtet wird, oder einen Spaziergang durch die Natur machten und als Kontrollform Entspannungsmusik h\u00f6rten. <!--more-->Die Studie wurde von Wissenschaftlern der Universit\u00e4t Oslo rund um Prof. Fahri Saatcioglu durchgef\u00fchrt. Die Ergebnisse k\u00f6nnen dabei helfen, die positiven gesundheitlichen Auswirkungen von Yoga-\u00dcbungen, die zuvor dokumentiert wurden, auf der molekularen Ebene zu erkl\u00e4ren.<\/p> <p>Die Probanden nahmen an jeder Untersuchungsform zweimal teil. Das Yoga-Programm enthielt K\u00f6rperhaltungen (Asanas), Atem\u00fcbungen (einschlie\u00dflich Sudarshan Kriya) und Meditation. Vor und nach jeder Yogasession und der Kontrollform (die etwa 2 Stunden dauerten, an verschiedenen Tagen, zur gleichen Zeit am Tag), entnahmen die Forscher den Probanden Blut, isolierten die Immunzellen im Umlauf, und verglichen m\u00f6gliche Ver\u00e4nderungen in der Genexpression &#8211; wie das genetische Programm der DNA dieser Zellen aktiviert oder unterdr\u00fcckt wird.<\/p> <p>Es wurde festgestellt, dass es 97 verschiedene Gene gibt, die durch das Yoga-Programm reguliert werden, verglichen mit nur 24 Genen, die durch die Kontrollform reguliert werden und nur 14 Gene, die sowohl von der Yoga- als auch Kontrolluntersuchungsform angesprochen wurden. Die angesprochenen Gene sind aus fr\u00fcheren Studien bekannt daf\u00fcr, das sie eine Menge von Funktionen besitzen, aber in vielen F\u00e4llen sind ihre genaue Funktion in den Immunzellen noch nicht bekannt.<\/p> <p>&#8222;Dies ist das erste Mal, dass eine schnelle (innerhalb von 2 Stunden von Beginn der \u00dcbungen) und signifikante Ver\u00e4nderung der Genexpression in den Immunzellen der Aus\u00fcbenden w\u00e4hrend eines Yoga-Programms dokumentiert wurde. Diese Daten deuten darauf hin, dass bereits berichtete Auswirkungen von Yoga-\u00dcbungen eine integrale physiologische Komponente auf molekularer Ebene bilden, die unmittelbar w\u00e4hrend der Praxis initiiert wird und die Grundlage f\u00fcr die langfristig stabile Wirkung bilden kann&#8220; erkl\u00e4rt Prof. Saatcioglu.<\/p> <p>Vergleichsstudien zwischen Yoga und Bewegung haben zuvor vorgeschlagen, dass Yoga genauso effektiv oder sogar besser als Bewegung geeignet sein kann, eine Vielzahl von gesundheitsbezogenen Zielgr\u00f6\u00dfen zu verbessern. &#8222;Unsere Daten stehen im Einklang mit diesen fr\u00fcheren Befunden und legen nahe, dass ein Yoga-Programm im Vergleich zu Bewegung plus einfacher Entspannung zus\u00e4tzliche Auswirkung dabei haben kann, den gesundheitlichen Nutzen durch unterschiedliche Effekte auf molekularer Ebene zu induzieren&#8220;, betont Prof. Saatcioglu.<\/p> <p>Die Studie er\u00f6ffnet eine Reihe neuer M\u00f6glichkeiten f\u00fcr die zuk\u00fcnftige Forschung und wird voraussichtlich daf\u00fcr n\u00fctzlich sein, die Wirksamkeit von verschiedenen Yoga-Arten untereinander zu vergleichen.<\/p> <p>Was ist Sudarshan Kriya<\/p> <p>Sudarshan Kriya\u00a9 (SK) wurde von Sri Sri Ravi Shankar (https:\/\/plus.google.com\/+TheArtofLiving) konzipiert und wird exklusiv von der Art of Living Foundation weltweit unterrichtet. Sudarshan Kriya und begleitende Yoga- und Pranayama-\u00dcbungen (SK +P) ber\u00fccksichtigen spezifische nat\u00fcrliche Atemrhythmen, die den K\u00f6rperrhythmus und den Rhythmus der Emotionen harmonisieren und sie mit den Rhythmen der Natur in Einklang bringen Das besondere an SK + P ist, dass durch den Atem unsere verschiedenen Emotionen reguliert werden k\u00f6nnen. Das geschieht durch chemische Botenstoffe, die Neuropeptide, die bei jeder Gef\u00fchlsregung produziert werden. Diese werden rasch aufgenommen von den Zellen des Immunsystems, des Hormonsystems und des autonomen Nervensystems und haben somit einen direkten Einfluss auf deren Aktivit\u00e4t.<\/p> <p>Forschung im Fokus<\/p> <p>Die subjektiven Berichte von verbesserter Gesundheit, Vitalit\u00e4t, Wohlbefinden und geistiger Ausgeglichenheit von Tausenden SK&amp;P Praktizierenden sind in Einklang mit den modernen Forschungsergebnissen, welche eine St\u00e4rkung des Geist-K\u00f6rper-Systems best\u00e4tigen. EEG, Cortisolspiegel und Laktatwerte zeigen einen Zustand von Entspannung bei gleichzeitiger Wachheit an. Die signifikante Zunahme der nat\u00fcrlichen Killerzellen und Antioxidantien legt nahe, dass regelm\u00e4\u00dfige \u00dcbung vielen ernsten Erkrankungen vorbeugen kann. Die Abnahme von Cholesterin kann Herzerkrankungen vorbeugen; bei vielen Patienten werden Depressionen schnell gelindert. Obwohl weitere Forschungen n\u00f6tig sind, belegen diese Ergebnisse bereits die starke Wirkung dieser altehrw\u00fcrdigen Praktiken in der Wiederherstellung und Erhaltung der Gesundheit.<\/p> <p>Sudarshan Kriya in Deutschland lernen<\/p> <p>Die Sudarshan Kriya kann bei der Art of Living im Kurs &#8222;Die des Atmens&#8220; oder &#8222;Yes!+&#8220; weltweit und in vielen St\u00e4dten Deutschlands erlernt werden. Mehr Informationen zu den Kursen unter presse@artofliving.de oder unter www.artofliving.org.<\/p> <p>\u00dcber die Art of Living Foundation<\/p> <p>Die Art of Living Foundation (AOLF) wurde 1981 von Sri Sri Ravi Shankar gegr\u00fcndet und ist in \u00fcber 150 L\u00e4ndern t\u00e4tig. Sie ist eine der gr\u00f6\u00dften unabh\u00e4ngigen, humanit\u00e4ren Nicht-Regierungsorganisationen (NGO) der Welt. Die AOLF h\u00e4lt einen Sonderberaterstatus beim Wirtschafts- und Sozialrat (ECOSOC) der Vereinten Nationen (UN) inne und ist in zahlreichen anderen internationalen Gremien und Aussch\u00fcssen in den Bereichen Gesundheit, Bildung und nachhaltiger Entwicklung t\u00e4tig. Zu den Schwerpunkten z\u00e4hlen Hilfsprojekte in Entwicklungsl\u00e4ndern, Trauma- und Stressbew\u00e4ltigung in Krisengebieten und Resozialisierungsprogramme f\u00fcr Gewaltopfer und Gef\u00e4ngnisinsassen. Dar\u00fcber hinaus werden Yoga- und Meditationskurse angeboten. Wesentlicher Bestandteil ist die Sudarshan Kriya\u2122, eine gesundheitsf\u00f6rdernde Atemtechnik. Mehr Informationen unter www.artofliving.org.<\/p> <p>Die Art of Living Foundation (AOLF) wurde 1981 von Sri Sri Ravi Shankar gegr\u00fcndet und ist in \u00fcber 150 L\u00e4ndern t\u00e4tig. Sie ist eine der gr\u00f6\u00dften unabh\u00e4ngigen, humanit\u00e4ren Nicht-Regierungsorganisationen (NGO) der Welt. Die AOLF h\u00e4lt einen Sonderberaterstatus beim Wirtschafts- und Sozialrat (ECOSOC) der Vereinten Nationen (UN) und ist in zahlreichen anderen internationalen Gremien und Aussch\u00fcssen in den Bereichen Gesundheit, Bildung und nachhaltiger Entwicklung t\u00e4tig. Zu den Schwerpunkten z\u00e4hlen Hilfsprojekte in Entwicklungsl\u00e4ndern, Trauma- und Stressbew\u00e4ltigung in Krisengebieten und Resozialisierungsprogramme f\u00fcr Gewaltopfer und Gef\u00e4ngnisinsassen. Dar\u00fcber hinaus werden Yoga- und Meditationskurse angeboten. Wesentlicher Bestandteil ist die Sudarshan Kriya\u2122, eine gesundheitsf\u00f6rdernde Atemtechnik.<\/p> <p>Mehr unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.artofliving.org\" title=\"the art of living\" >www.artofliving.org<\/a>.<\/p> <p>Kontakt:<br \/> The Art of Living &#8211; Die Kunst des Lebens Deutschland e.V.<br \/> Cirstin Ehlers<br \/> Potsdamer Stra\u00dfe 98<br \/> 10785 Berlin<br \/> 00 49 151 43101428<br \/> Presse@artofliving.de<br \/> http:\/\/www.artofliving.org\/de-de<\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Neues Forschungsergebnis zeigt Wirksamkeit von Yoga auf die DNA Eine Studie, die vor einigen Tagen von Forschern der Universit\u00e4t Oslo ver\u00f6ffentlicht wurde hat gezeigt, dass ein umfassendes Yoga-Programm in kurzer Zeit zu Auswirkungen auf genetischer Ebene f\u00fchrt. In der Studie analysierten die Forscher 10 Personen, die entweder ein Yoga-Programm bestehend aus Yoga\u00fcbungen, Atemtechniken mit Sudarshan<\/p>\n","protected":false},"author":1,"featured_media":26684,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[134],"class_list":["post-26617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernaehrung-wellness-gesundheit","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/26617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=26617"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/26617\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=26617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=26617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=26617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}