{"id":266528,"date":"2020-01-24T12:33:47","date_gmt":"2020-01-24T11:33:47","guid":{"rendered":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=266528"},"modified":"2021-01-15T11:43:52","modified_gmt":"2021-01-15T10:43:52","slug":"kann-tee-als-heilmittel-wirklich-helfen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/kann-tee-als-heilmittel-wirklich-helfen-10266528\/","title":{"rendered":"Kann Tee als Heilmittel wirklich helfen?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-266529 size-full\" title=\"die ZUbereitung entscheidet \u00fcber die Wirksamkeit von Tee\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2020\/01\/tee-1252420_640-e1579865388171.jpg\" alt=\"Blick von oben in eine Teebox\" width=\"300\" height=\"179\" \/>Verschiedene Kr\u00e4uter, Tinkturen und Beeren wurden schon von jeher als nat\u00fcrliches Heilmittel eingesetzt. Auch heute noch nehmen Menschen diverse Tees gegen Leiden wie Kopfschmerzen, Erk\u00e4ltungen oder Probleme mit dem Magen bzw. dem Darm ein. Doch was k\u00f6nnen die fl\u00fcssigen, sanften Heilmittel tats\u00e4chlich bewirken?<\/p> <p>Mit den Waffen der Natur gegen verschiedene Leiden<\/p> <p><!--more-->Unter anderem berichten Menschen davon, dass Tees gegen Menstruationsleiden und akute Verstopfungen helfen. Dass es sich hierbei um einen blo\u00dfen Placeboeffekt handelt, kann ohne entsprechende Studien nat\u00fcrlich nie g\u00e4nzlich ausgeschlossen werden. Gegen diese These spricht allerdings, dass so viele Menschen bei Erk\u00e4ltungen und Co. zu Tee greifen und immer und immer wieder von einer Besserung durch den Konsum berichten.<\/p> <p>Denkbar ist es auf jeden Fall, dass die verschiedenen Tees eine Wirkung erzielen, sofern es sich um die richtige Dosierung und um einen qualitativ hochwertigen Tee handelt. Zudem sollten Konsumenten nicht vergessen, dass jeder Organismus anders auf bestimmte Inhaltsstoffe reagiert. W\u00e4hrend bei einem Menschen eher der Tee gegen Magenschmerzen anschl\u00e4gt, k\u00f6nnen wieder andere Personen mit einem frischen Kamillentee erfolgreich etwas gegen die Symptome einer Erk\u00e4ltung tun.<\/p> <p>Besonders im Trend in den letzten Jahren liegt der sogenannte Chaga-Tee. Dieser wird aus einem speziellen Pilz hergestellt, der dem menschlichen K\u00f6rper sehr gut bekommen soll. Sie sekund\u00e4ren Pflanzenstoffe sollen unter anderem das Immunsystem st\u00e4rken. Weitere Informationen und Eigenschaften von Chaga-Tee erhalten Interessierte im Web oder durch gezieltes Nachfragen beim Hersteller.<\/p> <p>Richtige Zubereitung enorm wichtig f\u00fcr die Wirksamkeit<\/p> <p>Wer gerne m\u00f6chte, dass der Tee nicht nur als Genussmittel oder als Durstl\u00f6scher eingesetzt wird, der muss dieses Lebensmittel richtig zubereiten. Je nach Sorte sind verschiedene Ziehzeiten einzuhalten. Auch die Temperatur spielt eine gro\u00dfe Rolle. Diese sorgt nicht nur daf\u00fcr, dass der Tee besser schmeckt. Auch die sekund\u00e4ren Pflanzenstoffe, Vitamine und andere gesunde Stoffe bleiben eher erhalten, wenn der Tee weder zu lange zieht, noch zu hei\u00df gekocht wird. Wer sich mit der jeweiligen Teesorte nicht auskennt, der sollte sich vorab \u00fcber die richtige Zubereitung informieren.<\/p> <p>Neben der Zubereitungsart ist es auch wichtig, dass der pflanzliche Tee aus biologischem Anbau stammt. Werden die Kr\u00e4uter, Beeren oder Obstsorten schon vor der Ernte mit <a href=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/pestizide-und-schwermetall-deine-krankmacher-im-darm-10270441\/\">Pestiziden und Co<\/a>. belastet, so darf an einer Wirksamkeit gegen gewisse Symptome gezweifelt werden. Lebensmittel mit einer zu hohen Belastung durch chemische Zus\u00e4tze, Zucker oder Geschmacksverst\u00e4rker sind ebenfalls per se nicht gesund. Das gilt nat\u00fcrlich f\u00fcr Tees ebenso wie f\u00fcr alle anderen Lebensmittel.<\/p> <p>Diese Tees helfen vielen Menschen<\/p> <p>Es gibt bestimmte Teesorten, die von besonders vielen Personen als wohltuend beschrieben werden. Was so vielen Verbrauchern hilft, kann dem Einzelnen sicherlich nicht schaden. Nat\u00fcrlich sollte vorab immer zuerst mit dem Arzt abgekl\u00e4rt werden, ob die Symptome eventuell durch eine ernst zu nehmende Krankheit hervorgerufen werden. Handelt es sich um einen eher harmlose Angelegenheit, kann der Tee zur schnelleren Genesung beitragen.<\/p> <p>Besonders gesund sind die Klassiker: Pfefferminztee sorgt f\u00fcr einen frischen Atem und kann dabei helfen, nach einer Erk\u00e4ltung endlich wieder frei zu atmen. Hochwertiger Kamillentee wird hingegen dazu genutzt, um den Magen nach einer Magen-Darm-Grippe wieder zu beruhigen. Der frische Tee aus Brennnesseln kann dem K\u00f6rper dabei helfen, mehr eigene Abwehrkr\u00e4fte aufzubauen. Au\u00dferdem enthalten die Brennnesseln zahlreiche verschiedene N\u00e4hrstoffe, welche dem menschlichen K\u00f6rper gut bekommen. Wer dem Organismus gerade im Winter ein Extra an Vitaminen zuf\u00fchren m\u00f6chte, der kann einem frischen Kr\u00e4utertee einen Spritzer Zitronensaft beimischen. Zucker sollte hingegen nach M\u00f6glichkeit vermieden oder nur in geringen Mengen beigesetzt werden.<\/p> <p>Bild von congerdesign auf Pixabay<\/p>","protected":false},"excerpt":{"rendered":"<p>Verschiedene Kr\u00e4uter, Tinkturen und Beeren wurden schon von jeher als nat\u00fcrliches Heilmittel eingesetzt. Auch heute noch nehmen Menschen diverse Tees gegen Leiden wie Kopfschmerzen, Erk\u00e4ltungen oder Probleme mit dem Magen bzw. dem Darm ein. Doch was k\u00f6nnen die fl\u00fcssigen, sanften Heilmittel tats\u00e4chlich bewirken? Mit den Waffen der Natur gegen verschiedene Leiden<\/p>\n","protected":false},"author":12,"featured_media":266529,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[],"class_list":["post-266528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernaehrung-wellness-gesundheit"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/266528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=266528"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/266528\/revisions"}],"predecessor-version":[{"id":267098,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/266528\/revisions\/267098"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/266529"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=266528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=266528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=266528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}