{"id":28151,"date":"2013-05-10T11:21:00","date_gmt":"2013-05-10T11:21:00","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=28151"},"modified":"2013-05-10T12:36:41","modified_gmt":"2013-05-10T11:36:41","slug":"neuheit-mehr-flexibilitaet-fuer-diodenlaser","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/neuheit-mehr-flexibilitaet-fuer-diodenlaser-1028151\/","title":{"rendered":"Neuheit: Mehr Flexibilit\u00e4t f\u00fcr Diodenlaser"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"zwei Laserwelten in einem Ger\u00e4t\" alt=\"zwei Laserwelten in einem Ger\u00e4t\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/05\/172188-150x150.jpg\" width=\"126\" height=\"126\" \/>Omicron stellt innovative 2-in-1-L\u00f6sung auf Laser-Messe vor<\/p> <p>Mit neuer Diodenlaser-Serie verbindet Omicron zwei Laser-Welten in einem Ger\u00e4t<br \/> Der Laserspezialist Omicron aus Rodgau bringt mit der neuen Laserserie &#8222;BrixX ps&#8220; mehr Flexibilit\u00e4t in die Welt der Diodenlaser. Durch einfache Umstellung im Betriebsmodus kann mit nur einem Ger\u00e4t sowohl die Diodenlaserfunktion mit gepulsten Pikosekunden als auch die modulierte Laserfunktion gew\u00e4hlt werden.<\/p> <p><!--more-->Mit der innovativen Laserserie &#8222;BrixX ps&#8220; pr\u00e4sentiert Omicron erstmals universelle Diodenlaser, die sowohl im Pikosekundenbereich gepulst, als auch im Modus &#8222;Continuous Wave&#8220; (CW) und im modulierten Betrieb arbeiten k\u00f6nnen. Die kompakten Lasermodule mit komplett integrierter Treiberelektronik, hochpr\u00e4ziser Temperaturregelung und Strahlformungsoptik k\u00f6nnen ultrakurze Pulse bis zu 50 Pikosekunden, Pulse im Nanosekundenbereich und schnell analog- und digital-modulierte CW-Emissionen ausgeben.<\/p> <p>In den neuen &#8222;BrixX ps&#8220;-Systemen sind Dioden mit bis zu 1.500 Milliwatt optischer Ausgangsleistung und Wellenl\u00e4ngen zwischen 375 und 2.300nm einsatzf\u00e4hig. Der Lichtausgang kann sowohl als Faser oder Freistrahl ausgef\u00fchrt werden. Im CW-Modus kann die Leistung mit bis zu 100 Megahertz digital als auch bis zu einem Megahertz analog moduliert werden. Zudem verf\u00fcgen die innovativen Module \u00fcber einen elektronischen Shutter, mit dem das Licht mit mehr als 500kHz Bandbreite voll an- und ausgeschaltet werden kann. Im gepulsten Modus kann die Repetitionsrate entweder \u00fcber ein externes Synchronisationssignal getriggert oder durch den internen, programmierbaren Frequenzgenerator mit bis zu 100 Megahertz erzeugt werden.<\/p> <p>\u00dcber die integrierten RS-232 und USB-2.0 Schnittstellen lassen sich die &#8222;BrixX ps&#8220;-Module optimal in neue und vorhandene Applikationen einbinden. F\u00fcr den Laborbetrieb wird eine komfortable Kontrollsoftware mitgeliefert. Neben einem Standardprogramm k\u00f6nnen kundenspezifische Wellenl\u00e4ngen sowie vom Kunden bereitgestellte Dioden in die Ger\u00e4te integriert werden. Typische Anwendungsgebiete sind die Mikroskopie, Spektrometrie, Fluoreszenzanalyse und die Verwendung als Seed- oder Pumplaser.<\/p> <p>Die neuen &#8222;BrixX ps&#8220;-Diodenlaser von Omicron gehen im zweiten Quartal 2013 in Serienfertigung und werden auf der weltweit f\u00fchrenden Messe &#8222;Laser 2013 &#8211; World of Photonics&#8220; vom 13. bis 16. Mai 2013 in M\u00fcnchen vorgestellt.<\/p> <p>Weitere Informationen \u00fcber die Omicron Laserprodukte gibt es unter www.omicron-laser.de.<br \/> +++<\/p> <p>Bildrechte: Omicron-Laserage Laserprodukte GmbH<\/p> <p>Hintergrundinformation:<br \/> Omicron entwickelt, konstruiert und produziert seit 1989 innovative Laser-Systeme. Das hochqualifizierte Team hat sich seit dem auf die Entwicklung individueller Kundenl\u00f6sungen in den Anwendungsgebieten der Medizin, Forschung und Biotechnologie wie Mikroskopie und Durchflusszytometrie, Digital Imaging und optische Datenspeicherung sowie der Qualit\u00e4tssicherung und Messtechnik spezialisiert. Entwicklung und Produktion entsprechen dabei sowohl den europ\u00e4ischen als auch den US-amerikanischen Richtlinien. F\u00fcr individuelle Anforderungen steht eine breite Palette an Laserquellen im Bereich UV VIS\/IR zur Verf\u00fcgung. Dabei werden sowohl einzelne Lichtquellen als auch Systeml\u00f6sungen angeboten. Omicron hat den Anspruch, in Sachen Produktentwicklung immer einen Schritt voraus zu sein und hat mit seinen zahlreichen Neuentwicklungen in der Laser-Technologie nicht nur Trends gesetzt, sondern auch international bereits f\u00fcr Furore gesorgt.<\/p> <p>Kontakt<br \/> Omicron Laserage Laserprodukte GmbH<br \/> S\u00f6nke Baumann<br \/> Raiffeisenstra\u00dfe 5e<br \/> 63110 Rodgau<br \/> 06106 &#8211; 8224 0<br \/> mail@omicron-laser.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.omicron-laser.de\" title=\"Omicron-Laserage Laserprodukte GmbH\" >http:\/\/www.omicron-laser.de<\/a><\/p> <p>Pressekontakt:<br \/> PR Solutions by Melanie Schacker<br \/> Melanie Schacker<br \/> Am Nonnenhof 55<br \/> 60435 Frankfurt\/Main<br \/> 069 &#8211; 95 20 8991<br \/> presse@pr-schacker.de<br \/> http:\/\/www.pr-schacker.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Omicron stellt innovative 2-in-1-L\u00f6sung auf Laser-Messe vor Mit neuer Diodenlaser-Serie verbindet Omicron zwei Laser-Welten in einem Ger\u00e4t Der Laserspezialist Omicron aus Rodgau bringt mit der neuen Laserserie &#8222;BrixX ps&#8220; mehr Flexibilit\u00e4t in die Welt der Diodenlaser. Durch einfache Umstellung im Betriebsmodus kann mit nur einem Ger\u00e4t sowohl die Diodenlaserfunktion mit gepulsten Pikosekunden als auch die<\/p>\n","protected":false},"author":1,"featured_media":152959,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[134],"class_list":["post-28151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-technik","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/28151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=28151"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/28151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152959"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=28151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=28151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=28151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}