{"id":28241,"date":"2013-05-12T08:00:33","date_gmt":"2013-05-12T08:00:33","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=28241"},"modified":"2013-05-13T16:22:05","modified_gmt":"2013-05-13T15:22:05","slug":"fachmesse-fuer-museen-konservierung-und-kulturerbe","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/fachmesse-fuer-museen-konservierung-und-kulturerbe-1028241\/","title":{"rendered":"Fachmesse f\u00fcr Museen, Konservierung und Kulturerbe"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Von Standard- bis Designmobiliar \u2013 wir liefern schnell, zuverl\u00e4ssig und f\u00fcr die meisten Messen transportkostenfrei. \" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/05\/171569.jpg\" width=\"146\" height=\"76\" \/>Die Exponatec Cologne bietet 2013 viele interessante Aussteller<\/p> <p>M\u00f6bel f\u00fcr Messen jeder Art kann man bei JMT schnell und unkompliziert anmieten und liefern lassen &#8211; JMT Mietm\u00f6bel Deutschland GmbH &amp; Co.KG<br \/> Die Exponatec Cologne ist die bedeutendste Fachmesse f\u00fcr Museen in Europa und wird von der Koelnmesse veranstaltet. Vom 20. Bis zum 22. November 2013 \u00f6ffnet die Fachmesse f\u00fcr Museen, Konservierung und Kulturerbe wieder ihre Pforten. Neben den Kernthemen wie Konservierungsmethoden, Restauration und Materialforschung bietet die Exponatec vieles mehr. <!--more-->Wichtige Themen sind auch die unterschiedlichen Dienstleistungsangebote im Museumsumfeld, also Besucherforschung, \u00d6ffentlichkeitsarbeit und Museumsshops bis hin zu Logistik, Verwaltungsbedarf und Personaldienstleistungen. Au\u00dferdem wird sich auch ausgiebig mit Ausstellungsdesign und Pr\u00e4sentationstechnik besch\u00e4ftigt. Nicht nur Hersteller und Dienstleister nutzen die Exponatec als Gesch\u00e4ftsplattform, sondern auch Vertriebsgesellschaften, Verb\u00e4nden sowie Gro\u00dfh\u00e4ndlern und Importeuren ziehen ihren Nutzen. Dar\u00fcber hinaus begleitet ein Fachkongress, der zielgruppenorientierte Diskussionen und Vortr\u00e4ge bietet, die Messe (http:\/\/www.jmt.de) . Kooperationen mit relevanten Institutionen und Verb\u00e4nden, zum Beispiel mit dem Deutschen Museumsbund, der Europa Nostra und der Organisation Best in Heritage unterstreichen den internationalen Fokus der Fachveranstaltung. Die Mietm\u00f6bel der JMT GmbH sorgen f\u00fcr ein angemessenes Ambiente f\u00fcr jede Gelegenheit.<\/p> <p>Durch seine zentrale Lage in Europa hat sich K\u00f6ln als Standort f\u00fcr eine Museumsmesse einen Namen gemacht. Die Exponatec ist die internationale Fachmesse f\u00fcr Museen, Konservierung und Kulturerbe. Sie vereint mit ihrem jungen und innovativen Konzept die Schnittstelle zwischen Gegenwart und Zukunft, zwischen Gespr\u00e4ch und Gesch\u00e4ft, zwischen Anwender und L\u00f6sungsanbieter. Letztmalig zeigte sie sich vom 16.-18. November 2011 als pulsierende Plattform voller Inspiration mit 247 Ausstellern aus 17 L\u00e4ndern. Unter diesen Teilnehmern befanden sich 158 Aussteller und 28 zus\u00e4tzlich vertretene Unternehmen aus Deutschland. Die Exponatec 2011 wurde von insgesamt rund 4.000 Fachbesuchern besucht.<\/p> <p>Bei einer Messe alles perfekt in Szene zu setzen und f\u00fcr die Besucher f\u00fcr angenehmen Komfort zu sorgen, ist oberstes Gebot bei der JMT GmbH. Unter www.jmt.de (<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.jmt.de\" title=\"Mietm\u00f6bel f\u00fcr Kongresse, Hauptversammlungen, Events oder Produktshows\" >http:\/\/www.jmt.de<\/a>) k\u00f6nnen Aussteller und Veranstalter aus den unterschiedlichsten mietbaren Messem\u00f6beln das passende ausw\u00e4hlen. Bei Fragen zu Terminen oder den M\u00f6beln steht das Team des Spezialisten f\u00fcr Miet- und Messem\u00f6bel telefonisch und per E-Mail zur Verf\u00fcgung.<\/p> <p>Weitere Informationen:<\/p> <p>JMT Mietm\u00f6bel Deutschland GmbH &amp; Co.KG<br \/> Otto-Hahn-Strasse 11<br \/> 40721 Hilden<br \/> Tel: +49 (0) 2103 9826-0<br \/> E-Mail: info@jmt.de<br \/> Web: http:\/\/www.jmt.de<\/p> <p>JMT Mietm\u00f6bel Deutschland GmbH &amp; Co.KG ist spezialisiert auf die Vermietung hochwertiger Mietm\u00f6bel f\u00fcr Messen und Events jeder Gr\u00f6\u00dfenordnung. Von der Bestuhlung bis zur kompletten K\u00fccheneinrichtung werden alle Mietm\u00f6bel fristgerecht geliefert und f\u00fcr die Messe oder das Event aufgebaut. Auf Wunsch werden die M\u00f6bel mit vorhandenen Einrichtungsgegenst\u00e4nden abgestimmt. Spezielle W\u00fcnsche k\u00f6nnen ebenfalls realisiert werden. Hierzu geh\u00f6ren Theken, Lounges, Displays und Regalsysteme. Bei Fragen zu den Messem\u00f6beln, Einrichtungsgegenst\u00e4nden, Lieferzeiten und Konditionen kann man sich direkt pers\u00f6nlich, telefonisch und per E-Mail an die Experten von JMT wenden.<\/p> <p>Kontakt<br \/> JMT Mietm\u00f6bel Deutschland GmbH &amp; Co.KG<br \/> S\u00f6nke Westphal<br \/> Otto-Hahn-Strasse 11<br \/> 40721 Hilden<br \/> +49 (0) 2103 9826-0<br \/> info@jmt.de<br \/> http:\/\/www.jmt.de<\/p> <p>Pressekontakt:<br \/> Web SEO Online<br \/> Dieter Hanke<br \/> Grevenbroicher Str.45<br \/> 50829 K\u00f6ln<br \/> 0221\/29884152<br \/> info@web-seo-online.de<br \/> http:\/\/www.web-seo-online.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Exponatec Cologne bietet 2013 viele interessante Aussteller M\u00f6bel f\u00fcr Messen jeder Art kann man bei JMT schnell und unkompliziert anmieten und liefern lassen &#8211; JMT Mietm\u00f6bel Deutschland GmbH &amp; Co.KG Die Exponatec Cologne ist die bedeutendste Fachmesse f\u00fcr Museen in Europa und wird von der Koelnmesse veranstaltet. Vom 20. Bis zum 22. November 2013<\/p>\n","protected":false},"author":1,"featured_media":152963,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[134],"class_list":["post-28241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultur-kunst-literatur","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/28241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=28241"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/28241\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152963"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=28241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=28241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=28241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}