{"id":28408,"date":"2013-05-13T14:14:07","date_gmt":"2013-05-13T14:14:07","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=28408"},"modified":"2013-05-13T16:30:00","modified_gmt":"2013-05-13T15:30:00","slug":"trend-zum-zweit-oder-drittstudium","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/trend-zum-zweit-oder-drittstudium-1028408\/","title":{"rendered":"Trend zum Zweit- oder Drittstudium"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Studium oder Beruf?\" alt=\"Studium oder Beruf?\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/05\/172478-150x120.jpg\" width=\"150\" height=\"120\" \/><\/p> <p>Weiterbildung oder Studium: Warum nicht nochmal die Schulbank dr\u00fccken?<\/p> <p>Viele Unternehmen lassen sich mittlerweile einiges einfallen, um in die K\u00f6pfe ihrer Mitarbeiter zu investieren. Hier ein Seminar, dort ein Workshop oder mal ganz modern: ein E-Learning.<br \/> Allenfalls knausrige Arbeitgeber versuchen noch mit altert\u00fcmlichen Programmen, wie dem &#8222;Lunch and Learn&#8220;, ihre Mitarbeiter dazu zu bringen, ihre Mittagspause auf dem Altar der Weiterbildung zu opfern. Stellt sich die Frage, warum motivierte Arbeitnehmer nicht gleich nochmal ein vollst\u00e4ndiges Studium absolvieren und im g\u00fcnstigsten Fall das Erlernte direkt in die Arbeitspraxis transferieren? Doppelt h\u00e4lt schlie\u00dflich besser!<\/p> <p><!--more-->Viele Arbeitnehmer in Festanstellung befinden sich in einem Dilemma: Weiterbildungen m\u00f6gen punktuell zu einer Verbesserung der eigenen Leistung erbringen, doch wirklich nachhaltige Impulse setzen solche Ma\u00dfnahmen nicht.<\/p> <p>Trend geht zum Zweit- und Drittstudium<br \/> Darf man neuen Umfragen Glauben schenken, so geht mittlerweile der Trend zum Zweit- und Drittstudium. Doch in vielen Unternehmen ist man darauf nicht vorbereitet. Die F\u00f6rderung von berufsbegleitenden Master-Programmen kommt in der Personalentwicklung oftmals nicht vor. Zu gro\u00df ist die Furcht vor einer kostspieligen und kopflastigen Zusatzausbildung ohne Nutzen f\u00fcr das Unternehmen.<\/p> <p>Theorie und Praxis sinnvoll verkn\u00fcpfen<br \/> Dabei gibt es durchaus sinnvolle Varianten eines Erg\u00e4nzungsstudiums. Was, wenn dem Ingenieur oder dem Informatiker wichtige Wirtschaftskenntnisse f\u00fcr den Berufsalltag fehlen? In einer Wissensgesellschaft, in der lebenslanges Lernen vorausgesetzt wird, kann z.B. ein generalistisches MBA-Studium die L\u00f6sung sein! Am besten aber eines, indem nicht nur frontal Theorie gelehrt, sondern das eigene Unternehmen in Fallstudien und Projektarbeiten integriert wird. Dabei m\u00fcssen berufsbegleitende und berufsintegrierte Konzepte voneinander unterscheiden werden.<\/p> <p>Berufsbegleitende versus berufsintegrierte MBA-Studieng\u00e4nge<br \/> Beim klassischen berufsbegleitenden MBA-Studium sind Arbeit und Studium strikt voneinander getrennt. Der Student erh\u00e4lt zwar klassisches wirtschaftswissenschaftliches Handwerkszeug, eine Br\u00fccke zum operativen Tagesgesch\u00e4ft wird aber in der Regel nicht geschlagen. Beim berufsintegrierten MBA, wie z.B. dem SteinbeisMBA der SIBE an der Steinbeis Hochschule Berlin hingegen wird vom ersten Tag an die erlernte Theorie in die Praxis transferiert. Erfahrene Projektdozenten aus der Wirtschaft unterst\u00fctzen die Studierenden beim Anfertigen von Projektstudienarbeiten, die einen Bezug auf ein konkretes Projekt im Unternehmen haben m\u00fcssen. So werden Theorie und Praxis sinnvoll miteinander verzahnt.<\/p> <p>Wer tr\u00e4gt die Kosten?<br \/> Wer sich geschickt verh\u00e4lt, verhandelt bereits bei seiner Einstellung \u00fcber Fortbildungsvereinbarungen und deren Kosten\u00fcbernahme. Je nach H\u00f6he der Programmgeb\u00fchren eines MBA kann es sein, dass der Arbeitgeber von seinem Recht einer Unternehmensbindung von bis zu f\u00fcnf Jahren Gebrauch macht. Scheidet der Mitarbeiter vor Ablauf der Frist aus, ist er verpflichtet, dem Arbeitgeber die aufgewendeten Kosten anteilig zur\u00fcckzuzahlen.<\/p> <p>Qui bono &#8211; wem nutzt es?<br \/> Dem Unternehmen und dem Arbeitnehmer! Eine echte Win-Win-Situation also.<\/p> <p>Die SCHOOL OF INTERNATIONAL BUSINESS AND ENTREPRENEURSHIP (SIBE) ist die internationale Business School der Steinbeis-Hochschule Berlin (SHB) mit Sitz in Herrenberg und Berlin &#8211; geleitet wird die Hochschule von Prof. Dr. Werner G. Faix, der die SIBE gegr\u00fcndet hat.<br \/> Die SIBE steht f\u00fcr erfolgreichen Wissens-Transfer und systematischen Kompetenz-Aufbau zwischen Wissenschaft und Wirtschaft. Sie ist fokussiert auf Unternehmen, Organisationen und \u00f6ffentliche Verwaltungen und auf kompetente, unternehmerisch global denkende und handelnde High Potentials. Wir sorgen mit unseren Innovations-Projekten und unseren High Potentials bei unseren Partner-Unternehmen f\u00fcr Wachstum und Globalisierung &#8211; und f\u00fcr kompetente F\u00fchrungs- und Nachwuchsf\u00fchrungskr\u00e4fte.<\/p> <p>Mit MBA- und Masterprogrammen (M.A. und M.Sc. im Double-Degree) seit 1994, mit derzeit \u00fcber 1.074 Studierenden, mehr als 2.262 erfolgreichen Absolventen und mit \u00fcber 350 Partner-Unternehmen ist die SIBE kompetenter Partner f\u00fcr Wachstum, Globalisierung und Weiterqualifizierung.<\/p> <p>Kontakt<br \/> School of International Business and Entrepreneurship (SIBE)<br \/> Sandra Flint<br \/> G\u00fcrtelstra\u00dfe 29a\/30<br \/> 10247 Berlin<br \/> 0176 &#8211; 1945 8015<br \/> flint@steinbeis-sibe.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.steinbeis-sibe.de\" title=\"STEINBEIS, SCHOOL OF INTERNATIONAL BUSINESS AND ENTREPRENEURSHIP \" >http:\/\/www.steinbeis-sibe.de<\/a><\/p> <p>Pressekontakt:<br \/> SIBE GmbH<br \/> Sandra Flint<br \/> G\u00fcrtelstr. 29a\/30<br \/> 10247 Berlin<br \/> 030\/49782220<br \/> flint@steinbeis-sibe.de<br \/> http:\/\/www.steinbeis-sibe.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Weiterbildung oder Studium: Warum nicht nochmal die Schulbank dr\u00fccken? Viele Unternehmen lassen sich mittlerweile einiges einfallen, um in die K\u00f6pfe ihrer Mitarbeiter zu investieren. Hier ein Seminar, dort ein Workshop oder mal ganz modern: ein E-Learning. Allenfalls knausrige Arbeitgeber versuchen noch mit altert\u00fcmlichen Programmen, wie dem &#8222;Lunch and Learn&#8220;, ihre Mitarbeiter dazu zu bringen, ihre<\/p>\n","protected":false},"author":1,"featured_media":152953,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[134],"class_list":["post-28408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-karriere-beruf-bildung","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/28408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=28408"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/28408\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152953"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=28408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=28408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=28408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}