{"id":30522,"date":"2013-05-28T14:31:13","date_gmt":"2013-05-28T14:31:13","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=30522"},"modified":"2013-05-29T14:50:54","modified_gmt":"2013-05-29T13:50:54","slug":"plastikmuell-teppich-im-pazifik-so-gross-wie-mitteleuropa","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/plastikmuell-teppich-im-pazifik-so-gross-wie-mitteleuropa-1030522\/","title":{"rendered":"Plastikm\u00fcll-Teppich im Pazifik so gro\u00df wie Mitteleuropa"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Die GreenTec Awards ehren Pioniere, die auf dem Weg in eine umweltbewusste Zukunft, einen Schritt vorausgehen.\" alt=\"Die GreenTec Awards ehren Pioniere, die auf dem Weg in eine umweltbewusste Zukunft, einen Schritt vorausgehen.\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/05\/174863-150x150.jpg\" width=\"133\" height=\"133\" \/>Offizielle Nominierung f\u00fcr den GreenTec Award 2013: One Earth &#8211; One Ocean e.V. f\u00fcr die Sammlung von Plastikm\u00fcll aus Gew\u00e4ssern<\/p> <p>Aus \u00fcber 100 eingereichten Projekten ausgew\u00e4hlt<br \/> Die Umweltorganisation One Earth &#8211; One Ocean, die sich die Reinigung der globalen Gew\u00e4sser vom Plastikm\u00fcll auf ihre Fahnen geschrieben hat, wurde k\u00fcrzlich f\u00fcr den renommierten deutschen Umwelt- und Medienpreis GreenTec Award 2013 nominiert. One Earth &#8211; One Ocean konnte dabei im Umfeld von \u00fcber einhundert Einreichungen in acht verschiedenen Kategorien eine unabh\u00e4ngige Expertenjury \u00fcberzeugen. Parallel dazu nahmen \u00fcber 16.000 Teilnehmer im Internet an einem \u00f6ffentlichen Online-Voting teil.<\/p> <p><!--more-->Die GreenTec Awards ehren nach Aussage des Veranstalters &#8222;Pioniere, die auf dem Weg in eine umweltbewusste Zukunft einen Schritt vorausgehen&#8220;. One Earth &#8211; One Ocean (OEOO) ist eine von drei nominierten Einreichungen der Kategorie &#8222;Galileo Wissenspreis&#8220;, in der Erfindungen und Initiativen ausgezeichnet werden, die unser Leben in unserer Umwelt harmonischer gestalten oder helfen, die Umwelt zu sch\u00fctzen. OEOO wurde durch eine Expertenjury aus \u00fcber einhundert Einreichungen ausgew\u00e4hlt. Eine prominent besetzte und unabh\u00e4ngige Gruppe von 50 Juroren wird unter Ausschluss der \u00d6ffentlichkeit am 4. Juni 2013 aus den jeweils drei Nominierten pro Kategorie einen Preistr\u00e4ger w\u00e4hlen. Dieser wird dann auf einer feierlichen Gala am 30. August in Berlin pr\u00e4miert. Schirmherr der Veranstaltung ist Bundesumweltminister Peter Altmaier. OEOO wird sein Projekt auch im Rahmen einer Ausstellung bei der Gala vor 800 geladenen G\u00e4sten aus Wirtschaft, Politik, Wissenschaft, Kultur und Medien pr\u00e4sentieren.<\/p> <p>Projekt: Nachhaltiger Umweltschutz und Recycling von Plastikm\u00fcll aus Gew\u00e4ssern<\/p> <p>Die Verschmutzung der Weltmeere, Fl\u00fcsse und Seen ist eine der gr\u00f6\u00dften Herausforderungen f\u00fcr die Gesellschaft. Etwa 100-150 Millionen Tonnen M\u00fcll sind heute bereits in den Weltmeeren, jedes Jahr kommen weitere 6,4 Millionen Tonnen hinzu. 80 Prozent davon haben ihren Ursprung an Land. Der M\u00fcll besteht zu fast zwei Dritteln aus Kunststoffen. Heute schwimmen riesige Teppiche aus Plastikm\u00fcll auf den Weltmeeren, der gr\u00f6\u00dfte davon im Pazifik ist so gro\u00df wie Mitteleuropa. Durch Zersetzung und mechanische Einfl\u00fcsse entsteht Mikroplastik, das in die Nahrungskette von Meerestieren und schlie\u00dflich dem Menschen gelangt. \u00dcber die schleichende Einwirkung auf die Nahrungskette bedrohen Plastikbestandteile (Weichmacher) Mensch und Tier. Die Umweltorganisation One Earth &#8211; One Ocean hat sich deshalb die Reinigung der Meere und Binnengew\u00e4sser vom Plastikm\u00fcll mit speziell entwickelten Katamaranen unterschiedlicher Gr\u00f6\u00dfe auf ihre Fahnen geschrieben. Der M\u00fcll wird dabei in Netzen gesammelt, die unter dem Schiff angebracht sind. Erste Prototypen kleiner Schiffe von etwa drei Metern L\u00e4nge und zwei Metern Breite f\u00fcr die Reinigung von Binnengew\u00e4ssern sind bereits im Einsatz. Noch in 2013 soll mit dem Bau des n\u00e4chstgr\u00f6\u00dferen Modells begonnen werden. Das Schiff, ebenfalls auf Basis der Katamaran-Form, wird bereits eine Gr\u00f6\u00dfe von 12 x 9 Metern haben. Mit ihm lassen sich Binnengew\u00e4sser, Flussm\u00fcndungen und bei ruhiger See auch K\u00fcstenabschnitte reinigen<\/p> <p>Vision von G\u00fcnther Bonin, Unternehmer, Segler und Gr\u00fcnder von One Earth &#8211; One Ocean, ist eine &#8222;maritime M\u00fcllabfuhr&#8220; und die R\u00fcckf\u00fchrung des Plastiks in den Wertstoffkreislauf. In einem ersten Schritt wird der Plastikm\u00fcll mit speziell entwickelten Schiffen eingesammelt, sortiert und zerkleinert. Trennung und Recycling des M\u00fclls erfolgen derzeit noch an Land. Aus einer Tonne Plastik lassen sich dabei umweltschonend ca. 900 Liter \u00d6l r\u00fcckgewinnen.<\/p> <p>Bonin ist mit seiner Idee bereits auf gro\u00dfes Interesse gesto\u00dfen. Geplant sind vier unterschiedliche Bootsgr\u00f6\u00dfen bis hin zum hochseetauglichen M\u00fcllsammelschiff, die in einigen Jahren teils vollautomatisch und angetrieben durch moderne Wind- und Solar-Technologien selbst\u00e4ndig das Plastik aus den Gew\u00e4ssern &#8222;grasen&#8220; und die vollen Netze mit Peilsender und Bojen ablegen. Diese werden dann von Schiffen eingesammelt und ihr Inhalt recycelt.<\/p> <p>Der Award<\/p> <p>Am 30. August 2012 findet unter der Schirmherrschaft von Bundesumweltminister Peter Altmaier in Berlin die Preisverleihung des GreenTec Awards 2013 statt. Ziel dieses renommierten Awards ist es, den Einsatz von Umwelttechnologien sowie einen nachhaltigen Lebensstil zu fordern.<\/p> <p>In acht unterschiedlichen Kategorien wurden insgesamt je drei Projekte unter vorgegebenen Kriterien wie Innovationsgrad, Eignung als Botschafter fur Umwelttechnologien oder Wirtschaftlichkeit nominiert. Dabei galt es, neben der Pr\u00fcfung durch eine unabh\u00e4ngige Expertenjury auch im Online-Voting zu \u00fcberzeugen, an dem in diesem Jahr \u00fcber 16.000 Personen teilnahmen. Aus den drei Nominierten pro Kategorie w\u00e4hlt die Expertenjury dann am 4. Juni 2013 jeweils einen Preistrager. Zur Preisverleihung werden rund 800 geladene Gaste aus Wirtschaft, Wissenschaft, Politik, Kultur und Medien erwartet.<\/p> <p>Der in diesem Jahr unter dem neuem Namen GreenTec Award auftretende , aber insgesamt bereits zum sechsten mal verliehene Preis wird in seiner Zielsetzung von zahlreichen prominenten Botschaftern unterst\u00fctzt, z.B. Sir Bob Geldof, Michael Ballhaus, Heinz-Harald Frentzen, Senta Berger, Hannes Jaenicke, Tina Ruland, Nina Eichinger uvm.. Die Prominenten verstehen sich dabei als Multiplikatoren und Vorbilder, die breite Bev\u00f6lkerungsschichten erreichen und die mediale Aufmerksamkeit auf die innovativen Projekte lenken. Weitere Informationen unter <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.greentec-awards.com\" title=\"F\u00f6rderung \u00f6kologischen und \u00f6konomischen Engagements und den Einsatz von Umwelttechnologien\" >http:\/\/www.greentec-awards.com<\/a>.<\/p> <p>One Earth &#8211; One Ocean e. V.<br \/> Die Umweltorganisation One Earth &#8211; One Ocean (OEOO) mit Sitz in M\u00fcnchen Garching hat das Ziel, unsere Gew\u00e4sser vom Plastikm\u00fcll zu befreien. Bereits heute schwimmen auf den Weltmeeren riesige Teppiche aus Plastikm\u00fcll, der gr\u00f6\u00dfte davon im Pazifik ist so gro\u00df wie Mitteleuropa, d.h. wie Deutschland, \u00d6sterreich, Schweiz, Polen, Luxemburg, Ungarn und Tschechien zusammen. Schreitet die Verschmutzung im derzeitigen Tempo weiter voran, werden die Meere in wenigen Jahren vollst\u00e4ndig verm\u00fcllt sein.<br \/> Gr\u00fcnder von One Earth &#8211; One Ocean ist G\u00fcnther Bonin, 56, Inhaber einer IT-Firma und passionierter Segler. Seine Vision der &#8222;maritimen M\u00fcllabfuhr&#8220; gliedert sich in mehrere Stufen: In einem ersten Schritt wird der Plastikm\u00fcll mit speziell von ihm entwickelten Ger\u00e4ten auf den Meeren eingesammelt, sortiert und zerkleinert, z.B. von den drei Millionen Fischern in Europa, gegen Bezahlung. Trennung und Recycling des M\u00fclls erfolgt an Land. In einer sp\u00e4teren Phase soll das gesammelte Plastik direkt an Bord von Tankern in \u00d6l r\u00fcckverwandelt werden. Aus einer Tonne Plastik lassen sich ca. 800-900 Liter \u00d6l r\u00fcckgewinnen.<br \/> Was wie die Utopie eines Idealisten klingt, nimmt mittlerweile konkrete Formen an. Mehr als 100 Unternehmen und Privatpersonen unterst\u00fctzen das Projekt in unterschiedlicher Weise. Der prominenteste unter ihnen ist Thomas Hahn, der bei BMW Oracle das Siegerschiff des America&#8220;s Cup mitkonstruierte. Hahn unterst\u00fctzt ebenso wie der renommierte Schiffsbauer Dirk Lindenau OEOO auch bei der Entwicklung und dem Bau der M\u00fcllschlucker-Schiffe. Erste Prototypen sind bereits fertiggestellt und im Einsatz.<br \/> Weitere Informationen erhalten Sie unter http:\/\/www.oneearth-oneocean.com oder auf der Facebook-Seite unter https:\/\/www.facebook.com\/pages\/One-Earth-One-Ocean\/163573257046660<\/p> <p>Kontakt<br \/> One Earth &#8211; One Ocean e.V.<br \/> G\u00fcnther Bonin<br \/> LIchtenbergstr. 8<br \/> 85748 Garching bei M\u00fcnchen<br \/> 089-5484 2361<br \/> info@oneearth-oneocean.de<br \/> http:\/\/www.oneearth-oneocean.de<\/p> <p>Pressekontakt:<br \/> Gr\u00fcne Welle Kommunikation<br \/> Frank Brodmerkel<br \/> Notburgastr. 3<br \/> 80639 M\u00fcnchen<br \/> 089-17876165<br \/> kontakt@gruenewellepr.de<br \/> http:\/\/www.gruenewellepr.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Offizielle Nominierung f\u00fcr den GreenTec Award 2013: One Earth &#8211; One Ocean e.V. f\u00fcr die Sammlung von Plastikm\u00fcll aus Gew\u00e4ssern Aus \u00fcber 100 eingereichten Projekten ausgew\u00e4hlt Die Umweltorganisation One Earth &#8211; One Ocean, die sich die Reinigung der globalen Gew\u00e4sser vom Plastikm\u00fcll auf ihre Fahnen geschrieben hat, wurde k\u00fcrzlich f\u00fcr den renommierten deutschen Umwelt- und<\/p>\n","protected":false},"author":1,"featured_media":152996,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[134],"class_list":["post-30522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-umwelt-klima-energie","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/30522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=30522"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/30522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152996"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=30522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=30522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=30522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}