{"id":3168,"date":"2012-11-12T15:53:00","date_gmt":"2012-11-12T14:53:00","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=3168"},"modified":"2015-06-15T06:54:47","modified_gmt":"2015-06-15T05:54:47","slug":"neue-therapie-gegen-ruecken-und-gelenkschmerzen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/neue-therapie-gegen-ruecken-und-gelenkschmerzen-103168\/","title":{"rendered":"Gro\u00dfe Erfolge auch bei austherapierten Patienten"},"content":{"rendered":"<p>Der Mosbacher Physiotherapeut Daniel Gatzka hat ein Buch \u00fcber die Biotonus-Therapie verfasst &#8211; Gro\u00dfe Erfolge auch bei austherapierten Patienten<\/p> <p>Physiotherapeut Daniel Gatzka (www.physiotherapie-gatzka.de (http:\/\/www.physiotherapie-gatzka.de)aus Mosbach hat ein Buch geschrieben, das R\u00fcckenkranke und Menschen mit Beschwerden im Gelenk- und Bewegungsapparat besonders interessieren wird: &#8222;Die Biotonus-Therapie. Schmerzfrei besser f\u00fchlen, besser leben.&#8220; Darin stellt er eine Therapieform vor, die verbl\u00fcffende Erfolge geliefert und schon manchen Patienten vor einer Operation bewahrt hat. <!--more-->In einer Studie bei der Firma W\u00fcrth wurden diese Erfolge best\u00e4tigt. Eine schwere Knieverletzung brachte Daniel Gatzka schon in jungen Jahren dazu, sich intensiv mit den Themen Schmerz und Muskelaufbau sowie der Therapie auseinanderzusetzen. Als selbstst\u00e4ndiger Physiotherapeut machte er die Erfahrung, dass viele Therapieformen nicht immer oder verschiedenen Patienten nicht gleicherma\u00dfen halfen. Auf seiner Suche stie\u00df er auf die von Frank Himmelsbach entwickelte Biotonus-Therapie.. Mit dieser Behandlungmethode korrigiert der Therapeut die Spannungsverh\u00e4ltnisse in den Muskeln &#8211; und das mit verbl\u00fcffendem Erfolg. Bereits nach wenigen Behandlungen lassen die Schmerzen meist deutlich nach. In Verbindung mit \u00dcbungen, die die Patienten zuhause absolvieren, verbessert sich die Situation der Patienten in der Regel erheblich. Zahlreiche Referenzschreiben von Sportlern und anderen Patienten zeugen von dem Erfolg dieser Behandlungsmethode. So behandelt Daniel Gatzka seit Jahren unter anderem die Gewichtheber Nico M\u00fcller, Jakob Neufeld und Manfred Nerlinger sowie international erfolgreiche Springreiter wie Thomas M\u00fchlbauer und den Profiboxer und IBF-Juniorenweltmeister Dominik Britsch. Ein Zahnarzt lobt die Biotonus-Therapie: &#8222;Ich kann wieder Sport treiben, meine Schmerzen in Kniegelenk und Schultern sind weg, und ich f\u00fchle mich wohl.&#8220; Eine andere Patientin mit insgesamt vier erlittenen Bandscheibenvorf\u00e4llen klagte vor der Behandlung durch Daniel Gatzka \u00fcber erhebliche Schmerzen, Gleichgewichtsst\u00f6rungen und Taubheit der Extremit\u00e4ten. Dank der Biotonus-Therapie kann sie inzwischen wieder fast normal arbeiten. In dem neu erschienenen Buch erl\u00e4utert Daniel Gatzka die Zusammenh\u00e4nge zwischen Gelenken, Muskeln und Schmerzen im Bewegungsapparat. Au\u00dferdem enth\u00e4lt das Buch eine Reihe von \u00dcbungen, die jeder zu Hause absolvieren kann, auch zur Vorbeugung von R\u00fccken- und Gelenkschmerzen. Das Buch kann im Buchhandel oder \u00fcber die Homepage von Daniel Gatzka (http:\/\/www.physiotherapie-gatzka.de) bestellt werden.<\/p> <p>Daniel Gatzka ist staatlich gepr\u00fcfter Physiotherapeut aus Mosbach. Er befasst sich seit vielen Jahren mit den urs\u00e4chlichen Problemen von Schmerzpatienten. An sechs Standorten, unter anderem in Buchen, Mosbach und Adelsheim-Sennfeld, arbeiten er und seine Mitarbeiter mit der neuen und erfolgreichen Biotonus-Therapie. Mit dieser gelingt es, selbst austherapierten Menschen zu helfen und zahlreiche Operationen zu verhindern.<\/p> <p>Kontakt: Physiotherapie Gatzka Daniel Gatzka Am Henschelberg 8 74821 Mosbach 0800 \/ 42 895 20 daniel.gatzka@web.de <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.physiotherapie-gatzka.de\" title=\"Die Biotonus-Therapie ist nicht, wie viele andere Therapieformen, auf Behandlungstechniken und ein Gebiet fixiert, sondern deckt das gesamte Behandlungsspektrum der Orthop\u00e4die, Chirurgie, P\u00e4diatrie und Neurologie ab\" >http:\/\/www.physiotherapie-gatzka.de<\/a><\/p> <p>Pressekontakt: die feder Martin Bernhard Zu den Dill\u00e4ckern 3 74722 Buchen 06281564338 Martin.Bernhard@diefeder.de http:\/\/www.diefeder.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Der Mosbacher Physiotherapeut Daniel Gatzka hat ein Buch \u00fcber die Biotonus-Therapie verfasst &#8211; Gro\u00dfe Erfolge auch bei austherapierten Patienten Physiotherapeut Daniel Gatzka (www.physiotherapie-gatzka.de (http:\/\/www.physiotherapie-gatzka.de)aus Mosbach hat ein Buch geschrieben, das R\u00fcckenkranke und Menschen mit Beschwerden im Gelenk- und Bewegungsapparat besonders interessieren wird: &#8222;Die Biotonus-Therapie. Schmerzfrei besser f\u00fchlen, besser leben.&#8220; Darin stellt er eine Therapieform vor,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108],"tags":[134],"class_list":["post-3168","post","type-post","status-publish","format-standard","hentry","category-medizin-gesundheit","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=3168"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3168\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=3168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=3168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=3168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}