{"id":31701,"date":"2013-06-04T08:16:51","date_gmt":"2013-06-04T08:16:51","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=31701"},"modified":"2015-04-30T10:28:06","modified_gmt":"2015-04-30T09:28:06","slug":"welche-ausbildung-in-der-pferdewirtschaft","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/welche-ausbildung-in-der-pferdewirtschaft-1031701\/","title":{"rendered":"Welche Ausbildung in der Pferdewirtschaft?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Pferdewirt oder Studiengang?\" alt=\"Pferdewirt oder Studiengang?\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/06\/175912-150x150.jpg\" width=\"132\" height=\"132\" \/>Englische Horse-Grooms<\/p> <p>Vorreiter f\u00fcr deutsche Ausbildungsmodelle in der Pferdewirtschaft<br \/> Wer in Deutschland in der professionellen Pferdewelt Fuss fassen will, hat die M\u00f6glichkeit einen Pferdemanagementstudiengang oder eine klassische Ausbildung als Pferdewirt zu absolvieren. Neben den pferde- und agrarwissenschaftlichen Aspekten, ist das betriebswirtschaftliche Know-how im Studium von gro\u00dfer Bedeutung. Hingegen stehen beim Pferdewirt die individuelle Pferdef\u00fctterung und -pflege, Futterbeschaffung, Stall- und Weidemanagement und das Bewegen der Pferde im Vordergrund.<\/p> <p><!--more-->Aktuell entstehen an europ\u00e4ischen Universit\u00e4ten eine Vielzahl von Studieng\u00e4ngen in der Pferdewirtschaft. Ausbildungsstellen sind demgegen\u00fcber eher rar. Das Studium kann, sofern die schulischen Abschl\u00fcsse es erlauben, eine Alternative zum Ausbildungsplatz sein, jedoch wird das hohe Leistungsniveau oft untersch\u00e4tzt und erh\u00f6ht das Risiko des Studienabbruchs.<\/p> <p>Absolventen pferdewissenschaftlicher Studieng\u00e4nge die Pferde- und Betriebswirtschaftliches Wissen vereinen, sind zwar hervorragend ausgebildet, aber f\u00fcr kleine und mittlere Betriebe kaum finanzierbar. Wiederum kennt sich der klassisch ausgebildete Pferdewirt beachtlich in der Pflege der Pferde aus, kann aber die betriebswissenschaftlichen Anforderungen meisst nicht erf\u00fcllen.<\/p> <p>England als Vorreiter<br \/> Die Engl\u00e4nder sind Vorreiter auf diesem Gebiet, indem sie begonnen haben die Kompetenzen ihrer Horsegrooms zu erweitern. Der Horse Groom ist keine gesetzlich anerkannte Berufsausbildung, wie in Deutschland der Pferdewirt, sondern ist mit dem deutschen Pferdepfleger zu vergleichen, der eine Pr\u00fcfung vor der FN ablegen kann, sofern er sich Pferdepfleger FN nennen will. Entsprechende Zertifikate kann auch der englische Horsegroom erwerben z.B \u00fcber die Association of British Riding Schools oder die British Grooms Association.<\/p> <p>Er arbeitet in den Bereichen allgemeine Pferdepflege, medizinische Versorgung und \u00fcbernimmt mittlerweile auch zahlreiche Zusatzaufgaben im Managementbereich, in der Reiseplanung f\u00fcr Turnierreiter, der Buchhaltung von Pferdewirtschaftsbetrieben etc.. Von diesem breit gef\u00e4cherten Wissen profitieren alle.<\/p> <p>F\u00fcr Profisportreiter \u00fcbernimmt der Groom sowohl die Verantwortung in den Bereichen Pflege und medizinische Grundversorgung, als auch f\u00fcr das gesamte Betriebsmanagement. So k\u00f6nnen sich Profisportreiter mit Hilfe ihrer Grooms vollkommen auf den Sport fokussieren.<\/p> <p>In landwirtschaftlichen Betrieben, die auf Pferdehaltung umgestellt haben, erlaubt der Groom den Landwirten, sich weiterhin nur um die landwirtschaftlichen Aspekte, wie Futterherstellung oder den Ausbau von Stallungen und Reitanlagen zu konzentrieren, w\u00e4hrend er die t\u00e4glichen Stall- und Pferdearbeiten, sowie organisatorische und buchhalterische Aufgaben \u00fcbernimmt.<\/p> <p>F\u00fcr kleinere und mittlere Pferdebetriebe stellt der Groom die rechte Hand in allen Punkten des t\u00e4glichen Gesch\u00e4fts dar und hat den entscheidenden Vorteil, dass er f\u00fcr die Betriebe wirtschaftlich tragbar ist, weil er nicht auf dem Gehaltsniveau akademischer Mitarbeiter liegt, trotzdem auch betriebwirtschaftliche und organisatorische Aufgaben \u00fcbernehmen kann.<\/p> <p>Damit bietet der Groom neben dem gro\u00dfen Nutzen f\u00fcr Pferdebetriebe vor allem jungen Leuten die Chance, in ihre Traumsparte einzusteigen, auch wenn sie keine Lehrstelle finden oder nicht \u00fcber die ausreichenden schulischen Anforderungen f\u00fcr ein Studium verf\u00fcgen.<\/p> <p>Deutschland zieht nach<br \/> Mittlerweile sind die englischen Horse-Grooms auch in einigen deutschen St\u00e4llen zum Geheimtip geworden und hoch gesch\u00e4tzte Mitarbeiter, aufgrund ihrer vielf\u00e4ltigen Qualifikationen.<\/p> <p>Mit ihnen stehen dem Arbeitsmarkt Mitarbeiter zur Verf\u00fcgung mit guten Qualifikationen, breitem Wissensschatz und einem Preisniveau, dass sich auch kleinere und mittlere Betriebe leisten k\u00f6nnen, die den \u00fcberwiegenden Anteil der Pferdebetriebe in Deutschland ausmachen.<\/p> <p>Dieses duale Ausbildungskonzept bietet nun auch die Pferdepflegerschule NRW an. \u00dcber die Inhalte der Pferdepflege und die Intensivierung von pferdespezifischen Lernthemen hinaus, bietet sie einen fach\u00fcbergreifenden Ansatz durch die Erg\u00e4nzung wirtschaftlicher Grundlagen wie Officemanagement, Buchf\u00fchrung, Marketing, Veranstaltungsorganisation etc.. \u00dcber der unabdingbaren Fachkompetenz hinaus, liegt ein gro\u00dfes Augenmerk auch auf Softskills wie Zuverl\u00e4ssigkeit, Verantwortungsbewusstsein, Durchhalteverm\u00f6gen, Teamf\u00e4higkeit etc.<\/p> <p>In Praxisphasen und Fachvortr\u00e4gen, haben junge Leute hier die M\u00f6glichkeit interdisziplin\u00e4res Fachwissen zu erlangen, um ihnen so neue Chancen am Arbeitsmarkt zu er\u00f6ffnen.<\/p> <p>Weitere Infos unter: www.pferdepflegerschule.de<\/p> <p>Argentur<\/p> <p>Kontakt:<br \/> Agentur Pferdepflegerschule NRW<br \/> Agentur Media und Event<br \/> Brandsackerstr. 10<br \/> 40764 Langenfeld<br \/> 03221 1240947<br \/> post@pferdepflegerschule.de<br \/> http:\/\/www.pferdepflegerschule.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Englische Horse-Grooms Vorreiter f\u00fcr deutsche Ausbildungsmodelle in der Pferdewirtschaft Wer in Deutschland in der professionellen Pferdewelt Fuss fassen will, hat die M\u00f6glichkeit einen Pferdemanagementstudiengang oder eine klassische Ausbildung als Pferdewirt zu absolvieren. Neben den pferde- und agrarwissenschaftlichen Aspekten, ist das betriebswirtschaftliche Know-how im Studium von gro\u00dfer Bedeutung. Hingegen stehen beim Pferdewirt die individuelle Pferdef\u00fctterung und<\/p>\n","protected":false},"author":1,"featured_media":153023,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[109],"tags":[134],"class_list":["post-31701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiere-haustiere","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/31701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=31701"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/31701\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153023"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=31701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=31701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=31701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}