{"id":3187,"date":"2012-11-14T16:00:07","date_gmt":"2012-11-14T15:00:07","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=3187"},"modified":"2016-04-08T14:27:18","modified_gmt":"2016-04-08T13:27:18","slug":"fairtrade-deutschland-zeichnet-erste-schule-aus","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/fairtrade-deutschland-zeichnet-erste-schule-aus-103187\/","title":{"rendered":"Fairtrade Deutschland zeichnet erste Schule aus!"},"content":{"rendered":"<p>Die Siegelinitative TransFair hat in diesem Jahr die Kampagne Fairtrade Schools gestartet. Die Auszeichnung f\u00fcr faire Schulen steht unter der Schirmherrschaft von Sylvia L\u00f6hrmann, der stellvertretenden Ministerpr\u00e4sidentin und Ministerin f\u00fcr Schule und Weiterbildung des Landes Nordrhein-Westfalen. I am Fair! informiert \u00fcber die erste Auszeichnung Deutschlands.<\/p> <p>Mit der Kampagne k\u00f6nnen Schulen in NRW zeigen, dass sie sich aktiv f\u00fcr den fairen Handel einsetzen wollen. Dabei erhalten Sch\u00fclerinnen und Sch\u00fcler ein Bewusstsein daf\u00fcr, dass auch in jungen Jahren die Welt verbessert werden kann. Die Kampagne Fairtrade Schools wird von der Stiftung Umwelt und Entwicklung Nordrhein-Westfalen gef\u00f6rdert.<\/p> <p><!--more-->IST DIE SCHULE FAIR? F\u00dcNF KRITERIEN Zur Beurteilung ob Schulen fair handeln wurden f\u00fcnf Kriterien entwickelt. Eine Fairtrade School muss ein Fair trade-Schulteam gr\u00fcnden, dass aus Lehrerinnen, Lehrern, Sch\u00fclerinnen, Sch\u00fclern, Eltern und weiteren Interessierten besteht. Dann muss die Schule einen Fairtrade-Leitfaden erstellen, der vom Rektor oder der Rektorin unterschrieben sein muss. Als drittes Kriterium m\u00fcssen in der Schule fair gehandelte Produkte angeboten oder verzehrt werden.<\/p> <p>In mindestens zwei Jahrgansstufen muss in zwei unterschiedlichen F\u00e4chern das Thema &#8222;Fair trade&#8220; oder &#8222;fairer Handel&#8220; im Unterricht behandelt werden. Zus\u00e4tzlich m\u00fcssen Fair trade Schulen einmal im Jahr eine Aktion rund um das Thema &#8222;Fairtrade&#8220; veranstalten. Abschlie\u00dfend muss die Erf\u00fcllung dieser Kriterien in dem Fairtrade-Schools-Blog festgehalten werden.<\/p> <p>DIE ERSTE AUSZEICHNUNG &#8211; FAIRTRADE DEUTSCHLAND Heute wird in D\u00fcsseldorf das erzbisch\u00f6fliche Suitbertus-Gymnasium als erste Fairtrade-Schule Deutschlands aufgezeichnet. Die Feier startet um 18:30 Uhr im Foyer des Gymnasiums. Dabei wird Sylvia L\u00f6hrmann die Auszeichnung \u00fcberreichen. Musik aus aller Welt begleitet den Abend. Bei der Veranstaltung wird der Fair-o-mat eingeweiht, der erste faire S\u00fc\u00dfigkeiten-Automat.<\/p> <p>Auch Deutschlands erster Fairtrade Marktplatz und Onlineshop f\u00fcr nachhaltigen Handel &#8211; I am Fair! &#8211; gratulierte dem D\u00fcsseldorfer Gymnasium zur Auszeichnung und w\u00fcnscht allen Beteiligten weiterhin viel Erfolg. Das Erkrather Start-Up bietet seit April viele verschiedene Produkte, unter anderem auch S\u00fc\u00dfwaren, in seinem Online-Shop (www.iamfair.de (http:\/\/www.iamfair.de)) an. Ob fair gehandelte Schokolade, N\u00fcsse und Fr\u00fcchte oder Fair Trade Kaffee, Tee oder Kakao. Auch viele faire Kleidungsst\u00fccke findet man im Webshop.<\/p> <p>Das Erkrather Start-Up &#8222;I am Fair!&#8220; macht seit April 2012 jeden Einkauf zu einem fairen Deal f\u00fcr K\u00e4ufer und H\u00e4ndler. Auf dem neuen eCommerce-Portal sind alle angebotenen Produkte mit dem unabh\u00e4ngigen &#8222;Fair Trade&#8220;-Siegel zertifiziert.<\/p> <p>I am Fair f\u00fchrt konsequent die Idee des nachhaltigen Einkaufens aus, die dem ganzen Gesch\u00e4ftskonzept zugrunde liegt. Unter www.iamfair.de haben Kunden n\u00e4mlich Zugriff auf \u00fcber 500 Artikel, die alle ausschlie\u00dflich Fairtrade zertifiziert sind. Die Produktpalette reicht von kulinarischen Delikatessen \u00fcber Fashion f\u00fcr die ganze Familie bis hin zu stilvoller Badausstattung. Das Angebot w\u00e4chst kontinuierlich, basierend auf der von der TransFair e.V. (Fairtrade Deutschland) zur Verf\u00fcgung gestellten Produktliste. Angelegt als &#8222;Shop-in-Shop&#8220; Prinzip stellt iamfair.de den H\u00e4ndlern dabei die Online-Plattform inklusiv Technik, die Zahlungsabwicklung bei Bestellungen, sowie die Vermarktung &#8211; die Bestellungen werden von den H\u00e4ndlern direkt an den Kunden versendet.<\/p> <p>Kontakt: I am Fair! UG (haftungsbeschr\u00e4nkt) Andreas Grosch Gruitener Str. 5 40699 Erkrath 02104 \/ 912 65 61 andreas.grosch@iamfair.de http:\/\/www.iamfair.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Siegelinitative TransFair hat in diesem Jahr die Kampagne Fairtrade Schools gestartet. Die Auszeichnung f\u00fcr faire Schulen steht unter der Schirmherrschaft von Sylvia L\u00f6hrmann, der stellvertretenden Ministerpr\u00e4sidentin und Ministerin f\u00fcr Schule und Weiterbildung des Landes Nordrhein-Westfalen. I am Fair! informiert \u00fcber die erste Auszeichnung Deutschlands. Mit der Kampagne k\u00f6nnen Schulen in NRW zeigen, dass sie<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[123],"tags":[134],"class_list":["post-3187","post","type-post","status-publish","format-standard","hentry","category-familie-jugend-erziehung","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=3187"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3187\/revisions"}],"predecessor-version":[{"id":201926,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3187\/revisions\/201926"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=3187"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=3187"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=3187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}