{"id":3231,"date":"2012-11-20T16:32:50","date_gmt":"2012-11-20T15:32:50","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=3231"},"modified":"2025-12-05T13:02:17","modified_gmt":"2025-12-05T12:02:17","slug":"tipps-zum-einsatz-von-infografiken-im-online-marketing","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/tipps-zum-einsatz-von-infografiken-im-online-marketing-103231\/","title":{"rendered":"Tipps zum Einsatz von Infografiken im Online-Marketing"},"content":{"rendered":"<p>Das Netz ist voller Informationen, teilweise voll von umfangreichen und komplexen Sachverhalten. Die Zeit, die wir zur Rezeption zur Verf\u00fcgung haben, ist durch einen immer st\u00e4rker werdenden Informations\u00fcberfluss in den letzten Jahren stark gesunken. Infografiken erkl\u00e4ren Zusammenh\u00e4nge visuell in einer anschaulichen und ansprechenden Weise. Texte oder Fotomaterial allein k\u00f6nnen diese Transferleistung oft nicht gew\u00e4hrleisten. Leserfreundlich, einpr\u00e4gsam und schnell erfassbar \u2013 das sind die Vorteile von Infografiken.<\/p> <p><!--more-->Infografiken erkl\u00e4ren und illustrieren schwer verst\u00e4ndliche Texte und erleichtern so die Informationsaufnahme. Vor allem technische Fakten und Anwendungen lassen sich in der Regel fotografisch nicht aufzeigen oder als reiner Text beschreiben. In einer Infografik ist die Reduzierung auf die Kernfeatures und Produktmerkmale besser m\u00f6glich. Trockene Zahlen werden durch eine Illustration untermalt und komplexe Zusammenh\u00e4nge werden dem Leser spielerisch deutlich gemacht. Das verschafft der Infografik auch gro\u00dfe Beliebtheit in sozialen Netzwerken: Schnell verstanden, schnell geliked, schnell geteilt.<\/p> <p>Grafiken wecken die Neugier des Betrachters und damit von potenziellen Kunden. Interessenten werden in die Thematik hineingezogen und sind eher bereit, den passenden Text dazu zu lesen. Damit steigt auch die Bekanntheit Ihres Unternehmens. In der Pressearbeit sind Infografiken ebenfalls zu einem bedeutenden Instrument geworden. Journalisten k\u00f6nnen so Pressemitteilungen zu technischen Themen attraktiver platzieren. Alle Vorteile von Infografiken sowie Tipps zur Erstellung sehen Sie in der \u00dcbersicht:<\/p> <p>Vorteile des Einsatzes von Infografiken:<br \/> \u2022 Machen dem Leser komplexe Zusammenh\u00e4nge verst\u00e4ndlich<br \/> \u2022 Komprimieren gro\u00dfe Mengen an Informationen<br \/> \u2022 Veranschaulichen visuell<br \/> \u2022 Schnell einpr\u00e4gsam f\u00fcr den viel besch\u00e4ftigten Leser von heute<br \/> \u2022 Kosteng\u00fcnstig durch Mehrfachverwertung (Webauftritt, Pressemitteilung oder Produktbrosch\u00fcre)<\/p> <p>Tipps &amp; Tricks bei der Erstellung einer Infografik:<br \/> \u2022 Keep it simple: Versuchen Sie nicht zu viel in einem Bild unterzubekommen.<br \/> \u2022 Die Farbe macht\u00b4s: Entscheiden Sie sich dabei jedoch f\u00fcr ein Farbschema, um den Leser nicht zu \u00fcberfordern.<br \/> \u2022 Facts &amp; Figures: Forschen Sie nach einigen tollen Fakten und Statistiken, die Sie visuell aufbereiten wollen.<br \/> \u2022 Infografik als visueller Essay: Stellen Sie sich die Infografik als visuellen Essay vor. Dabei muss sicher gestellt sein, dass Ihre Argumente relevant und stimmig sind.<br \/> \u2022 Vergessen Sie nie: Infografiken wollen Wissen schnell vermitteln. Die Bedeutung der komplexen Inhalte muss leserfreundlich und schnell einpr\u00e4gsam sein.<br \/> \u2022 Geben Sie die Quelle an: Verweisen Sie in Ihrer Infografik stets auf die Quelle der Fakten.<\/p> <p>Mit diesen Tools erstellen Sie kinderleicht Infografiken:<br \/> F\u00fcr die eigenen Kan\u00e4le \u2013 Corparate Blog, Facebook-Seite, Twitter-Stream, Pinterest, usw. \u2013 k\u00f6nnen Infografiken \u00fcber die Communities ihre Unternehmensinhalte verbreiten. Mit diesen Tools, gelingt Ihnen das zeitsparend und effektiv:<\/p> <p>Piktochart<br \/> Piktochart ist der Vorreiter unter den Infografik-Tools. Es \u00fcberzeugt durch hohe Usability und vier kostenfreien Layout-Formen zur Gestaltung. Die Bearbeitungsmaske erinnert an das Pr\u00e4sentationsprogramm Keynote und ist daher sehr eing\u00e4nglich. \u00dcber eine Taskleiste k\u00f6nnen altbekannte Redaktionsdienste ausgew\u00e4hlt werden. F\u00fcr je 1, 99 Dollar k\u00f6nnen Nutzer weitere Layout-Formen hinzukaufen.<\/p> <p>visual.ly<br \/> Der Dienst visual.ly bietet Ihnen die M\u00f6glichkeit, Twitter- und Facebook-Daten ohne Design-Kenntnisse selbst zu visualisieren. Der kostenlose Service stellt insgesamt drei Arten von Twitter-Infografiken und zwei Facebook-Variationen zur Verf\u00fcgung. F\u00fcr die Erstellung einer Infografik ist das Einloggen bei Twitter bzw. Facebook notwendig.<\/p> <p>Google Public<br \/> Mit dem Google Diagramme-Explorer \u201ePublic Data\u201d k\u00f6nnen Sie gro\u00dfe Datenmengen einfach analysieren, visualisieren und kommunizieren. Neben Text und Tabellen bietet Ihnen Google die Option, unterschiedlichste Grafiken zu erstellen. Die Bedienung ist intuitiv und leicht zu erlernen.<\/p> <p>Best Practice: Von Marktforschung bis Social Recruiting<br \/> Ob Studien oder Personalmarketing: Mit Infografiken lassen sich jegliche Informationen verarbeiten. Der TWT Interactive-Partner Adobe bereitet seinen aktuellen Digital Index Report mit einer Infografik visuell auf. Die wichtigsten Erkenntnisse, n\u00e4mlich dass das Marken-Engagement auf Facebook um 900 Prozent gestiegen ist, werden grafisch zusammengefasst. Leser erhalten so einen direkten \u00dcberblick zu allen zentralen Studienergebnissen.<\/p> <p>Doch auch im Recruiting spielen Infografiken eine bedeutende Rolle. Die Allianz sucht per Infografik Praktikanten. Weiterf\u00fchrende Angaben, z.B. Freizeitm\u00f6glichkeiten am Standort oder \u201cnice-to-know\u201d-Informationen zum Unternehmen, runden die Infografik und damit das Bild des Unternehmens ab.<br \/> All dies zeigt, dass Infografiken zu einer festen Gr\u00f6\u00dfe in der Unternehmenskommunikation geworden sind, die keine Redaktion ungenutzt lassen sollte.<\/p> <p>Autor: Hans J. Even<br \/> Gesch\u00e4ftsf\u00fchrer TWT Interactive GmbH<br \/> Diplom-Kaufmann<\/p> <p>Adresse:<br \/> TWT Interactive GmbH<br \/> Corneliusstra\u00dfe 20-22,<br \/> 40215 D\u00fcsseldorf<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Netz ist voller Informationen, teilweise voll von umfangreichen und komplexen Sachverhalten. Die Zeit, die wir zur Rezeption zur Verf\u00fcgung haben, ist durch einen immer st\u00e4rker werdenden Informations\u00fcberfluss in den letzten Jahren stark gesunken. Infografiken erkl\u00e4ren Zusammenh\u00e4nge visuell in einer anschaulichen und ansprechenden Weise. Texte oder Fotomaterial allein k\u00f6nnen diese Transferleistung oft nicht gew\u00e4hrleisten. Leserfreundlich,<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114],"tags":[],"class_list":["post-3231","post","type-post","status-publish","format-standard","hentry","category-marketing-public-relations"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=3231"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3231\/revisions"}],"predecessor-version":[{"id":270351,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3231\/revisions\/270351"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=3231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=3231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=3231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}