{"id":32933,"date":"2013-06-12T09:44:17","date_gmt":"2013-06-12T09:44:17","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=32933"},"modified":"2013-06-13T14:35:55","modified_gmt":"2013-06-13T13:35:55","slug":"aktuelle-markttrends-im-projektmanagement","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/aktuelle-markttrends-im-projektmanagement-1032933\/","title":{"rendered":"Aktuelle Markttrends im Projektmanagement"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-33028\" title=\"der Trend geht zu Integration neuer Methoden\" alt=\"der Trend geht zu Integration neuer Methoden\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/06\/Screenshot_11.jpg\" width=\"225\" height=\"132\" \/>Studie vergleicht Softwarel\u00f6sungen f\u00fcr das Projektmanagement<\/p> <p>Eine aktuelle BARC-Studie untersucht und bewertet 26 aktuelle Softwarel\u00f6sungen f\u00fcr das Projektmanagement<\/p> <p>Die 7. Auflage der Studie &#8222;Project Management Software Systems Requirements, Selection Process and Products&#8220; ist ab sofort verf\u00fcgbar. F\u00fcr die neue Auflage wurden 26 f\u00fchrende L\u00f6sungen anhand von \u00fcber 300 Kriterien getestet. 130 dieser Kriterien wurden f\u00fcr die 7. Auflage komplett neu formuliert, aktualisiert und erg\u00e4nzt, um aktuelle Markttrends widerzuspiegeln. Die Studie wurde von BARC (Business Application Research Center) in Zusammenarbeit mit parameta und der Gesellschaft f\u00fcr Projektmanagement (GPM) erstellt.<\/p> <p><!--more-->Gute Usability, Webfunkionen und Mobilit\u00e4t<\/p> <p>Dr. Mey Mark Meyer, Autor der Studie, konnte bei fast allen L\u00f6sungen Fortschritte im Vergleich zu vorher getesteten Versionen erkennen. &#8222;Die Anbieter haben insbesondere weiter in die Bedienbarkeit investiert. Solide Funktionen f\u00fcr das Ressourcen- und Projektportfolio-Management sind inzwischen Standard, der Trend geht zur Integration neuerer Methoden wie Scrum. Funktionen, die das Projektmanagement sinnvoll erg\u00e4nzen, etwa Produktmanagement und Helpdesk-Funktionen, sind im Kommen.&#8220;<\/p> <p>Einige Kernerkenntnisse der Studie:<\/p> <p>&#8211; Usability\/Optik: Nahezu alle Anbieter nutzen die neuen Versionen, um die Bedienoberfl\u00e4chen in ein moderneres Layout zu bringen, und die Bedienung zu vereinfachen. Webanwendungen erhalten zunehmend mehr interaktive Elemente und werden Desktopprogrammen damit immer \u00e4hnlicher.<\/p> <p>&#8211; Mobilit\u00e4t\/&#8220;Live-Daten&#8220;: Es zeigt sich, dass sich der Trend zu mobilen Anwendungen zunimmt. Die Anbieter konzentrieren sich dabei meist auf Zeiterfassung, Reporting und Dashboards.<\/p> <p>&#8211; Endlich SaaS: Software as a Service wird von immer mehr Anbietern als zus\u00e4tzliche Option angeboten. Technisch steht dahinter allerdings oftmals eher ein Hosting der Software durch den Anbieter &#8211; gleichwohl erhalten Kunden damit die M\u00f6glichkeit, vor allem zum Einstieg in eine PM-Software den internen IT-Aufwand auf einem Minimum zu halten.<\/p> <p>&#8211; Schnittstellen, Integration: Projektmanagementsoftware ist zunehmend in weitere Unternehmenssoftware eingebunden. Auch wenn Schnittstellen jeweils im Einzelfall konzipiert werden m\u00fcssen, richten immer mehr Anbieter ihre Aufmerksamkeit auf flexible, konfigurierbare Schnittstellen, die ohne Programmierung durch das PMO konfiguriert werden k\u00f6nnen.<\/p> <p>&#8211; Produktmanagement: Komplexere L\u00f6sungen bieten neben dem mittlerweile etablierten Projektportfolio-Management immer h\u00e4ufiger auch Funktionen f\u00fcr das Produktmanagement. Projekte k\u00f6nnen so im Zusammenhang mit dem Produktportfolio betrachtet werden.<\/p> <p>&#8211; IT: Agile Methoden &#8211; Der Trend zu agilen Methoden in der IT &#8211; vor allem zu Scrum &#8211; schl\u00e4gt sich auch in der PM-Software nieder. Ein gutes Viertel der f\u00fchrenden Multi-PM-Softwareprodukte bietet mittlerweile Funktionen, um auch agil gesteuerte Projekte im Projektportfolio im Blick zu behalten.<\/p> <p>F\u00fcr weitere Informationen zu getesteten Anbietern, Testmethode und Bestellm\u00f6glichkeiten besuchen Sie bitte www.barc.de\/pm-software (http:\/\/www.barc.de\/pm-software) oder http:\/\/www.pm-software-report.com<\/p> <p>Das Business Application Research Center (BARC) ist ein Forschungs- und Beratungsinstitut f\u00fcr Unternehmenssoftware mit Fokus auf die Bereiche Business Intelligence, Enterprise Content Management (ECM) und Enterprise Resource Planning. BARC-Mitarbeiter sind seit 1994 in der Evaluation von Business-Intelligence- und ECM-Produkten und Beratung von Unternehmen t\u00e4tig. Dabei vereinen die BARC-Analysten Markt-, Produkt- und Einf\u00fchrungswissen. Know-how-Basis sind die seit Jahren st\u00e4ndig durchgef\u00fchrten Marktanalysen und Produktvergleichsstudien, die ein umfassendes Detailwissen \u00fcber den Leistungsumfang aller marktrelevanten Software-Anbieter und neueste Entwicklungen im Markt sicherstellen. \u00dcber 1200 Kunden j\u00e4hrlich, darunter \u00fcber 90 Prozent der DAX100-Unternehmen sowie Beh\u00f6rden und Finanzinstitute, nutzen das vielf\u00e4ltige Angebot von BARC bei der Softwareauswahl-Unterst\u00fctzung sowie in Beratungs- und IT-Strategie-Projekten.<\/p> <p>Kontakt:<br \/> BARC GmbH<br \/> Axel Bange<br \/> Steinbachtal 2b<br \/> 97082 W\u00fcrzburg<br \/> 0931880651-0<br \/> info@barc.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.barc.de\" title=\"Business Application Research Center\" >http:\/\/www.barc.de<\/a><\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Studie vergleicht Softwarel\u00f6sungen f\u00fcr das Projektmanagement Eine aktuelle BARC-Studie untersucht und bewertet 26 aktuelle Softwarel\u00f6sungen f\u00fcr das Projektmanagement Die 7. Auflage der Studie &#8222;Project Management Software Systems Requirements, Selection Process and Products&#8220; ist ab sofort verf\u00fcgbar. F\u00fcr die neue Auflage wurden 26 f\u00fchrende L\u00f6sungen anhand von \u00fcber 300 Kriterien getestet. 130 dieser Kriterien wurden f\u00fcr<\/p>\n","protected":false},"author":1,"featured_media":33028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[124],"tags":[134],"class_list":["post-32933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-it-internet-computer","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/32933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=32933"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/32933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=32933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=32933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=32933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}