{"id":3314,"date":"2012-11-28T15:34:14","date_gmt":"2012-11-28T14:34:14","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=3314"},"modified":"2026-02-06T12:07:16","modified_gmt":"2026-02-06T11:07:16","slug":"berufsbegleitendes-fernstudium-zum-energieinformatiker","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/berufsbegleitendes-fernstudium-zum-energieinformatiker-103314\/","title":{"rendered":"Berufsbegleitendes Fernstudium zum Energieinformatiker"},"content":{"rendered":"<p>Neuer Bachelorstudiengang an der Wilhelm B\u00fcchner Hochschule<\/p> <p>Die Frage nach der Energieversorgung der Zukunft wird immer h\u00e4ufiger und intensiver diskutiert. Um k\u00fcnftig komplexe Energieversorgungssysteme zu regeln und zu managen, vereint die Energieinformatik die Informatik mit der Energietechnik und -wirtschaft. An der Wilhelm B\u00fcchner Hochschule k\u00f6nnen Interessierte und ausgebildete Fachkr\u00e4fte aus dem IT- oder Energiesektor berufsbegleitend den neuen Bachelor-Studiengang &#8222;Energieinformatik&#8220; belegen und sich als Energieinformatiker qualifizieren. <!--more-->Die Studieninhalte umfassen wissenschaftliche IT-Grundlagen und anwendungsorientiertes Wissen in den Bereichen Informatik und Energietechnik sowie f\u00e4cher\u00fcbergreifende BWL- und Management-Themen. Der 7-semestrige Bachelor-Studiengang wurde von der Akkreditierungsagentur ACQUIN ohne Auflagen akkreditiert. Er kann jederzeit begonnen und vier Wochen kostenlos getestet werden.<\/p> <p>&#8222;Energieinformatiker verf\u00fcgen \u00fcber die notwendigen Kernkompetenzen, die Bereiche Informatik, Energietechnik und -wirtschaft zu vereinen. Aufgrund dieser interdisziplin\u00e4ren Ausrichtung sehen sie aussichtsreichen Karrierechancen entgegen. Die Absolventen unseres Studiengangs sind in der Lage, die technischen und wirtschaftlichen Aspekte heutiger und zuk\u00fcnftiger Energieversorgungssysteme zu verstehen und optimale L\u00f6sungen f\u00fcr die Erzeugung, Speicherung und Verteilung von Energie zu erarbeiten&#8220;, so Prof. Dr. J\u00fcrgen Otten, Dekan des Fachbereiches Informatik der Wilhelm B\u00fcchner Hochschule. &#8222;Die Aufgabenfelder reichen dabei von der Planung, Konzeption und Gestaltung von Energieinformationssystemen und -netzen bis hin zur technischen Realisierung und Qualit\u00e4tssicherung. Energieinformatiker sind sowohl in der klassischen IT-Branche als auch bei Energieversorgern und KMUs aus der Energiebranche sowie in der Forschung gesucht.&#8220;<\/p> <p>Interdisziplin\u00e4re Studieninhalte Das Grundstudium beinhaltet die Themenbl\u00f6cke Mathematik und Technik, Informatik und Energietechnik. Dar\u00fcber hinaus eignen sich die Studierenden \u00fcberfachliche Kompetenzen aus der Betriebswirtschaftslehre sowie wissenschaftliches Arbeiten an. Im ersten Wahlpflichtbereich vertiefen sie entweder ihre Englischkenntnisse oder studieren die Grundlagen der interkulturellen Kompetenz. Im anschlie\u00dfenden Kern- und Vertiefungsstudium wird das Know-how in Informatik und Energietechnik nochmals erweitert. Wahlpflichtbereiche bieten zudem ausreichend Gelegenheit, das Studium nach fachlichen Interessen zu gestalten. So k\u00f6nnen die Studierenden im Bereich der Informatik zwischen der weiterf\u00fchrenden Programmierung, der Digital- und Mikrorechentechnik oder dem Informationsmanagement entscheiden. Im Wahlpflichtbereich der Energietechnik stehen Schwerpunkte wie Energieeffizienz und Nachhaltigkeit, Energiemanagement oder Energiespeichertechnik zur Auswahl. Im Studienbereich Informatikpraxis l\u00f6sen die Studierenden typische Aufgabenstellungen eines Energieinformatikers. Dies geschieht in einem Einf\u00fchrungsprojekt, der berufspraktischen Phase, einer Projektarbeit sowie der abschlie\u00dfenden Bachelorarbeit. Die praxisnahen und zum Teil im Team zu l\u00f6senden Aufgaben f\u00f6rdern vernetztes Denken, Probleml\u00f6sungskompetenz sowie Kommunikations- und Teamf\u00e4higkeit.<\/p> <p>Flexible Studiengestaltung Basis des Fernstudiengangs sind die umfangreichen schriftlichen Studienunterlagen. Erg\u00e4nzt werden diese durch zus\u00e4tzliches Material auf dem Online-Campus &#8222;StudyOnline&#8220;. Die interaktiven Angebote des Online-Campus erm\u00f6glichen eine individuelle und zeitnahe Studienbetreuung durch Tutoren sowie Kontakte zu einem aktiven Netzwerk aus Mitstudierenden und Dozenten. Pr\u00e4senzphasen bieten Gelegenheit f\u00fcr pers\u00f6nliche Begegnungen. In einem Testmonat k\u00f6nnen Interessierte den Studiengang unverbindlich kennen lernen.<\/p> <p>Informationen zum Bachelor-Studiengang, zum berufsbegleitenden Fernstudium und zur Wilhelm B\u00fcchner Hochschule sind unter der Telefonnummer 0800-924 10 00 (geb\u00fchrenfrei) oder per E-Mail \u00fcber info@wb-fernstudium.de erh\u00e4ltlich. Weitere Informationen: www.wb-fernstudium.de<\/p> <p>Druckf\u00e4higes Bildmaterial erhalten Sie unter https:\/\/www.net-files.net\/maisberger\/public\/Wilhelm B\u00fcchner Hochschule Quelle: Cello Armstrong @ fotolia Um die Zusendung eines Belegexemplars wird gebeten.<\/p> <p>Bildrechte: Cello Armstrong @ fotolia<\/p> <p>\u00dcber die Wilhelm B\u00fcchner Hochschule:<\/p> <p>Mit \u00fcber 5 000 Studierenden ist die staatlich anerkannte Wilhelm B\u00fcchner Hochschule die gr\u00f6\u00dfte private Hochschule f\u00fcr Technik in Deutschland. Das Studienangebot der in Pfungstadt bei Darmstadt ans\u00e4ssigen Fernhochschule richtet sich schwerpunktm\u00e4\u00dfig an Berufst\u00e4tige und umfasst Bachelor- und Masterstudieng\u00e4nge in den Fachrichtungen Informatik, Elektro- und Informationstechnik, Mechatronik, Maschinenbau, Wirtschaftsingenieurwesen und Technologiemanagement. Ebenfalls zum Studienprogramm geh\u00f6ren akademische Weiterbildungen sowie Kurzstudieng\u00e4nge. Alle Studieng\u00e4nge zeichnen sich dadurch aus, dass sie nicht nur das n\u00f6tige technische Fachwissen, sondern auch fach\u00fcbergreifende Kompetenzen wie Betriebswirtschaft, F\u00fchrung und Kommunikation vermitteln. Absolventen sind dadurch in der Lage, komplexe Projekte oder ganze Unternehmensbereiche zu f\u00fchren. Mit dem Online-Campus &#8222;StudyOnline&#8220;, pers\u00f6nlicher Studienbetreuung, schnell erreichbaren Tutoren sowie einem aktiven Netzwerk versteht sich die zur Klett-Gruppe geh\u00f6rende Wilhelm B\u00fcchner Hochschule als Service-Hochschule f\u00fcr Berufst\u00e4tige. Zertifizierungen nach ISO 9001, ISO 29990 und PAS 1037 belegen die hohen Qualit\u00e4ts- und Servicestandards der Wilhelm B\u00fcchner Hochschule.<\/p> <p>Weitere Informationen unter: www.wb-fernstudium.de<\/p> <p>Kontakt: Wilhelm B\u00fcchner Hochschule Barbara Debold Ostendstra\u00dfe 3 64319 Pfungstadt bei Darmstadt +49 (0) 6157 806-932 barbara.debold@wb-fernstudium.de http:\/\/www.wb-fernstudium.de<\/p> <p>Pressekontakt: Maisberger GmbH Emma Deil-Frank Claudius-Keller-Stra\u00dfe 3c 81669 M\u00fcnchen +49 (0) 89 419599-53 emma.deil@maisberger.com http:\/\/www.maisberger.com<\/p>","protected":false},"excerpt":{"rendered":"<p>Neuer Bachelorstudiengang an der Wilhelm B\u00fcchner Hochschule Die Frage nach der Energieversorgung der Zukunft wird immer h\u00e4ufiger und intensiver diskutiert. Um k\u00fcnftig komplexe Energieversorgungssysteme zu regeln und zu managen, vereint die Energieinformatik die Informatik mit der Energietechnik und -wirtschaft. An der Wilhelm B\u00fcchner Hochschule k\u00f6nnen Interessierte und ausgebildete Fachkr\u00e4fte aus dem IT- oder Energiesektor berufsbegleitend<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[134],"class_list":["post-3314","post","type-post","status-publish","format-standard","hentry","category-karriere-beruf-bildung","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=3314"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3314\/revisions"}],"predecessor-version":[{"id":270464,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3314\/revisions\/270464"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=3314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=3314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=3314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}