{"id":33814,"date":"2013-06-18T14:33:55","date_gmt":"2013-06-18T14:33:55","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=33814"},"modified":"2013-06-20T15:09:45","modified_gmt":"2013-06-20T14:09:45","slug":"einfach-sein","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/einfach-sein-1033814\/","title":{"rendered":"Einfach SEIN"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Dr.h.c. Bahr\" alt=\"Dr.h.c. Bahr\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/06\/178292-150x150.jpg\" width=\"150\" height=\"150\" \/>Mann oder Maus &#8211; das ist hier die Frage<\/p> <p>Supervisor Claas Bahr aus M\u00fcnster \u00fcber das Mannsein<br \/> Sie sind erfolgreich, smart, liebevoll als Ehemann und Vater sowie zielstrebig als Karrierist &#8211; kein weltfremder Nerd oder Honk? Sie glauben an das, was Sie sehen und daran, dass Ihre Wahrnehmung der Wahrheit entspricht? Sie f\u00fchlen sich als Mann, frei und gleichzeitig sicher verankert in der Welt, Ihrer Identit\u00e4t, Ihrem Selbst? &#8222;Das ist alles Illusion&#8220;, behauptet Claas Bahr. Der Coach und Supervisor l\u00e4dt den Leser auf eine Reise ein. Sie beginnt in der Welt der Introjekte, jene inneren S\u00e4tze, denen jeder Mensch folgt. <!--more-->Im Anschluss erl\u00e4utert der Psychologe die Bedeutung des Y-Chromosoms, das den Unterschied zwischen Mann und Frau ausmacht. Nach einem kleinen Exkurs zum Zweiten Weltkrieg zeigt Claas Bahr die Auswirkungen der 68er-Bewegung f\u00fcr das Mannsein auf. Ebenso haben die 90er-Jahre mit dem aufkeimenden Feminismus und dem Drang nach Geschlechterneutralit\u00e4t ihre Spuren bei den M\u00e4nnern hinterlassen. &#8222;Diese Entwicklungen haben zur Folge, dass wir das evolutionsbiologisch tief in uns verankerte Kr\u00e4ftespiel zwischen Animus (M\u00e4nnlich) und Anima (Weiblich) ignorieren und uns unsere eigene Welt, die nur in unserer Fantasie existiert, schaffen. Wir entwerfen unsere Idee von uns selbst und haben verlernt, einfach zu SEIN,&#8220; betont Claas Bahr. Aber nicht verzagen &#8211; hier ist die Reise noch lange nicht zu Ende: Dem indischen Wissenschaftler und Autor Deepak Chopra zufolge, ist alles sein, weil das gesamte Universum in uns ist. Welche Idee jeder schlussendlich von sich entwirft, liegt an ihm selbst. Interesse geweckt?<\/p> <p>Lesen Sie mehr \u00fcber die Ausf\u00fchrungen von Claas Bahr hier:<\/p> <p>https:\/\/plus.google.com\/117222042749090051491 (https:\/\/plus.google.com\/117222042749090051491)<\/p> <p>http:\/\/www.xing.com\/profile\/Claas_Bahr<\/p> <p>http:\/\/claasbahr.wordpress.com<\/p> <p>Seit \u00fcber 30 Jahren ist Claas Bahr in den Bereichen Psychotherapie\/K\u00f6rpertherapie\/ Coaching und Supervision in eigener Praxis t\u00e4tig. Gleichzeitig war er einer der ersten, die in M\u00fcnster und Umgebung mit der Methode der Gestalttherapie nach Pearls und Bioenergetik nach Lowen arbeitete. 12 Jahre war er in medizinischen Kliniken konsiliarisch t\u00e4tig. So f\u00fchrte er u.a. die Methode der Bioenergetik auch zur psychisch medizinischen Behandlung in den Kliniken ein. Seit 1998 arbeitet er selbst\u00e4ndig im Zentrum f\u00fcr Pers\u00f6nlichkeitsentwicklung in M\u00fcnster. Das Zentrum hat sich der Methode der humanistischen Psychologie und des ganzheitlichen Ansatzes verpflichtet. Dieser Ansatz hat sich sowohl in Einzel- als auch in Firmencoachings bew\u00e4hrt. WIE ICH SEIN MUSS wird ersetzt durch: Wie will ich werden, wie will ich sein? Dar\u00fcber hinaus zeichnet sich das Zentrum durch sehr effektive und au\u00dferordentliche Interventionen aus. So z.B. durch Weltreisen mit eigenen Wohnmobilien durch unterentwickelte Staaten wie Laos, Kambodscha, Vietnam, Tibet etc. Die Enge der Wohnmobile und das Eintauchen in vorwissenschaftliche Kulturen entwickeln bei den Teilnehmern z.B. sehr vielf\u00e4ltiges Verhalten.<\/p> <p>Kontakt:<br \/> Zentrum f\u00fcr Pers\u00f6nlichkeitsentwicklung<br \/> Claas Bahr<br \/> Warendorfer Str. 511<br \/> 48157 M\u00fcnster<br \/> +49 251 26500-0<br \/> kontakt@persoenlichkeitsentwicklung-muenster.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.persoenlichkeitsentwicklung-muenster.de\" title=\"Zentrum f\u00fcr Pers\u00f6nlichkeitsentwicklung\" >http:\/\/www.persoenlichkeitsentwicklung-muenster.de<\/a><\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Mann oder Maus &#8211; das ist hier die Frage Supervisor Claas Bahr aus M\u00fcnster \u00fcber das Mannsein Sie sind erfolgreich, smart, liebevoll als Ehemann und Vater sowie zielstrebig als Karrierist &#8211; kein weltfremder Nerd oder Honk? Sie glauben an das, was Sie sehen und daran, dass Ihre Wahrnehmung der Wahrheit entspricht? Sie f\u00fchlen sich als<\/p>\n","protected":false},"author":1,"featured_media":153093,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[122],"tags":[134],"class_list":["post-33814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frauen-maenner-senioren","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/33814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=33814"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/33814\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153093"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=33814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=33814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=33814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}