{"id":3431,"date":"2012-12-10T17:22:30","date_gmt":"2012-12-10T16:22:30","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=3431"},"modified":"2015-06-15T21:06:20","modified_gmt":"2015-06-15T20:06:20","slug":"nicht-ohne-meine-winterreifen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/nicht-ohne-meine-winterreifen-103431\/","title":{"rendered":"Nicht ohne meine Winterreifen"},"content":{"rendered":"<p>Fehlende Winterreifen k\u00f6nnen in der Kfz-Versicherung eine Rolle spielen<\/p> <p>Auch wenn es in Deutschland keine verbindliche Winterreifenpflicht gibt, sollten Autofahrer in der kalten Jahreszeit ihre Bereifung nicht au\u00dfer Acht lassen. Denn die Stra\u00dfenverkehrsordnung (\u00a72 Absatz 3a der STVO) fordert von Verkehrsteilnehmern, dass &#8222;die Ausr\u00fcstung an die Wetterverh\u00e4ltnisse anzupassen&#8220; ist. Was man sich unter dieser freien Formulierung vorzustellen hat, hat der Gesetzgeber mittlerweile konkretisiert: Wer bei Glatteis, Schneegl\u00e4tte, Schneematsch, Eis- oder Reifgl\u00e4tte mit dem Auto unterwegs ist, muss Winterreifen aufgezogen haben.<\/p> <p><!--more-->Was einen Reifen zum Winterreifen macht? Autofahrer brauchen beim Kauf keine technischen Details kennen, es gen\u00fcgt auf die Bezeichnung M+S oder ein Alpine-Symbol (Bergpiktogramm mit Schneeflocke) zu achten. Zugelassen sind auch sogenannte Allwetter- oder Ganzjahresreifen.<\/p> <p>Wer die Regel missachtet, riskiert nicht nur Punkte und ein Bu\u00dfgeld in Flensburg. Kommt es zum Unfall, kann, so die HUK-COBURG, mangelhafte Bereifung auch zu Konsequenzen beim Versicherungsschutz f\u00fchren. Das gilt besonders dann, wenn sich der Unfall nach mehreren Wochen mit Eis und Schnee ereignet. Nat\u00fcrlich reguliert die Kfz-Haftpflichtversicherung eines Unfallverursachers immer den Schaden des Opfers. Allerdings kann sie den eigenen Versicherungsnehmer, der ohne Winterreifen unterwegs war, im Nachgang mit bis zu 5.000 Euro in Regress nehmen.<\/p> <p>Auch beim Unfallopfer kann das Thema unangemessene Bereifung durchaus zum Problem werden, wenn sich nachweisen l\u00e4sst, dass die fehlende Winterausr\u00fcstung urs\u00e4chlich f\u00fcr den Unfall war, weil sich zum Beispiel der Bremsweg drastisch verl\u00e4ngert hat. In diesem Fall muss das Unfallopfer mit einer Mithaftung rechnen. Die Kfz-Haftpflichtversicherung des Unfallgegners ersetzt den Schaden nicht mehr komplett, sondern nur bis zu einem bestimmten Prozentsatz. Besonders prek\u00e4r kann sich das bei Personensch\u00e4den auswirken, wenn es um Schmerzensgeld, Verdienstausfall oder Rentenzahlungen geht. Aber auch Kasko-Versicherten, die sich ins Auto setzen, ohne Winterreifen losfahren und ihr eigenes Fahrzeug besch\u00e4digen, kann eine Mithaftung drohen. Zudem spielt die Frage der Mithaftung nicht allein f\u00fcr die Versicherung eine Rolle, sie kann auch strafrechtlich wichtig werden.<\/p> <p>HUK-COBURG Versicherungsgruppe Mit rund zehn Millionen Kunden versteht sich die HUK-COBURG Versicherungsgruppe als der gro\u00dfe Versicherer f\u00fcr den privaten Haushalt. Die Beitragseinnahmen summierten sich 2011 auf 5,3 Mrd. Euro. Traditioneller Schwerpunkt des Gesch\u00e4fts ist die Kfz-Versicherung, auf die knapp die H\u00e4lfte der Beitragseinnahmen entfallen. Mit rund neun Millionen versicherten Kraftfahrzeugen ist die Unternehmensgruppe der gr\u00f6\u00dfte deutsche Autoversicherer; in der privaten Haftpflicht- sowie in der Hausratversicherung hat sie jeweils Platz zwei inne. Besondere Bedeutung haben f\u00fcr die HUK-COBURG Versicherungsgruppe traditionell die Angeh\u00f6rigen des \u00f6ffentlichen Dienstes. Vier Millionen ihrer Kunden z\u00e4hlen zu ihm; damit ist die HUK-COBURG Versicherungsgruppe auch der gr\u00f6\u00dfte deutsche Beamtenversicherer.<\/p> <p>Kontakt: HUK-COBURG Pressestelle Karin Benning Postfach 18 02 96444 Coburg 09561-96-2084 karin.benning@huk-coburg.de http:\/\/presse@huk-coburg.de<\/p> <p>Pressekontakt: HUK-COBURG Benning Karin Bahnhofsplatz 96444 Coburg 0 95 61\/ 96 20 84 karin.benning@huk-coburg.de <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.huk.de\" title=\"HUK-COBURG \u2013 einer der gr\u00f6\u00dften Autoversicherer Deutschlands\" >http:\/\/www.huk.de<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Fehlende Winterreifen k\u00f6nnen in der Kfz-Versicherung eine Rolle spielen Auch wenn es in Deutschland keine verbindliche Winterreifenpflicht gibt, sollten Autofahrer in der kalten Jahreszeit ihre Bereifung nicht au\u00dfer Acht lassen. Denn die Stra\u00dfenverkehrsordnung (\u00a72 Absatz 3a der STVO) fordert von Verkehrsteilnehmern, dass &#8222;die Ausr\u00fcstung an die Wetterverh\u00e4ltnisse anzupassen&#8220; ist. Was man sich unter dieser freien<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[134],"class_list":["post-3431","post","type-post","status-publish","format-standard","hentry","category-auto-motorrad-motorgeraete","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=3431"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/3431\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=3431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=3431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=3431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}