{"id":35393,"date":"2013-06-28T08:09:20","date_gmt":"2013-06-28T08:09:20","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=35393"},"modified":"2017-06-23T11:55:25","modified_gmt":"2017-06-23T10:55:25","slug":"auf-gesunde-und-natuerliche-weise-zur-bikini-figur","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/auf-gesunde-und-natuerliche-weise-zur-bikini-figur-1035393\/","title":{"rendered":"Auf gesunde und nat\u00fcrliche Weise zur Bikini-Figur"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Brosch\u00fcre &quot;Gesund und nat\u00fcrlich zum Wohlf\u00fchlgewicht&quot;\" alt=\"Brosch\u00fcre &quot;Gesund und nat\u00fcrlich zum Wohlf\u00fchlgewicht&quot;\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/06\/179977-150x150.jpg\" width=\"130\" height=\"130\" \/>Wohlf\u00fchlgewicht f\u00fcr den Sommer &#8211; Alltagstaugliche Tipps<\/p> <p>Kostenlose Fachbrosch\u00fcre von erfahrenem \u00c4rzte-Team mit Tipps zum gesunden und nachhaltigen Abnehmen<br \/> Leckere Grillw\u00fcrstel, erfrischende Eiscreme und prickelnde Sommergetr\u00e4nke z\u00e4hlen zu den kulinarischen Verlockungen des Sommers. Dabei ist es nicht immer leicht, \u00fcberfl\u00fcssige Pfunde abzuspecken und das erreichte Wohlf\u00fchlgewicht auch zu halten. Das \u00c4rzteteam Dr. med. Hannelore Kleditzsch und Prof. Dr. med. J\u00fcrgen Kleditzsch aus Bad W\u00f6rishofen begleitet seit \u00fcber 30 Jahren Menschen erfolgreich bei der nachhaltigen Gewichtsreduzierung und gibt erprobte Tipps zum gesunden Abnehmen. <!--more-->Diese sind in der zwanzigseitigen Brosch\u00fcre &#8222;Gesund und nat\u00fcrlich zum Wohlf\u00fchlgewicht&#8220; zusammengestellt (kostenfrei auf www.baerbel-drexel.de (http:\/\/shop.baerbel-drexel.com\/broschure-gesund-und-naturlich-zum-wohlfuhlgewicht.html) oder telefonisch unter 0180-500 60 10 bestellbar).<\/p> <p>Wer den Sommer unbeschwert und leicht genie\u00dfen m\u00f6chte und trotz Ausfl\u00fcge in den Biergarten und in die Eisdiele sein Wohlf\u00fchlgewicht erreichen m\u00f6chte, der sollte nicht nur die bisher gewohnte Nahrungsmenge reduzieren. Wichtiger ist es, die eigene Ern\u00e4hrung sinnvoll und ausgewogen zusammenzustellen:<\/p> <p>&#8211; Auf die richtigen Kohlenhydrate und Ballaststoffe kommt es an &#8211; sie liefern dem K\u00f6rper pure Energie. Vorzuziehen sind langsamer verdauliche Kohlenhydrate mit einem hohen Ballaststoffanteil wie zum Beispiel Kartoffeln, Naturreis und Vollkornprodukte aus Roggen, Dinkel, Hafer, Amaranth sowie Nudeln aus Hartweizen. Gerade in den Sommermonaten ist das Angebot an wasserreichem Gem\u00fcse wie Gurken, Tomaten, Pilze, Spargel, Zucchini und Spinat gro\u00df. Diese Gem\u00fcsesorten sollten auf keinem Di\u00e4tplan fehlen und k\u00f6nnen jederzeit ohne schlechtes Gewissen genossen werden.<\/p> <p>&#8211; Eine wichtige Rolle spielt der Kalorienbedarf. Wer abnehmen will, sollte \u00fcber einen bestimmten Zeitraum, zum Beispiel \u00fcber vier bis zehn Wochen, t\u00e4glich nicht mehr als 1000 &#8211; 1500 Kalorien zu sich nehmen. Vielen Menschen f\u00e4llt das an hei\u00dfen Tagen leichter als sonst, weil sie bei hohen Temperaturen weniger Hunger haben.<\/p> <p>&#8211; Das t\u00e4glich verzehrte Nahrungsfett liefert wichtige Energie. Dabei sollte jedoch auf die Qualit\u00e4t und Zusammensetzung der Fette geachtet werden. Ein Drittel der Fette sollte aus ges\u00e4ttigten, ein Drittel aus einfach unges\u00e4ttigten und ein Drittel aus mehrfach unges\u00e4ttigten Fetts\u00e4uren bestehen.<\/p> <p>&#8211; Proteine, wie Eiwei\u00df auch genannt wird, sind die Bausteine des Lebens. Wichtige Nahrungsquellen hierf\u00fcr sind Eier, Milchprodukte, Fleisch, H\u00fclsenfr\u00fcchte, Soja und Algen. Gerade w\u00e4hrend einer verminderten Kalorienaufnahme ist die erh\u00f6hte Zufuhr von biologisch hochwertigem Eiwei\u00df besonders wichtig. Der Bellaform Sojaeiwei\u00dfdrink (http:\/\/shop.baerbel-drexel.com\/bellaform-sojaeiweissdrink-450-g.html) von B\u00e4rbel Drexel beispielsweise ist so zusammengesetzt, dass er mit seiner Zusammensetzung optimal unterst\u00fctzen kann.<\/p> <p>&#8211; Das Abnehmen steht in sehr engem Zusammenhang mit einer ausreichenden Trinkmenge. Die Trinkformel, mit der die individuelle Fl\u00fcssigkeitszufuhr berechnet werden kann, lautet: K\u00f6rpergewicht in kg x 40 ml = Fl\u00fcssigkeitsbedarf\/Tag. An hei\u00dfen Sommertagen sollten es mindestens zwei bis drei Liter t\u00e4glich sein. So wird Fl\u00fcssigkeitsverlust durch Schwitzen ausgeglichen.<\/p> <p>&#8211; Auf dem Weg zum Wohlf\u00fchlgewicht ist die Umstellung der Ern\u00e4hrung nur die halbe Miete. Der volle Erfolg ergibt sich aus der Kombination mit einem entsprechenden Bewegungsprogramm. Die Bewegung soll ein wichtiges Element des Alltags werden, ohne zu \u00fcberfordern. Gerade im Sommer gibt es vielf\u00e4ltige M\u00f6glichkeiten im Freien wie Schwimmen, Radfahren und Inlineskating. In der Brosch\u00fcre sind jederzeit und einfach umsetzbare Bewegungstipps enthalten.<\/p> <p>Die Zeit danach: Das neue Gewicht sicher halten<\/p> <p>Wer einige Kilo abgespeckt hat, m\u00f6chte das neue Wohlf\u00fchlgewicht im Alltag und \u00fcber den Sommer hinaus sicher halten. Hier gibt die Brosch\u00fcre praxistaugliche Empfehlungen. Unter anderem sollte folgendes beachtet werden:<\/p> <p>&#8211; Wer auf gesunde Weise abgenommen hat, ist mit einer ausgewogenen Ern\u00e4hrung bereits vertraut. Diese spielt auch weiterhin eine wichtige Rolle und sollte unbedingt beibehalten werden.<\/p> <p>&#8211; Es sollte darauf geachtet werden, weiterhin mehrere kleinere Mahlzeiten einzunehmen und &#8222;Hungerl\u00f6cher&#8220; zu vermeiden. Dabei kann der Bellaform Sojaeiwei\u00dfdrink (http:\/\/shop.baerbel-drexel.com\/bellaform-sojaeiweissdrink-450-g.html) von B\u00e4rbel Drexel ein wertvoller Dauerbegleiter werden. Hochwertiges Sojaeiwei\u00df und enthaltener Safranextrakt sorgen f\u00fcr ein angenehmes S\u00e4ttigungsgef\u00fchl. Au\u00dferdem f\u00f6rdert das Sojaeiwei\u00dfpulver den Energiestoffwechsel und wirkt insbesondere durch die hohe biologische Wertigkeit der Proteine einem Jo-Jo-Effekt entgegen.<\/p> <p>-Bewegung sollte auch weiterhin als festes Element in den Tagesablauf und den Wochenplan eingebaut werden, denn damit werden Muskeln aufgebaut und der Kalorienverbrauch erh\u00f6ht.<\/p> <p>Kostenlose Brosch\u00fcre mit wertvollen Abnehmtipps<\/p> <p>Die B\u00e4rbel Drexel GmbH, ein Pionier f\u00fcr Naturprodukte rund um Gesundheit und Sch\u00f6nheit, hat in Zusammenarbeit mit dem \u00c4rzteteam Dr. med. Hannelore Kleditzsch und Prof. Dr. med. J\u00fcrgen Kleditzsch eine Brosch\u00fcre zum Thema Abnehmen herausgegeben. Die Leser erfahren, was vor dem Beginn einer Gewichtsreduktion zu beachten ist, wie man gesund, nat\u00fcrlich und mit Leichtigkeit zu seiner pers\u00f6nlichen Wunschfigur kommt und wie man diese auch auf Dauer beibehalten kann. Die Brosch\u00fcre kann kostenfrei auf www.baerbel-drexel.de (http:\/\/shop.baerbel-drexel.com\/broschure-gesund-und-naturlich-zum-wohlfuhlgewicht.html) abgerufen werden oder telefonisch unter 0180-500 60 10 angefordert werden.<\/p> <p>Die B\u00e4rbel Drexel GmbH mit Sitz in Baar (Bayern) gilt als Pionier f\u00fcr hochwertige Naturkosmetik und naturreine Nahrungserg\u00e4nzungsmittel in Deutschland. Nach der Gr\u00fcndung durch die Heilpraktikerin B\u00e4rbel Drexel im Jahr 1996 etablierte sich das Unternehmen mit der Verpflichtung auf h\u00f6chste Qualit\u00e4tsstandards, Transparenz und reine Naturprodukte schnell im Markt. Heute besch\u00e4ftigt B\u00e4rbel Drexel 170 Mitarbeiter. S\u00e4mtliche Produkte stammen aus eigener professioneller Forschung und Entwicklung sowie aus nachhaltiger Produktion am Firmensitz des Unternehmens.<\/p> <p>Kontakt<br \/> B\u00e4rbel Drexel GmbH<br \/> Dietmar Vogler (Gesch\u00e4ftsf\u00fchrer)<br \/> Aichacher Stra\u00dfe 7<br \/> 86674 Baar (Schwaben)<br \/> +49 (0) 8276\/518-0<br \/> service@baerbel-drexel.de<br \/> http:\/\/www.baerbel-drexel.de<\/p> <p>Pressekontakt:<br \/> Glogauer &amp; Company Communications<br \/> Tatjana Nuding<br \/> Hauptplatz 8<br \/> 86899 Landsberg am Lech<br \/> +49 (0) 8806-95 88 64 -0<br \/> t.nuding@glogauer.de<br \/> http:\/\/www.glogauer.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Wohlf\u00fchlgewicht f\u00fcr den Sommer &#8211; Alltagstaugliche Tipps Kostenlose Fachbrosch\u00fcre von erfahrenem \u00c4rzte-Team mit Tipps zum gesunden und nachhaltigen Abnehmen Leckere Grillw\u00fcrstel, erfrischende Eiscreme und prickelnde Sommergetr\u00e4nke z\u00e4hlen zu den kulinarischen Verlockungen des Sommers. Dabei ist es nicht immer leicht, \u00fcberfl\u00fcssige Pfunde abzuspecken und das erreichte Wohlf\u00fchlgewicht auch zu halten. Das \u00c4rzteteam Dr. med. Hannelore Kleditzsch<\/p>\n","protected":false},"author":1,"featured_media":153045,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[134],"class_list":["post-35393","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernaehrung-wellness-gesundheit","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/35393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=35393"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/35393\/revisions"}],"predecessor-version":[{"id":264347,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/35393\/revisions\/264347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153045"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=35393"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=35393"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=35393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}