{"id":36787,"date":"2013-07-09T08:45:38","date_gmt":"2013-07-09T08:45:38","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=36787"},"modified":"2020-03-27T12:51:50","modified_gmt":"2020-03-27T11:51:50","slug":"wertbasierter-lebens-und-konsumstil","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wertbasierter-lebens-und-konsumstil-1036787\/","title":{"rendered":"Wertbasierter Lebens- und Konsumstil"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"LOHAS ist die Abk\u00fcrzung f\u00fcr \u201eLifestyles Of Health And Sustainability\u201c, und steht f\u00fcr gesunde und nachhaltige Lebensweisen.\" alt=\"LOHAS ist die Abk\u00fcrzung f\u00fcr \u201eLifestyles Of Health And Sustainability\u201c, und steht f\u00fcr gesunde und nachhaltige Lebensweisen.\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/07\/181481-150x150.jpg\" width=\"150\" height=\"150\" \/>LOHAS Lifestyle Magazin<\/p> <p>Lebensstile auf Basis von Gesundheit und Nachhaltigkeit<br \/> LOHAS Magazin &#8211; erneuertes LOHAS-Portal f\u00fcr nachhaltige Lebens- und Wirtschaftsweise<\/p> <p>Die Nachhaltigkeitsplattform LOHAS.de war schon im Gr\u00fcndungsjahr 2005 wegweisender Impulsgeber f\u00fcr viele weitere Aktivit\u00e4ten nachhaltiger Lebensweise und weckte Begehrlichkeiten in den M\u00e4rkten zwischen Wirtschaft und Konsum. Die Wirkungsweise der Inhalte gr\u00fcndet auf weltweite Recherchen und Berichterstattung \u00fcber alternative Entwicklungen aus vielen Themenfeldern wie zum Beispiel Elektromobilit\u00e4t, Gesunde Ern\u00e4hrung, nachhaltige Produkte, Soziales Wirtschaften, Solarenergie, Gr\u00fcne Technologien, Gr\u00fcnes Bauen und Wohnen ect. <!--more-->Die Philosophie ist nach wie vor mit mit folgenden Werten verzahnt: Glaubw\u00fcrdigkeit, Transparenz, Zukunftsf\u00e4higkeit.<\/p> <p>LOHAS steht f\u00fcr Individuen, Unternehmen und ihre Stakeholder, die ein neues Verhalten praktizieren mit dem Ziel, die Lebensqualit\u00e4t f\u00fcr alle zu erhalten und Unternehmen zukunftstauglich zu machen.<\/p> <p>LOHAS ist die Abk\u00fcrzung f\u00fcr \u201eLifestyles Of Health And Sustainability\u201c, und steht f\u00fcr gesunde und nachhaltige Lebensweisen. Der Begriff tauchte zum ersten Mal in den Schlussfolgerungen einer Studie auf, welche vom US Marktforschungsinstitut \u201eConscious Media\u201c durchgef\u00fchrt wurde.<\/p> <p>Lohas-Bewusste orientieren sich an Gesundheit und Nachhaltigkeit und engagieren sich f\u00fcr eine intakte Natur und gerechte Gesellschaft. Beides wandelt sich zurzeit in noch nie dagewesenem Tempo. Der Fortbestand der Menschheit basiert auf innerer Stabilit\u00e4t und \u00e4usserem Gleichgewicht, die mittels Anpassung und Kooperation aufrecht erhalten werden.<\/p> <p>LOHAS leben einen wertbasierten Lebens- und Konsumstil, f\u00fcr sie gibt es neben Preis und Qualit\u00e4t eine neue Dimension der Markenorientierung: Ethik. Ihr Credo ist eine balancierte Lebensweise im Glauben an die Machbarkeit einer besseren Welt, die nicht durch Verzicht, sondern durch bessere Ideen, intelligente Technologien und aktivem Gemeinsinn erreicht wird.<\/p> <p>LOHAS ist in kurzer Zeit Mainstream geworden, denn immer mehr Menschen achten auf Kriterien wie Umweltvertr\u00e4glichkeit, soziale Verantwortung nach innen und aussen, Regionalit\u00e4t, Erhaltung der Biodiversit\u00e4t und der nat\u00fcrlichen Ressourcen. Das zwingt Unternehmen zur Anpassung sowohl ihrer Produkte und Dienstleistungen, ihrer Wertsch\u00f6pfungskette wie auch ihres Verhaltens im Markt und in der Gesellschaft.<\/p> <p>Eine kritische Betrachtung mit wohlwollender Begleitung vieler Initiativen und Entwicklungen sind die Grundlage, wie z.B. eine Momentaufnahme der Werbeindustrie mit beispielhaften Fakten in diesem Artikel: Werbeindustrie &#8211; Trust me I am Lying. Hier handelt es sich um Strategien, Einblicke + Trends der Agenturen. Nachhaltigkeit, Kommunikation, visuelle Bildsprache f\u00fcr Kampagnen sind inzwischen eigenst\u00e4ndige Themenbereiche in den PR- und Werbeagenturen auf der ganzen Welt.<\/p> <p>Als Informationsdrehscheibe und Schnittstelle f\u00fcr Wirtschaft, Medien und gesellschaftlichen Akteuren sind wir u.a. t\u00e4tig als Impulsgeber bei &#8222;nachhaltigen Projekten&#8220; mit international recherchierten Themen und als ThinkTank nachhaltiger Lebensweise mit Schwerpunkten auf Kommunikation, Beratung und Bewusstseinsentwicklung. Hierzu vermitteln wir Inhalte, Kontakte und Themen, sowie Beratung an Wirtschaftsvertreter, Medien und Netzwerke.<\/p> <p>Kontakt:<br \/> LOHAS Lifestyle<br \/> Peter Parwan<br \/> Wei\u00dfenburgerstr. 44<br \/> 81667 M\u00fcnchen<br \/> 089-41250093<br \/> parwan@lohas.de<br \/> www.LOHAS.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>LOHAS Lifestyle Magazin Lebensstile auf Basis von Gesundheit und Nachhaltigkeit LOHAS Magazin &#8211; erneuertes LOHAS-Portal f\u00fcr nachhaltige Lebens- und Wirtschaftsweise Die Nachhaltigkeitsplattform LOHAS.de war schon im Gr\u00fcndungsjahr 2005 wegweisender Impulsgeber f\u00fcr viele weitere Aktivit\u00e4ten nachhaltiger Lebensweise und weckte Begehrlichkeiten in den M\u00e4rkten zwischen Wirtschaft und Konsum. Die Wirkungsweise der Inhalte gr\u00fcndet auf weltweite Recherchen und<\/p>\n","protected":false},"author":1,"featured_media":153057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[116],"tags":[134],"class_list":["post-36787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-design-lifestyle","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/36787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=36787"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/36787\/revisions"}],"predecessor-version":[{"id":266602,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/36787\/revisions\/266602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153057"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=36787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=36787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=36787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}