{"id":40160,"date":"2013-08-02T08:00:46","date_gmt":"2013-08-02T08:00:46","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=40160"},"modified":"2016-12-23T12:36:13","modified_gmt":"2016-12-23T11:36:13","slug":"drei-jahre-danach","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/drei-jahre-danach-1040160\/","title":{"rendered":"Drei Jahre danach"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Die Befragung fokussierte sich auf drei Kernbereiche:\" alt=\"Die Befragung fokussierte sich auf drei Kernbereiche:\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/08\/185053-150x150.jpg\" width=\"135\" height=\"135\" \/>Master-Programme zahlen sich aus<\/p> <p>Nachgefragt: Was machen SIBE-Studierende nach Abschluss des Studiums?!<br \/> Mit aktuell knapp 2.500 Alumni im In- und Ausland verf\u00fcgt die SIBE \u00fcber ein betr\u00e4chtliches und erfolgreiches Netzwerk. Was machen unsere Absolventen\/-innen eigentlich heute? Diese Frage stand am Anfang unserer Verbleib-Studie, an der knapp 400 SIBE-Alumni teilnahmen &#8211; mittels Online-Befragung und mind. 3 Jahre nach ihrem Master-Abschluss. Der Gro\u00dfteil der Befragten verf\u00fcgte vor dem Master-Studium \u00fcber keine bis geringe Berufserfahrung.<\/p> <p><!--more-->Die Ergebnisse der Studie k\u00f6nnen sich sehen lassen: Mit einem Durchschnittsalter von 34 Jahren arbeiten 61 Prozent der Ehemaligen in einer Leitungsfunktion, davon 26 Prozent in einer hohen F\u00fchrungsposition. \u00dcber die H\u00e4lfte der Befragten verf\u00fcgt derzeit \u00fcber ein Bruttojahreseinkommen von 70.000 Euro oder mehr und ist in einem Gro\u00dfunternehmen t\u00e4tig. Einige herausragende Karrieren zeigen unsere Alumni heute im Vorstand oder der Gesch\u00e4ftsf\u00fchrung von bekannten Unternehmen wie der Bertrandt AG, der SAP AG oder der Flint Group Germany GmbH. Auch die Zahl der Firmen-Gr\u00fcnder ist mit 12 Prozent \u00fcberdurchschnittlich hoch. Als Beispiele dienen die mehrfach ausgezeichneten Unternehmen CureVac GmbH, EIGHT GmbH Co. KG oder GILDEMEISTER energy efficiency GmbH.<\/p> <p>Aktuell arbeiten unsere Alumni vor allem in den Sektoren Automobil, Beratung, Informationstechnologie sowie Energiewirtschaft. In der Zusammenfassung l\u00e4sst sich sagen: F\u00fcr 40 Prozent der Befragten f\u00f6rderte das SIBE-Studium ihre Karriere au\u00dferordentlich oder in hohem Ma\u00dfe, nur 4 Prozent der Absolventen sehen keinen klaren Mehrwert f\u00fcr sich. Die gro\u00dfe Mehrheit bewertete das berufsintegrierte Studien-Modell der SIBE als (sehr) gut und empfehlenswert. Besonders positiv schneiden die Themen Entwicklung von Management-Kompetenzen, Transfer-Kompetenz sowie die Kombination aus Berufseinstieg und Studium ab, was an folgenden Zitaten deutlich wird: &#8222;Es gab bisher so gut wie keinen Tag, an dem ich nicht vom Studium profitiert habe!&#8220;, &#8222;Das Studium als Verkn\u00fcpfung Titel plus Chance im Unternehmen hat die Karriere au\u00dferordentlich gef\u00f6rdert.&#8220; oder auch das &#8222;Studium entwickelt den Studenten umfassend, sowohl Fachkenntnis als auch Pers\u00f6nlichkeit und bietet die M\u00f6glichkeit Inhalte selbst zu bestimmen.&#8220;<\/p> <p>Wir sind stolz auf unsere Alumni und m\u00f6chten den Austausch st\u00e4rken. Die Xing-Community SIBE Alumni, eine Plattform f\u00fcr Absolventen wie Studierende, wurde k\u00fcrzlich zur aktivsten Hochschulgruppe Deutschlands gek\u00fcrt. Networking steht auch beim Mentoring@SIBE-Programm an oberster Stelle: Engagierte Absolventen unterst\u00fctzen Studierende im ersten Jahr mit Tipps rund um Beruf und Karriere. Zahlreiche Events wie regionale Stammtische, Jahrgangstreffen, Sport-Turniere oder Vortragsreihen erm\u00f6glichen zudem den regelm\u00e4\u00dfigen pers\u00f6nlichen Austausch.<\/p> <p>Eine umfangreichere Auswertung der Befragung finden Sie hier (http:\/\/www.steinbeis-sibe.de\/fileadmin\/pdf\/Dokumentenlinks\/130614_Verbleibstudie_-_Ergebnisse_gross.pdf) .<\/p> <p>Sie haben weitere Ideen oder m\u00f6chten selbst aktiver ins Networking einsteigen? F\u00fcr Fragen steht Ihnen Frau Aliona Nazmieva, nazmieva@steinbeis-sibe.de, 0 70 32 &#8211; 94 58 &#8211; 72, zur Verf\u00fcgung. Mehr Informationen erhalten Sie auch hier (http:\/\/www.steinbeis-sibe.de\/index.php?id=634) .<\/p> <p>Die SCHOOL OF INTERNATIONAL BUSINESS AND ENTREPRENEURSHIP (SIBE) ist die internationale Business School der Steinbeis-Hochschule Berlin (SHB) mit Sitz in Herrenberg und Berlin &#8211; geleitet wird die Hochschule von Prof. Dr. Werner G. Faix, der die SIBE gegr\u00fcndet hat.<br \/> Die SIBE steht f\u00fcr erfolgreichen Wissens-Transfer und systematischen Kompetenz-Aufbau zwischen Wissenschaft und Wirtschaft. Sie ist fokussiert auf Unternehmen, Organisationen und \u00f6ffentliche Verwaltungen und auf kompetente, unternehmerisch global denkende und handelnde High Potentials. Wir sorgen mit unseren Innovations-Projekten und unseren High Potentials bei unseren Partner-Unternehmen f\u00fcr Wachstum und Globalisierung &#8211; und f\u00fcr kompetente F\u00fchrungs- und Nachwuchsf\u00fchrungskr\u00e4fte.<\/p> <p>Mit MBA- und Masterprogrammen (M.A. und M.Sc. im Double-Degree) seit 1994, mit derzeit \u00fcber 1.074 Studierenden, mehr als 2.262 erfolgreichen Absolventen und mit \u00fcber 350 Partner-Unternehmen ist die SIBE kompetenter Partner f\u00fcr Wachstum, Globalisierung und Weiterqualifizierung.<\/p> <p>Kontakt<br \/> School of International Business and Entrepreneurship (SIBE)<br \/> Sandra Flint<br \/> G\u00fcrtelstra\u00dfe 29a\/30<br \/> 10247 Berlin<br \/> 0176 &#8211; 1945 8015<br \/> flint@steinbeis-sibe.de<br \/> http:\/\/www.steinbeis-sibe.de<\/p> <p>Pressekontakt:<br \/> SIBE GmbH<br \/> Sandra Flint<br \/> G\u00fcrtelstr. 29a\/30<br \/> 10247 Berlin<br \/> 030\/49782220<br \/> flint@steinbeis-sibe.de<br \/> http:\/\/www.steinbeis-sibe.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Master-Programme zahlen sich aus Nachgefragt: Was machen SIBE-Studierende nach Abschluss des Studiums?! Mit aktuell knapp 2.500 Alumni im In- und Ausland verf\u00fcgt die SIBE \u00fcber ein betr\u00e4chtliches und erfolgreiches Netzwerk. Was machen unsere Absolventen\/-innen eigentlich heute? Diese Frage stand am Anfang unserer Verbleib-Studie, an der knapp 400 SIBE-Alumni teilnahmen &#8211; mittels Online-Befragung und mind. 3<\/p>\n","protected":false},"author":1,"featured_media":153151,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[134],"class_list":["post-40160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-karriere-beruf-bildung","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/40160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=40160"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/40160\/revisions"}],"predecessor-version":[{"id":263842,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/40160\/revisions\/263842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153151"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=40160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=40160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=40160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}