{"id":40775,"date":"2013-08-07T16:48:08","date_gmt":"2013-08-07T16:48:08","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=40775"},"modified":"2019-02-19T11:05:48","modified_gmt":"2019-02-19T10:05:48","slug":"internationale-grundsteine","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/internationale-grundsteine-1040775\/","title":{"rendered":"Internationale Grundsteine"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Das internationale Studium birgt viele Potentiale\" alt=\"Das internationale Studium birgt viele Potentiale\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/08\/185684-150x150.jpg\" width=\"126\" height=\"126\" \/>Hinaus in die weite BWL-Welt<\/p> <p>Wirtschaft wirklich international studieren<br \/> Die International Business School Budapest (IBS) bietet acht Bachelor- und vier Masterstudieng\u00e4nge in englischer Sprache an. Alle Programme sind durch fest integrierte Auslandsaufenthalte stark international ausgerichtet. Besonderer Wert wird auch auf die Perfektionierung des Englischen als Arbeitssprache gelegt. Anfang 2013 er\u00f6ffnete die IBS zudem einen neuen Campus in Wien. www.wirtschaftsstudium-in-budapest.de<\/p> <p><!--more-->Internationales Bachelor-Studium<br \/> Das Bachelor-Studium an der IBS dauert sechs Semester. Grunds\u00e4tzlich beginnen die Studenten mit einem einf\u00fchrenden ersten Jahr, in dem die Grundlagen der Wirtschaftswissenschaften behandelt werden. Erst dann setzt man den Fokus beispielsweise auf &#8222;Kunst- und Kulturmanagement&#8220; (Arts Management) oder auf &#8222;Wirtschaft und Diplomatie&#8220; (Business and Diplomacy).<br \/> Das Studium an der IBS ist, wie an Business Schools \u00fcblich, vor allem praxisnah. Es beinhaltet viele Tutorien sowie anwendungsorientierte Gruppen- und Projektarbeit. In den letzten zwei Semestern ihres Studiums k\u00f6nnen Studenten ein Auslandspraktikum bei \u00fcber 300 Unternehmenspartnern weltweit machen oder sich f\u00fcr ein Auslandssemester an einer der 66 Partnerhochschulen entscheiden.<\/p> <p>Die folgenden dreij\u00e4hrigen und englischsprachigen Bachelor-Programme bietet die IBS in Budapest an: Arts Management, Business and Diplomacy, Business and Tourism, Financial Management, Management, Management with Information Systems, Management with Languages und Management with Psychology. www.wirtschaftsstudium-in-budapest.de\/index.php\/bsc\/psychology<\/p> <p>In einem Jahr zum Master of Science<br \/> Innerhalb von einem Jahr und inhaltlich nach englischem Vorbild k\u00f6nnen Bachelor-Absolventen aus dem Bereich der Wirtschaftswissenschaften an der IBS einen international anerkannten Master-Abschluss ablegen. Idealerweise arbeiten Master-Studenten bereits w\u00e4hrend des Studiums. Praktika vermittelt die IBS Budapest direkt durch ein umfangreiches Netzwerk bestehend aus mehreren Hundert Unternehmen.<\/p> <p>Die folgenden einj\u00e4hrigen und englischsprachigen Master-Programme bietet die IBS in Budapest und Wien an: International Business, Financial Management, Human Resource Management und Marketing Management. www.wirtschaftsstudium-in-budapest.de\/index.php\/msc\/marketing-management<\/p> <p>Kooperation mit englischer Universit\u00e4t<br \/> Durch die Kooperation mit der renommierten englischen Hochschule &#8222;The University of Buckingham&#8220; erhalten Absolventen einen Abschluss, der in den USA, Gro\u00dfbritannien und der EU akkreditiert und somit international anerkannt ist. Dass dieser Abschluss weltweit gesch\u00e4tzt wird, zeigt sich auch am Karriereweg der Absolventen. Einer Umfrage der IBS zufolge finden immerhin 70 Prozent der Graduierten nach sp\u00e4testens drei Monaten ihren &#8222;Einstiegs-Traumjob&#8220;.<\/p> <p>Verbindung zu deutschen Hochschulen und Erasmus-Austausch<br \/> In Deutschland kooperiert die IBS Budapest mit neun Hochschulen, unter anderem mit der Fachhochschule f\u00fcr Wirtschaft Berlin, der Fachhochschule Wedel in Hamburg und der Hochschule Bremen. Neben einem Auslandssemester als Student der IBS Budapest ist nat\u00fcrlich auch ein Erasmus-Austausch mit deutschen Hochschulen m\u00f6glich. http:\/\/wirtschaftsstudium-in-budapest.de\/index.php\/erasmus<\/p> <p>Video:<br \/> <iframe loading=\"lazy\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/4mxWTkOWbBs?feature=oembed\" frameborder=\"0\" allowfullscreen><\/iframe><\/p> <p>Die International Business School Budapest (IBS) wurde 1991 gegr\u00fcndet und gilt als die erste rein private ungarische Hochschule. 1997 erhielt die IBS vom Staat ihre offizielle Akkreditierung und damit das Recht, ungarische Bachelor-Abschl\u00fcsse zu vergeben. Durch die Kooperation mit einer Universit\u00e4t aus Gro\u00dfbritannien, konnte die IBS schon zuvor den Bachelor-Titel nach englischem Vorbild verleihen.<\/p> <p>Sukzessive wurde die Hochschule erweitert und bietet heute acht Bachelor-und vier Masterstudieng\u00e4nge in Budapest und an ihrem neuen Campus in Wien an. Bis 2012 schlossen insgesamt 3 300 Absolventen ein Studium an der IBS ab. 358 Deutsche kamen als Absolventen und als Austauschstudenten nach Ungarn. Das umfangreiche Alumni-Netzwerk der IBS kn\u00fcpft Verbindungen zu Graduierten in mehr als 80 L\u00e4nder der Erde. Auf die Alumni-Kontakte ist die Hochschule besonders stolz, denn jeder dritte Absolvent entscheidet sich, Teil dieses Netzwerks zu sein. www.wirtschaftsstudium-in-budapest.de<\/p> <p>Kontakt<br \/> IBS Budapest c\/o Finde Communications<br \/> Kai Schirdewahn<br \/> Gluckstr. 57<br \/> 22081 Hamburg<br \/> 040-22853541<br \/> info@wirtschaftsstudium-in-budapest.de<br \/> http:\/\/www.wirtschaftsstudium-in-budapest.de<\/p> <p>Pressekontakt:<br \/> Finde Communications<br \/> Kai Schirdewahn<br \/> Gluckstr. 57<br \/> 22081 Hamburg<br \/> 040-22853541<br \/> info@wirtschaftsstudium-in-budapest.de<br \/> http:\/\/www.finde-communications.com<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Hinaus in die weite BWL-Welt Wirtschaft wirklich international studieren Die International Business School Budapest (IBS) bietet acht Bachelor- und vier Masterstudieng\u00e4nge in englischer Sprache an. Alle Programme sind durch fest integrierte Auslandsaufenthalte stark international ausgerichtet. Besonderer Wert wird auch auf die Perfektionierung des Englischen als Arbeitssprache gelegt. Anfang 2013 er\u00f6ffnete die IBS zudem einen neuen<\/p>\n","protected":false},"author":1,"featured_media":153168,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[134],"class_list":["post-40775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-karriere-beruf-bildung","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/40775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=40775"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/40775\/revisions"}],"predecessor-version":[{"id":265866,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/40775\/revisions\/265866"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153168"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=40775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=40775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=40775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}