{"id":40890,"date":"2013-08-08T12:54:38","date_gmt":"2013-08-08T12:54:38","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=40890"},"modified":"2018-03-16T12:21:07","modified_gmt":"2018-03-16T11:21:07","slug":"innovatives-konzept-resilienztraining","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/innovatives-konzept-resilienztraining-1040890\/","title":{"rendered":"Innovatives Konzept Resilienztraining"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Brigitte Hettenkofer - Langj\u00e4hrige Erfahrung als Psychotherapeutin in Fachkliniken\" alt=\"Brigitte Hettenkofer - Langj\u00e4hrige Erfahrung als Psychotherapeutin in Fachkliniken\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/08\/185799-150x150.jpg\" width=\"131\" height=\"131\" \/>Fit und gesund im Job mit NeuroResilienz<\/p> <p>Das neue Institut NeuroResilienz, gegr\u00fcndet von Brigitte Hettenkofer unterst\u00fctzt arbeitende Menschen mit einem innovativen Konzept, gesund, fit und leistungsf\u00e4hig zu bleiben &#8211; ein Resilienztraining der besonderen Art.<br \/> Unter dem neuen Dach NeuroResilienz bietet die Theologin und Neuroimaginationscoach Brigitte Hettenkofer (http:\/\/www.brigittehettenkofer.de) ein innovatives Konzept f\u00fcr Trainings und Einzelcoachings an. Das Angebot hilft Menschen, stressfrei und erfolgreich zu arbeiten &#8211; gesund und leistungsf\u00e4hig zu bleiben.<br \/> <!--more-->Laut Duden bedeutet &#8222;Resilienz psychische Widerstandskraft; die F\u00e4higkeit, schwierige Lebenssituationen ohne anhaltende Beeintr\u00e4chtigung zu \u00fcberstehen.&#8220; Die Erkenntnisse aus der relativ jungen Resilienzforschung belegen, dass Menschen mit einer hohen Resilienz gerade mit der hochkomplexen Arbeitswelt besser umgehen k\u00f6nnen. Resiliente Menschen verf\u00fcgen \u00fcber eine typische Gestalter Mentalit\u00e4t. Sie sind ausgeglichen und stressresistent. Das Wissen aus der Resilienzforschung wird in Zukunft immer mehr in die Konzepte des betrieblichen Gesundheitsmanagements einflie\u00dfen. Es gibt schon Aussagen dar\u00fcber, dass ein fundiertes Resilienztraining einen festen Platz als Personalentwicklungsinstrument bekommen wird. Grund daf\u00fcr ist, dass die Resilienzkonzepte wirkungsvolle Strategien aufweisen, wie der arbeitende Mensch heute dauerhaft gesund, fit und erfolgreich bleiben kann.<br \/> Der Begriff &#8222;Resilienz&#8220; kommt aus der Physik und meint die F\u00e4higkeit eines K\u00f6rpers, nach Druckeinwirkung wieder die urspr\u00fcngliche Form einzunehmen. Auf den Menschen \u00fcbertragen, dr\u00fcckt das Bild des Stehaufm\u00e4nnchens diese F\u00e4higkeit ziemlich gut aus: Das Stehaufm\u00e4nnchen richtet sich aus jeder beliebigen Lage wieder von selbst auf. Es kommt aus jeder Schr\u00e4glage wieder hoch.<br \/> Resilienz ist keine neue Erfindung und auch keine neue Methode aus der Psychologie, sondern beschreibt vielmehr eine Kernkompetenz, mit der das herausfordernde Leben gelingen kann. Jeder und jede kann diese Kompetenz entwickeln &#8211; trainieren. Die Hirnforschung best\u00e4tigt das. Der Neurobiologe Professor Gerald H\u00fcther betont unerm\u00fcdlich und auf wunderbar einfache Art, dass wir Menschen ein Leben lang in der Lage sind, Neues zu lernen. Dieses Prinzip wird Neuroplastizit\u00e4t genannt. Bis ins hohe Alter kann der Mensch auf neue Art und Weise denken, f\u00fchlen und handeln. Neue Verhaltensweisen k\u00f6nnen entwickelt werden. Dabei bilden sich neue neuronale Netzwerke heraus. Das Gehirn ver\u00e4ndert sich. Die Neurobiologie belegt, innere St\u00e4rke, psychische Widerstandskraft kann trainiert werden.<\/p> <p>Damit ein Mensch Resilienz entfalten kann, braucht er einen klaren Kopf. Unter hohem Stress &#8211; unter hoher Belastung ist es schwer, diese Kernkompetenz zu entwickeln. Es f\u00fchlt sich dann wie harte und schwei\u00dftreibende Arbeit im Steinbruch an. Es geht auch einfacher. Mit der innovativen Methode Neuroimagination (<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.neuroimagination.de\" title=\"10 Jahre Neu\u00adro\u00adi\u00adma\u00adgi\u00adna\u00adtion\" >http:\/\/www.neuroimagination.de<\/a>) werden hinderliche Blockaden im Gehirn aufgel\u00f6st. Das ist die Voraussetzung daf\u00fcr, dass gesunde neuronale Muster entstehen. Neuroimagination ist eine k\u00f6rpergest\u00fctzte Mentaltechnik, von Horst Kraemer entwickelt und wissenschaftlich von dem Stressforscher Professor Manfred Schedlowski, Universit\u00e4t Duisburg-Essen auf seine Wirksamkeit hin evaluiert.<br \/> Das neue Institut NeuroResilienz (http:\/\/www.neuro-resilienz.de) , von Brigitte Hettenkofer, bietet eine F\u00fclle von Wissen und Informationen aus der Resilienz- und Hirnforschung. Eine einzigartige Kombination aus altbew\u00e4hrten Techniken und innovativen Mental\u00fcbungen unterst\u00fctzt Menschen dabei, stressresitent zu werden, sich (wieder) selbst zu steuern und selbstwirksam zu handeln, sowohl beruflich als auch privat.<\/p> <p>Das Institut unterst\u00fctzt Unternehmen und Einzelpersonen, gesund und leistungsf\u00e4hig auf dem Arbeitsplatz zu werden und zu bleiben.<\/p> <p>Kontakt:<br \/> Institut NeuroResilienz<br \/> Brigitte Hettenkofer<br \/> Homburger Landstr. 193<br \/> 60435 Fankfurt am Main<br \/> 069 58033766<br \/> bh@brigittehettenkofer.de<br \/> http:\/\/www.neuro-resilienz.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Fit und gesund im Job mit NeuroResilienz Das neue Institut NeuroResilienz, gegr\u00fcndet von Brigitte Hettenkofer unterst\u00fctzt arbeitende Menschen mit einem innovativen Konzept, gesund, fit und leistungsf\u00e4hig zu bleiben &#8211; ein Resilienztraining der besonderen Art. Unter dem neuen Dach NeuroResilienz bietet die Theologin und Neuroimaginationscoach Brigitte Hettenkofer (http:\/\/www.brigittehettenkofer.de) ein innovatives Konzept f\u00fcr Trainings und Einzelcoachings an.<\/p>\n","protected":false},"author":1,"featured_media":153171,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,129],"tags":[134],"class_list":["post-40890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-geisteswissenschaften-psychologie","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/40890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=40890"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/40890\/revisions"}],"predecessor-version":[{"id":264930,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/40890\/revisions\/264930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153171"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=40890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=40890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=40890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}