{"id":41783,"date":"2013-08-15T15:18:52","date_gmt":"2013-08-15T15:18:52","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=41783"},"modified":"2017-10-20T14:27:21","modified_gmt":"2017-10-20T13:27:21","slug":"kreativitaet-und-einfallsreichtum","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/kreativitaet-und-einfallsreichtum-1041783\/","title":{"rendered":"Kreativit\u00e4t und Einfallsreichtum"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-41925\" title=\"Das Maker Movement ist als Gegenbewegung zu in der Gesellschaft immer weiter verbreiteten fortschrittlichen Technologien wie Smartphones und Tablets entstanden\" alt=\"Das Maker Movement ist als Gegenbewegung zu in der Gesellschaft immer weiter verbreiteten fortschrittlichen Technologien wie Smartphones und Tablets entstanden\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/08\/Screenshot_34.jpg\" width=\"288\" height=\"100\" \/>Satelliten, Strandgiganten und Science Fiction bei der Kerkrade Mini Maker Faire<\/p> <p>Ein neun Meter hoher Nachbau des Eiffelturms, Schmuck aus Fahrradreifen, Lichtobjekte, ein Satellit, nachhaltige Kleidung, Kunstwerke aus Polyurethanschaum, 3D-Drucker, Science Fiction-Kost\u00fcme, Arduino-Plattformen f\u00fcr Anf\u00e4nger, ein 2 Meter hoher Roboter aus Karton, die Strandgesch\u00f6pfe von Theo Jansen: zum Line-up der Kerkrade Mini Maker Faire geh\u00f6ren bereits fantastische Kreationen von &#8222;Makern&#8220;.<\/p> <p>Satelliten, Strandgiganten und Science Fiction bei der Kerkrade Mini Maker Faire<\/p> <p><!--more-->Ein neun Meter hoher Nachbau des Eiffelturms, Schmuck aus Fahrradreifen, Lichtobjekte, ein Satellit, nachhaltige Kleidung, Kunstwerke aus Polyurethanschaum, 3D-Drucker, Science Fiction-Kost\u00fcme, Arduino-Plattformen f\u00fcr Anf\u00e4nger, ein 2 Meter hoher Roboter aus Karton, die Strandgesch\u00f6pfe von Theo Jansen: zum Line-up der Kerkrade Mini Maker Faire geh\u00f6ren bereits fantastische Kreationen von &#8222;Makern&#8220; aus der Euregio. Und t\u00e4glich melden sich weitere Maker f\u00fcr die erste Ausgabe dieses Festivals des Erfindungsreichtums am 7. und 8. September im Discovery Center Continium Kerkrade an. Ein Wochenende lang k\u00f6nnen die Besucher nicht nur allerlei faszinierende selbst hergestellte Kreationen bewundern, sondern auch an Workshops und hands on-Aktivit\u00e4ten teilnehmen. Es gilt der spezielle Eintrittspreis von 6,- EUR f\u00fcr Erwachsene ab 18 Jahren und 4,50 EUR f\u00fcr Kinder von 4-17. Mit der Eintrittskarte kann man sowohl die Mini Maker Faire als auch das Continium besuchen.<\/p> <p>Die Kerkrade Mini Maker Faire ist ein zweit\u00e4giges Festival, bei dem Jung und Alt die Kreativit\u00e4t und den Einfallsreichtum sogenannter Maker aus der Euregio kennen lernen k\u00f6nnen. Der Sammelbegriff &#8222;Maker&#8220; stammt aus den Vereinigten Staaten und bezeichnet Technik-Freaks ebenso wie Hobby-T\u00fcftler und andere Kreative. Ihnen allen gemeinsam ist, dass sie selbst etwas Ausgefallenes herstellen k\u00f6nnen &#8211; oft mit den eigenen H\u00e4nden. Diese Community trifft sich auf der Mini Maker Faire, zeigt ihre Produkte und teilt ihr Wissen mit der \u00d6ffentlichkeit.<\/p> <p>Unergr\u00fcndliche Technik<br \/> Das Maker Movement ist als Gegenbewegung zu in der Gesellschaft immer weiter verbreiteten fortschrittlichen Technologien wie Smartphones und Tablets entstanden. Immer mehr Menschen werden davon abh\u00e4ngig, doch immer weniger Menschen begreifen, wie diese Technik funktioniert. Die Hersteller sorgen oft selbst daf\u00fcr, dass diese Technik unergr\u00fcndlich ist, indem sie die Produkte so entwerfen, dass sie von den meisten Menschen nicht ge\u00f6ffnet werden k\u00f6nnen. Maker hingegen sch\u00e4tzen die Erfahrung des Ausdenkens, Bauens, Testens und Verbesserns ihrer Kreationen und kommen so auf die innovativsten Dinge.<\/p> <p>8. September: Theo Jansen<br \/> Manche Maker nutzen bestehende Technik, andere beginnen bei Null, wie der K\u00fcnstler und Erfinder Theo Jansen. Er kommt am 8. September mit seinen Strandgesch\u00f6pfen zur Kerkrade Mini Maker Faire: gigantische Installationen aus PVC-Rohren, die sich selbstst\u00e4ndig fortbewegen k\u00f6nnen. Jansen arbeitet fortw\u00e4hrend an der Optimierung seiner Kreaturen: Ziel ist ein Strandtier, dass sich selbst retten kann, genau wie lebendige Tiere. Am Sonntag, dem 8. September, zeigt er seine Strandtiere und h\u00e4lt um 16.00 Uhr einen Vortrag.<\/p> <p>Noch Pl\u00e4tze f\u00fcr Maker frei!<br \/> Das komplette Programm der Kerkrade Mini Maker Faire ist in K\u00fcrze auf www.makerfairekerkrade.com zu finden. Alle, die selbst etwas produzieren und sich f\u00fcr die Teilnahme an der Mini Maker Faire interessieren, k\u00f6nnen sich \u00fcber diese Website noch anmelden.<\/p> <p>Die KAM3 GmbH Kommunikationsagentur ist auf die Beratung von Unternehmen in der Kommunikation, Public Relations, Marktforschung, Mediaplanung, Werbung und Verkaufsf\u00f6rderung spezialisiert. Besondere Erfahrungen besitzt die Kommunikationsagentur KAM3 zudem im Design, im Ethnomarketing, in den Segmenten Fahrrad, Tourismus und Gesundheit sowie in der grenz\u00fcberschreitenden Kommunikation zwischen Deutschland, Belgien und den Niederlanden. 2013 feiert die Kommunikationsagentur KAM3 ihr 20j\u00e4hriges Bestehen!<\/p> <p>Kontakt:<br \/> KAM3 GmbH Kommunikationsagentur<br \/> Vojislav Miljanovic<br \/> Finkenstra\u00dfe 8<br \/> 52531 \u00dcbach-Palenberg<br \/> 02451-909310<br \/> vm@kam3.de<br \/> http:\/\/www.kam3.de<\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Satelliten, Strandgiganten und Science Fiction bei der Kerkrade Mini Maker Faire Ein neun Meter hoher Nachbau des Eiffelturms, Schmuck aus Fahrradreifen, Lichtobjekte, ein Satellit, nachhaltige Kleidung, Kunstwerke aus Polyurethanschaum, 3D-Drucker, Science Fiction-Kost\u00fcme, Arduino-Plattformen f\u00fcr Anf\u00e4nger, ein 2 Meter hoher Roboter aus Karton, die Strandgesch\u00f6pfe von Theo Jansen: zum Line-up der Kerkrade Mini Maker Faire geh\u00f6ren<\/p>\n","protected":false},"author":1,"featured_media":41925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[71],"tags":[134],"class_list":["post-41783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kultur-kunst-literatur","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/41783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=41783"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/41783\/revisions"}],"predecessor-version":[{"id":264648,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/41783\/revisions\/264648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=41783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=41783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=41783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}