{"id":41853,"date":"2013-08-16T08:38:07","date_gmt":"2013-08-16T08:38:07","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=41853"},"modified":"2013-08-19T16:06:41","modified_gmt":"2013-08-19T15:06:41","slug":"mikronaehrstoffe-in-der-krebstherapie","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/mikronaehrstoffe-in-der-krebstherapie-1041853\/","title":{"rendered":"Mikron\u00e4hrstoffe in der Krebstherapie"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Die Deutsche Gesundheitshilfe informiert \u00fcber die Bedeutung einer ausreichenden Versorgung, zeigt auf, wie ein Mangel entstehen kann, worauf bei der Einnahme geachtet werden sollte, was Mikron\u00e4hrstoffe bewirken k\u00f6nnen und welche Funktion sie haben.\" alt=\"Die Deutsche Gesundheitshilfe informiert \u00fcber die Bedeutung einer ausreichenden Versorgung, zeigt auf, wie ein Mangel entstehen kann, worauf bei der Einnahme geachtet werden sollte, was Mikron\u00e4hrstoffe bewirken k\u00f6nnen und welche Funktion sie haben.\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/08\/186813-150x150.jpg\" width=\"128\" height=\"128\" \/>Die richtigen Mikron\u00e4hrstoffe bei Krebs<\/p> <p>Neues Taschenbuch f\u00fcr Patienten erschienen<\/p> <p>Krebspatienten leiden h\u00e4ufig unter einem schweren Mangel an Vitaminen und Mineralstoffen. Die Deutsche Gesundheitshilfe informiert \u00fcber Ursachen, Risiken und Folgen sowie die M\u00f6glichkeiten einer ausreichenden Zufuhr.<\/p> <p><!--more-->Nach offiziellen Sch\u00e4tzungen erkranken in Deutschland jedes Jahr mehr als 450.000 Menschen neu an Krebs. Bereits bei Diagnose leiden viele Betroffene krankheitsbedingt unter einer erheblichen Unterversorgung mit Mikron\u00e4hrstoffen. Zus\u00e4tzlich ist der Bedarf aufgrund der belastenden und intensiven Behandlung deutlich erh\u00f6ht.<\/p> <p>Heute ist wissenschaftlich belegt, dass die kontrollierte Einnahme von Vitaminen, Mineralstoffen und Spurenelementen einen wichtigen Beitrag dazu leisten kann, die Tumorerkrankung positiv zu beeinflussen und das Immunsystem zu unterst\u00fctzen. Zus\u00e4tzlich k\u00f6nnen Mikron\u00e4hrstoffe helfen, die Nebenwirkungen der Chemotherapie und Strahlentherapie zu lindern, die Prognose der Krankheit zu verbessern und die Lebensqualit\u00e4t zu steigern.<\/p> <p>Die Deutsche Gesundheitshilfe kl\u00e4rt auf<\/p> <p>In dem neuen kostenlosen Taschenbuch &#8218;Mikron\u00e4hrstoffe bei Krebs&#8216; erfahren Patienten, ob sie sich ausreichend versorgen, an welchen N\u00e4hrstoffen es mangeln kann, worauf bei der Einnahme geachtet werden sollte und was Mikron\u00e4hrstoffe bei der Krebstherapie bewirken k\u00f6nnen.<\/p> <p>Weitere Informationen zum Thema sowie zur Anforderung des Taschenbuches auf www.gesundheitshilfe.de (http:\/\/www.gesundheitshilfe.de)<\/p> <p>Die Deutsche Gesundheitshilfe e.V. wurde 1978 gegr\u00fcndet und ist ein gemeinn\u00fctziger Verein f\u00fcr die bundesweite Aufkl\u00e4rung und Information in Gesundheit und Medizin. Im Mittelpunkt der Arbeit stehen sowohl allgemein alle Menschen als auch individuell der einzelne Patient in Therapie, Vorbeugung, Fr\u00fcherkennung und Prophylaxe. Gesund bleiben und gesund werden ist das Ziel &#8211; durch Gesundheitsberatung, Veranstaltungen oder Brosch\u00fcren. Hierbei informiert der Verein \u00fcber Symptome und deren Bedeutung, Verfahren der Diagnose, die Art der Krankheit, die medizinische Indikation und M\u00f6glichkeiten der Behandlung. Zus\u00e4tzlich ist die Deutsche Gesundheitshilfe f\u00fcr Fachkreise t\u00e4tig und richtet sich dabei an \u00c4rzte, Apotheker sowie andere Heilberufe und Therapeuten.<\/p> <p>Kontakt:<br \/> Deutsche Gesundheitshilfe e.V.<br \/> Sonja Roberti<br \/> Hausener Weg 61<br \/> 60489 Frankfurt am Main<br \/> T: 069-780042<br \/> pressekontakt@gesundheitshilfe.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.gesundheitshilfe.de\" title=\"Mikron\u00e4hrstoffmangel bei Krebs ist weit verbreitet und kann sowohl durch die Erkrankung selbst als auch durch die Therapie entstehen. \" >http:\/\/www.gesundheitshilfe.de<\/a><\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Die richtigen Mikron\u00e4hrstoffe bei Krebs Neues Taschenbuch f\u00fcr Patienten erschienen Krebspatienten leiden h\u00e4ufig unter einem schweren Mangel an Vitaminen und Mineralstoffen. Die Deutsche Gesundheitshilfe informiert \u00fcber Ursachen, Risiken und Folgen sowie die M\u00f6glichkeiten einer ausreichenden Zufuhr.<\/p>\n","protected":false},"author":1,"featured_media":153175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[134],"class_list":["post-41853","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernaehrung-wellness-gesundheit","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/41853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=41853"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/41853\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153175"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=41853"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=41853"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=41853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}