{"id":42526,"date":"2013-08-22T08:32:10","date_gmt":"2013-08-22T08:32:10","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=42526"},"modified":"2025-03-21T12:36:27","modified_gmt":"2025-03-21T11:36:27","slug":"zu-wenig-fuehrungsausbildung-in-unternehmen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/zu-wenig-fuehrungsausbildung-in-unternehmen-1042526\/","title":{"rendered":"Zu wenig F\u00fchrungsausbildung in Unternehmen"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Sales Management Review - Vertriebssteuerung\" alt=\"Sales Management Review - Vertriebssteuerung\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/08\/186880-150x150.jpg\" width=\"117\" height=\"117\" \/>Weniger Boni und mehr F\u00fchrung im Vertrieb: vom Milit\u00e4r lernen<\/p> <p>Ehemaliger General vergleicht Wirtschaft und Milit\u00e4r und sieht F\u00fchrungsschw\u00e4chen in vielen Au\u00dfendienstorganisationen | Erste Ausgabe der neuen Fachzeitschrift Sales Management Review mit Schwerpunkt Vertriebssteuerung erschienen<\/p> <p>&#8222;Unternehmen investieren in ihren Vertriebsabteilungen zu viel in Verg\u00fctung und zu wenig in F\u00fchrungsausbildung&#8220; &#8211; so eine der Kernaussagen des Brigadegeneral a.D. und Diplom-Ingenieur Stephan Kretschmer. <!--more-->Im Interview mit Ove Jensen, Professor am Lehrstuhl f\u00fcr Vertriebsmanagement an der WHU &#8211; Otto Beisheim School of Management, zieht der fr\u00fchere Kommandeur des Zentrums f\u00fcr Innere F\u00fchrung der Bundeswehr Analogien zwischen F\u00fchrungsgrunds\u00e4tzen des Milit\u00e4rs und denen von Vertriebsleitern aus der Wirtschaft. Das Interview ist Teil des Schwerpunktthemas Vertriebssteuerung der ersten Ausgabe der neuen Sales Management Review von Springer Gabler.<\/p> <p>&#8222;Wenn Unternehmen etwas vom Milit\u00e4r lernen k\u00f6nnen, dann ist es, dass F\u00fchrung Berufsmittelpunkt bei F\u00fchrungskr\u00e4ften sein muss und dass die F\u00fchrungskraft eher von der Mannschaft abh\u00e4ngt als umgekehrt&#8220;, erkl\u00e4rt Kretschmer. Gerade im Vertrieb werde zur Motivation aber stattdessen zu viel in Boni und zu wenig in F\u00fchrung investiert. Als der Experte sich aus der Welt des Milit\u00e4rs in die der Wirtschaft eingearbeitet hat, war er \u00fcberrascht, wie wenig F\u00fchrungsausbildung es in Unternehmen gibt: &#8222;Das Milit\u00e4r investiert viel mehr. Wenn ich zusammenrechne, was ich in meinem Leben an F\u00fchrungskr\u00e4fteausbildung genossen habe, kommen mehrere Jahre zusammen, Theorie und Praxis&#8220;.<\/p> <p>Die neue Fachzeitschrift Sales Management Review von Springer Gabler wird von Professor Dr. Ove Jensen herausgegeben. Zielgruppe sind Entscheider in vertrieblichen F\u00fchrungspositionen von Unternehmen. F\u00fcr diese schaffen Verlag und Herausgeber ein Informationsangebot an der Schnittstelle von Wissenschaft und Praxis. Realisiert wird das Konzept durch die enge Zusammenarbeit der Verlagsredaktion mit dem Vertriebs-Lehrstuhl der WHU. Unter der Dachmarke Campus for Sales organisiert der Lehrstuhl eine j\u00e4hrliche Managementkonferenz, einen Videokanal, eine Social Community sowie Seminarangebote. Digitale Heimat der Zeitschrift ist die Wissensplattform Springer f\u00fcr Professionals. Dort verkn\u00fcpft eine erweiterte Fachredaktion im Verlag die Zeitschriftenbeitr\u00e4ge mit eigenen redaktionellen Inhalten wie z.B. thematisch passenden Online-Dossiers, die die Leser bei der wirkungsvollen Vertriebsarbeit unterst\u00fctzen, und relevanten Informationen aus der Datenbank.<\/p> <p>Weitere Informationen:<\/p> <p>www.springer.com\/about+springer\/media\/pressreleases?SGWID=1-11002-6-1432941-0 | Pressemitteilung + Materialien zum Herunterladen<br \/> www.springerprofessional.de\/4621602.html | Springer f\u00fcr Professionals: Video-Interview mit Professor Dr. Ove Jensen zum Konzept der neuen Fachzeitschrift Sales Management Review<br \/> www.springerprofessional.de | Wissensplattform Springer f\u00fcr Professionals<br \/> www.springerprofessional.de\/vertrieb | Channel Vertrieb auf Springer f\u00fcr Professionals<br \/> www.whu.edu\/vertrieb | Lehrstuhl f\u00fcr Vertriebsmanagement WHU &#8211; Otto Beisheim School of Management<br \/> www.campus-for-sales.de | Website Campus for Sales<\/p> <p>Kontakt:<br \/> Karen Ehrhardt | Manager Corporate Communications | tel +49 611 7878 394 | karen.ehrhardt@springer.com<\/p> <p>Springer Gabler ist eine Marke von Springer DE. Springer DE ist Teil von Springer Science Business Media.<\/p> <p>Kontakt:<br \/> Springer Gabler | Springer Fachmedien Wiesbaden GmbH<br \/> Karen Ehrhardt<br \/> Abraham-Lincoln-Str. 46<br \/> 65189 Wiesbaden<br \/> tel +49 611 7878 394<br \/> cornelia.hesse@springer.com<br \/> http:\/\/www.springer-gabler.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Weniger Boni und mehr F\u00fchrung im Vertrieb: vom Milit\u00e4r lernen Ehemaliger General vergleicht Wirtschaft und Milit\u00e4r und sieht F\u00fchrungsschw\u00e4chen in vielen Au\u00dfendienstorganisationen | Erste Ausgabe der neuen Fachzeitschrift Sales Management Review mit Schwerpunkt Vertriebssteuerung erschienen &#8222;Unternehmen investieren in ihren Vertriebsabteilungen zu viel in Verg\u00fctung und zu wenig in F\u00fchrungsausbildung&#8220; &#8211; so eine der Kernaussagen des<\/p>\n","protected":false},"author":1,"featured_media":153134,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[134],"class_list":["post-42526","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-karriere-beruf-bildung","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/42526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=42526"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/42526\/revisions"}],"predecessor-version":[{"id":269694,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/42526\/revisions\/269694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153134"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=42526"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=42526"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=42526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}