{"id":43192,"date":"2013-08-27T13:20:31","date_gmt":"2013-08-27T13:20:31","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=43192"},"modified":"2013-08-27T15:04:46","modified_gmt":"2013-08-27T14:04:46","slug":"wir-steuern-das-schon","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wir-steuern-das-schon-1043192\/","title":{"rendered":"&#8222;Wir steuern das schon&#8220;"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-43225\" title=\"85,9 Prozent der Bundesliga-Fans meinen, Politik habe im Fu\u00dfball nichts zu suchen\" alt=\"85,9 Prozent der Bundesliga-Fans meinen, Politik habe im Fu\u00dfball nichts zu suchen\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/08\/Screenshot_181.jpg\" width=\"520\" height=\"134\" \/>Gro\u00dfe Mehrheit der Bundesliga-Fans lehnt &#8222;Anti-Hoene\u00df-Aktion&#8220; der Jusos ab<\/p> <p>Fan-Meinung: Politik hat in der Bundesliga nichts zu suchen, ergab die repr\u00e4sentative Umfrage der SLC Management, dem gr\u00f6\u00dften deutschen Unternehmen im Sportbefragungsmarkt<\/p> <p>Die Gro\u00dfe Mehrheit der Bundesliga-Fans lehnt die von den Jusos geplante &#8222;Anti-Hoene\u00df&#8220; Aktion ab. Das ist das Ergebnis einer aktuellen Fan-Befragung durch die SLC Management (http:\/\/www.slc-ag.com\/) . Die Jugendorganisation der SPD hatte am Wochenende geplant, 100.000 Postkarten, auf denen Steuers\u00fcnder Uli Hoene\u00df, Pr\u00e4sident des FC Bayern M\u00fcnchen, Bundeskanzlerin Angela Merkel l\u00e4chelnd die Hand dr\u00fcckt, vor den Bundesliga-Stadien zu verteilen. <!--more-->In Anspielung auf die Steueraff\u00e4re des Bayern-Pr\u00e4sidenten werden der Regierungschefin auf dem Flugblatt die Worte &#8222;Gl\u00fcckwunsch Uli! Wir Steuern das schon&#8220; in den Mund gelegt.<\/p> <p>85,9 Prozent der Bundesliga-Fans finden die Aktion nicht gut und sind der Meinung, dass Politik nichts in der Bundesliga zu suchen hat. Noch eindeutiger ist die Haltung unter den Fans des FC Bayern M\u00fcnchen. Dort lehnen 98,1 Prozent die geplante Aktion ab. &#8222;Das Ergebnis zeigt deutlich, dass politisch motivierte Wahlkampfaktionen in der Bundesliga nicht erw\u00fcnscht sind&#8220;, so Professor Dr. Alfons Madeja, Gesch\u00e4ftsf\u00fchrer der SLC Management GmbH.<\/p> <p>Zur &#8222;Anti-Hoene\u00df-Aktion&#8220; wurden repr\u00e4sentativ 1000 Bundesliga-Fans aller Vereine befragt. Die SLC Management GmbH ist das f\u00fchrende Unternehmen f\u00fcr repr\u00e4sentative Bundesliga-Marktforschung in Deutschland. Das Unternehmen verf\u00fcgt als Einziger \u00fcber einen repr\u00e4sentativen Bundesliga-Panel mit registrierten Teilnehmern aus dem Kreis aller Vereine.<\/p> <p>Die SLC Management GmbH ist das f\u00fchrende Unternehmen f\u00fcr repr\u00e4sentative Bundesliga-Marktforschung in Deutschland. Das Unternehmen verf\u00fcgt als Einziger \u00fcber einen repr\u00e4sentativen Bundesliga-Panel mit registrierten Teilnehmern aus dem Kreis aller Vereine und ist Herausgeber des Bundesliga-Barometers<\/p> <p>Kontakt<br \/> SLC Management GmbH<br \/> Professor Alfons Madeja<br \/> Laufamholzstra\u00dfe 116<br \/> 90482 N\u00fcrnberg<br \/> 0911 548180<br \/> info@slc-ag.com<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.slc-ag.com\" title=\"umfassende, individuelle und differenzierte Beratungs- und Konzeptionsleistungen\" >http:\/\/www.slc-ag.com<\/a><\/p> <p>Pressekontakt:<br \/> Redaktion M\u00fcnchen<br \/> Heiner Sieger<br \/> Zugspitzstra\u00dfe 140<br \/> 85591 Vaterstetten<br \/> 0049 15154679622<br \/> heiner.sieger@redaktionmuenchen.com<br \/> http:\/\/www.redaktionmuenchen.com<\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Gro\u00dfe Mehrheit der Bundesliga-Fans lehnt &#8222;Anti-Hoene\u00df-Aktion&#8220; der Jusos ab Fan-Meinung: Politik hat in der Bundesliga nichts zu suchen, ergab die repr\u00e4sentative Umfrage der SLC Management, dem gr\u00f6\u00dften deutschen Unternehmen im Sportbefragungsmarkt Die Gro\u00dfe Mehrheit der Bundesliga-Fans lehnt die von den Jusos geplante &#8222;Anti-Hoene\u00df&#8220; Aktion ab. Das ist das Ergebnis einer aktuellen Fan-Befragung durch die SLC<\/p>\n","protected":false},"author":1,"featured_media":43225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[100],"tags":[134],"class_list":["post-43192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/43192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=43192"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/43192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=43192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=43192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=43192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}