{"id":4426,"date":"2012-12-28T09:45:29","date_gmt":"2012-12-28T09:45:29","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=4426"},"modified":"2015-06-15T06:54:48","modified_gmt":"2015-06-15T05:54:48","slug":"wenig-klarheit-ueber-berufliche-perspektive","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wenig-klarheit-ueber-berufliche-perspektive-104426\/","title":{"rendered":"Wenig Klarheit \u00fcber berufliche Perspektive"},"content":{"rendered":"<div> <p>Vielen Leistungstr\u00e4gern (64 %) fehlt Klarheit \u00fcber ihre berufliche Perspektive. Das ist das Ergebnis der Umfrage &#8222;Karriereschwellen von Leistungstr\u00e4gern&#8220;, die Buchautorin und Executive Coach Gudrun Happich mit ihrem Galileo . Institut f\u00fcr Human Excellence in K\u00f6ln durchgef\u00fchrt hat.<\/p> <p>Zu den h\u00e4ufigsten Nennungen der befragten F\u00fchrungskr\u00e4fte und Experten in Schl\u00fcsselpositionen geh\u00f6rt zudem der Wunsch nach mehr Souver\u00e4nit\u00e4t in der eigenen Rolle (48,4 %) und nach einem Karriereaufstieg (43,8 %). Gudrun Happich, die sich seit 20 Jahren auf F\u00fchrungskr\u00e4fte Coachings spezialisiert hat, ist \u00fcber den mangelnden Klarblick nicht \u00fcberrascht. <!--more-->&#8222;Als F\u00fchrungskr\u00e4fte Coach erlebe ich h\u00e4ufig, dass es gerade die besten Leistungstr\u00e4ger eines Unternehmens sind, die sich \u00fcber ihre Karriere-Ziele zu wenig Gedanken machen.&#8220;<\/p> <p>Rund 42 % der Befragten geben an, dass sie nur noch funktionieren und keinen Spa\u00df mehr bei der Arbeit haben. Auch Ver\u00e4nderungssituationen im Unternehmen (rund 36 %), die Vorbereitung auf eine neue Rolle (26,6 %) oder das Finden der besten Position im Unternehmen (25 %) werden als Karriereschwellen genannt. Rund 19 % sind zwar beruflich erfolgreich, aber das Privateben ist zerr\u00fcttet. \u00dcber ein permanentes \u00dcberlastungsgef\u00fchl und Unzufriedenheit trotz steiler Karriere klagen jeweils 17 %.<\/p> <p>L\u00f6sungsideen vor dem F\u00fchrungskr\u00e4fte Coaching (<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.galileo-institut.de\" title=\"F\u00fchrungskr\u00e4fte Coaching mit bioSystemik\u00ae\" >http:\/\/www.galileo-institut.de<\/a>)<\/p> <p>Bei den ersten L\u00f6sungsideen der Leistungstr\u00e4ger (http:\/\/leistungstraeger-blog.de) dominiert der Unternehmenswechsel (58,3 %), vor dem kompletten Ausstieg aus der Karriere (40 %), dem Gedanken, besser werden zu m\u00fcssen (36,7 %) oder durch einen Karrieresprung (25 %) die Situation zu kl\u00e4ren. &#8222;Auch viele meiner Klienten schildern im F\u00fchrungskr\u00e4fte Coaching, dass ihre ersten Impulse &#8222;Ich muss woanders hin&#8220; oder &#8222;Ich muss noch mehr leisten&#8220; lauteten. \u00dcberrascht hat mich, wie h\u00e4ufig der Karriere-Ausstieg als Option genannt wird. Berufliche und pers\u00f6nliche Erf\u00fcllung, das scheinen viele Menschen nicht unter einen Hut zu bringen&#8220;, sagt Gudrun Happich.<\/p> <p>Bei fast allen Befragten lag die erste L\u00f6sungsidee also au\u00dferhalb des Unternehmens, tats\u00e4chlich sind aber 89 % bei ihrem Arbeitgeber geblieben. Ein Viertel hat immer noch die gleiche Position inne und hat an seiner Einstellung gearbeitet. 23,3 % haben das Unternehmen gewechselt, 20 % sind aufgestiegen, 15 % haben sich selbst\u00e4ndig gemacht, nur 6,7 % haben die beste Position im Unternehmen gefunden. Die Mehrheit &#8211; n\u00e4mlich 38,3 % &#8211; hat gar nichts unternommen und ist immer noch in der gleichen Situation!<\/p> <p>Ein Drittel der Umfrageteilnehmer hat sich von einem F\u00fchrungskr\u00e4fte Coach begleiten lassen, um mehr Klarheit \u00fcber ihre berufliche Perspektive zu gewinnen. Die gro\u00dfe Mehrheit &#8211; 76,6% der Befragten &#8211; f\u00fchlt sich von ihrem Arbeitgeber in Krisensituation alleingelassen. &#8222;Hier liegt noch viel Potential brach&#8220;, so Executive Coach Gudrun Happich (http:\/\/www.galileo-institut.de\/gudrun-happich.html).<\/p> <p>F\u00fchrungskr\u00e4ftecoach Gudrun Happich beschleunigt mit ihrem &#8222;Galileo Institut f\u00fcr Human Excellence&#8220; die Entwicklung von Leistungstr\u00e4gern zu modernen F\u00fchrungspers\u00f6nlichkeiten, die nat\u00fcrlich besser f\u00fchren. Die Buchautorin (&#8222;\u00c4rmel hoch. Die 20 schwierigsten F\u00fchrungshemen und wie Top-F\u00fchrungskr\u00e4fte sie anpacken&#8220;) ist ehemalige F\u00fchrungskraft, Diplom-Biologin und arbeitet seit 15 Jahren als systemischer Executive Business Coach. Dieser Multi-Background spiegelt sich in ihrem mehrfach ausgezeichneten bioSystemik\u00ae-Coaching-Konzept, das systemisches, naturwissenschaftliches und unternehmerisches Know-how integriert. Mehr Infos unter http:\/\/www.galileo-institut.de und http:\/\/leistungstraeger-blog.de<\/p> <p>Sie steht f\u00fcr Interviews zur Verf\u00fcgung<\/p> <p>Kontakt:<br \/> Galileo . Institut f\u00fcr Human Excellence<br \/> Gudrun Happich<br \/> D\u00fcrener Strasse 225<br \/> 50931 K\u00f6ln<br \/> 0221-80052960<br \/> webmarketing@galileo-institut.de<br \/> http:\/\/www.galileo-institut.de<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Vielen Leistungstr\u00e4gern (64 %) fehlt Klarheit \u00fcber ihre berufliche Perspektive. Das ist das Ergebnis der Umfrage &#8222;Karriereschwellen von Leistungstr\u00e4gern&#8220;, die Buchautorin und Executive Coach Gudrun Happich mit ihrem Galileo . Institut f\u00fcr Human Excellence in K\u00f6ln durchgef\u00fchrt hat. Zu den h\u00e4ufigsten Nennungen der befragten F\u00fchrungskr\u00e4fte und Experten in Schl\u00fcsselpositionen geh\u00f6rt zudem der Wunsch nach mehr<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[134],"class_list":["post-4426","post","type-post","status-publish","format-standard","hentry","category-karriere-beruf-bildung","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/4426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=4426"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/4426\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=4426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=4426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=4426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}