{"id":44356,"date":"2013-09-03T14:31:22","date_gmt":"2013-09-03T14:31:22","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=44356"},"modified":"2013-09-04T18:02:30","modified_gmt":"2013-09-04T17:02:30","slug":"hilfe-bei-aufkeimenden-kriegserinnerungen","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/hilfe-bei-aufkeimenden-kriegserinnerungen-1044356\/","title":{"rendered":"Hilfe bei aufkeimenden Kriegserinnerungen"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-44690\" title=\"Fachmagazin ProAlter\" alt=\"Fachmagazin ProAlter\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/09\/Screenshot_18.jpg\" width=\"119\" height=\"167\" \/>\u00c4lteren Menschen beim Umgang mit Kriegserinnerungen helfenViele Menschen erinnern sich im Alter an schreckliche Erlebnisse w\u00e4hrend des Zweiten Weltkriegs. Das Kuratorium Deutsche Altershilfe (KDA) gibt in seinem Fachmagazin ProAlter Hinweise, wie Angeh\u00f6rige und Pflegende helfen k\u00f6nnen.<\/p> <p>Im Zweiten Weltkrieg haben fast alle Menschen Schreckliches erlebt. Die Erinnerungen daran kehren bei vielen im Alter zur\u00fcck, wie aktuelle Forschungen zeigen. Manchmal wird dieser Effekt durch neue Erlebnisse verst\u00e4rkt, etwa das Gef\u00fchl der Hilflosigkeit vor einer Operation: <!--more-->Es kann an die Hilflosigkeit erinnern, die der Betroffene im Krieg gef\u00fchlt hat. Ein Drittel der Kriegskinder der 1929er bis 1947er Jahrg\u00e4nge ist noch heute von den Sp\u00e4tfolgen des Krieges belastet. Das sind etwa f\u00fcnf Millionen Menschen. Auch etwa 100.000 M\u00e4nner und 400.000 Frauen \u00fcber 90 Jahre k\u00f6nnten unter den Erinnerungen leiden. Ein gro\u00dfer Teil von ihnen ist an einer Demenz erkrankt und lebt im Heim.<\/p> <p>\u201eDie Erinnerungen der Kriegsgenerationen belasten auch die nachfolgenden Generationenbeziehungen und stellen eine Herausforderung bei der Begleitung von pflegebed\u00fcrftigen Menschen dar, insbesondere den an Demenz Erkrankten\u201c, erkl\u00e4rt Dr. h. c. J\u00fcrgen Gohde, Vorstandsvorsitzender des KDA.<\/p> <p>In der ProAlter-Ausgabe 5\/2013 finden Fachleute und Betroffene Anregungen und Tipps, wie sie den schrecklichen Erinnerungen begegnen k\u00f6nnen. Weitere Informationen zur ProAlter-Ausgabe 5\/2013 finden Sie auch unter http:\/\/www.kda.de\/news-detail\/items\/proalter-52013-maikaefer-flieg-kriegserinnerungen-im-alter.html.<br \/> Das KDA setzt sich seit 1962 f\u00fcr die Lebensqualit\u00e4t und Selbstbestimmung \u00e4lterer Menschen ein. Unter der Schirmherrschaft des Bundespr\u00e4sidenten f\u00fchren Experten Projekte und Studien durch. Das KDA ber\u00e4t Ministerien, Kommunen, Unternehmen und Sozialverb\u00e4nde, bietet Fortbildungs- und Qualifizierungsma\u00dfnahmen f\u00fcr F\u00fchrungs- und Fachkr\u00e4fte an und informiert die \u00d6ffentlichkeit durch Tagungen und Publikationen sowie sein Fachmagazin ProAlter.<\/p> <p>Kontakt:<br \/> Kuratorium Deutsche Altershilfe, Wilhelmine-L\u00fcbke-Stiftung e.V.<br \/> Simone Helck<br \/> An der Pauluskirche 3<br \/> 50677 K\u00f6ln<br \/> &#8211;<br \/> simone.helck@kda.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.kda.de\" title=\"Kuratorium deutsche Altershilfe\" >www.kda.de<\/a><\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>\u00c4lteren Menschen beim Umgang mit Kriegserinnerungen helfenViele Menschen erinnern sich im Alter an schreckliche Erlebnisse w\u00e4hrend des Zweiten Weltkriegs. Das Kuratorium Deutsche Altershilfe (KDA) gibt in seinem Fachmagazin ProAlter Hinweise, wie Angeh\u00f6rige und Pflegende helfen k\u00f6nnen. Im Zweiten Weltkrieg haben fast alle Menschen Schreckliches erlebt. Die Erinnerungen daran kehren bei vielen im Alter zur\u00fcck, wie<\/p>\n","protected":false},"author":1,"featured_media":44690,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[122],"tags":[134],"class_list":["post-44356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-frauen-maenner-senioren","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/44356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=44356"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/44356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=44356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=44356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=44356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}