{"id":46850,"date":"2013-09-16T23:07:45","date_gmt":"2013-09-16T23:07:45","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=46850"},"modified":"2025-03-21T12:36:27","modified_gmt":"2025-03-21T11:36:27","slug":"qualitaetskriterien-fuer-biografien","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/qualitaetskriterien-fuer-biografien-1046850\/","title":{"rendered":"Qualit\u00e4tskriterien f\u00fcr Biografien"},"content":{"rendered":"<p>Was macht eine gute Biografie aus? \u2013 Kriterien und Charakteristika<\/p> <p>acadoo berichtet<br \/> Eine gute Biografie zu verfassen, ist kein leichtes Unterfangen. Denn der oder die Leserin muss den Protagonisten der Biografie besser kennenlernen k\u00f6nnen. Er muss sich mit seinen Erfahrungen und Handlungsweisen nicht unbedingt identifizieren k\u00f6nnen, aber eine gute Bio-grafie stimuliert das Nachdenken \u00fcber ihre Hauptperson. Sie bringt dem Publikum dessen Leben n\u00e4her, sodass sich Fragen zu biografischen Ereignissen besser oder \u00fcberzeugender be-antworten lassen. Eine gute Biografie wiederholt nicht blo\u00df einfach nur bekannte Daten oder Ereignisse aus dem Leben einer Person, sondern erweitert das Blickfeld, indem z.B. famili\u00e4res oder politisches Hintergrundwissen einflie\u00dft und das Bild dieser Person reichhaltiger und deutlicher wird.<\/p> <p><!--more-->Dadurch kann die portr\u00e4tierte Person zu einem positiven Vorbild oder alternativ zu einem negativen Gegenbild f\u00fcr das eigene Handeln und Denken werden. Eine gute Biografie vermittelt nicht nur detailliertes Wissen \u00fcber die Person, sondern auch Einblicke in seine Ethik, seine Wertvorstellungen und handlungstreibenden Motive. Deshalb ist in einer guten Biografie die Darstellung der historischen, wirtschaftlichen und sozialen Kontexte sehr wichtig. Auch nat\u00fcrliche Einflussfaktoren, Naturph\u00e4nomene oder -katastrophen k\u00f6nnen im Leben des Prota-gonisten und seiner Biografie deutliche Spuren hinterlassen und m\u00fcssen daher einbezogen werden. So ist z.B. der Roman Frankenstein von Mary Shelley u.a. im Jahr ohne Sommer 1816 entstanden, nachdem 1815 ein Vulkanausbruch in Indonesien weltweit f\u00fcr verregnete und verschneite Sommer (!) sorgte.<\/p> <p>Eine gute Biografie l\u00e4sst den Leser bzw. die Leserin mit mehr Detailwissen \u00fcber das Leben der dargestellten Person zur\u00fcck. Denn es geht in einer guten Biografie nicht blo\u00df um Voyeu-rismus und schl\u00fcpfrige Details zum Leben einer Person, sondern um \u00fcberzeugend dargelegte Zusammenh\u00e4nge und Deutungen ihres Lebensweges. Diese bieten einen Interpretationsspiel-raum, zu dem sich das lesende Publikum Gedanken machen muss. Insofern umgibt eine gute Biografie die beschriebene Person auch immer mit einer geheimnisvollen Aura. Denn am Ende der Lekt\u00fcre wirft eine gute Biografie mehr Fragen auf als sie beantworten kann.<\/p> <p>Eine gute Biografie ist deshalb kaum etwas f\u00fcr allzu eilige Leserinnen und Leser.<\/p> <p>acadoo bietet professionellen und zuverl\u00e4ssigen Text- und Schreibservice an, die jeweils individuell Ihren Umst\u00e4nden angepasst werden. Die akademischen Autoren und Berater von acadoo bieten seit mehr als 10 Jahren Support rund um das Verfassen wissenschaftlicher Arbeiten. Eine ausf\u00fchrliche Bearbeitung ist dabei eine Selbstverst\u00e4ndlichkeit. Vertrauen Sie auf die Fachkompetenz unserer Ghostwriter. Wir finden sicher, schnell und unkompliziert f\u00fcr Sie den passenden Support.<\/p> <p>Kontakt:<br \/> acadoo<br \/> Claudia Schmitt<br \/> Speditionstrasse 21<br \/> 40221 D\u00fcsseldorf<br \/> 0160 917 32 185<br \/> team@acadoo.de<br \/> www.acadoo.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Was macht eine gute Biografie aus? \u2013 Kriterien und Charakteristika acadoo berichtet Eine gute Biografie zu verfassen, ist kein leichtes Unterfangen. Denn der oder die Leserin muss den Protagonisten der Biografie besser kennenlernen k\u00f6nnen. Er muss sich mit seinen Erfahrungen und Handlungsweisen nicht unbedingt identifizieren k\u00f6nnen, aber eine gute Bio-grafie stimuliert das Nachdenken \u00fcber ihre<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[129],"tags":[134],"class_list":["post-46850","post","type-post","status-publish","format-standard","hentry","category-geisteswissenschaften-psychologie","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/46850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=46850"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/46850\/revisions"}],"predecessor-version":[{"id":269696,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/46850\/revisions\/269696"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=46850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=46850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=46850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}