{"id":4733,"date":"2013-01-01T15:00:27","date_gmt":"2013-01-01T15:00:27","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=4733"},"modified":"2017-08-11T09:20:49","modified_gmt":"2017-08-11T08:20:49","slug":"die-fineartreisen-jahresstatistik-2012","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/die-fineartreisen-jahresstatistik-2012-104733\/","title":{"rendered":"Die FineArtReisen Jahresstatistik 2012"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-4847\" title=\"die Reisezeitung im Internet\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/01\/Screenshot_7.jpg\" width=\"232\" height=\"93\" \/>Die FineArtReisen Web-Statistik z\u00e4hlt aktuell t\u00e4glich rund 49.890 Leser, welches einen monatlichen Durchschnitt von 1.496.850 Leser ergibt. In Summe sind dies f\u00fcr 2012 rund 17.962.000 Leser mit insgesamt 116.834.947 aufgerufenen Seiten; das bedeutet im Jahresdurchschnitt 6,5 Seiten pro Leser.<\/p> <p>Im Jahresverlauf schwankten die monatlichen Leserzahlen zwischen 832.000 und maximal 2.353.000. Die h\u00f6chsten Leserzahlen wurden im M\u00e4rz und im August erzielt. In den traditionell f\u00fcr Reisethemen weniger nachgefragten Monaten Oktober bis Dezember konnten immerhin in Summe 3.126.000 Leser gez\u00e4hlt werden.<\/p> <p><!--more-->Das schwerpunktm\u00e4\u00dfige Interesse der Leser von FineArtReisen konzentrierte sich 2012 &#8211; neben der Reisewelt (die meist gelesene Kategorie mit 26% aller Seitenaufrufe) &#8211; auf den Veranstaltungskalender (16%) und die Kategorien: Reisen &amp; Urlaub (10%), Tagesausgabe (4%), Nachrichten (3%), Kunst &amp; Kultur (3%), St\u00e4dtetourismus (2%), Kulinaria (2%), Infoadressen (2%) und Literatur (1%).<\/p> <p>Geografie<br \/> Die geografische Suchstatistik ermittelt das l\u00e4nderspezifische Informationsbed\u00fcrfnis der Leser von FineArtReisen.<\/p> <p>Weltweit wurden in 2012<br \/> Weltweit werden am h\u00e4ufigsten Informationen \u00fcber das Reiseland Deutschland gesucht (48%), gefolgt von Reiseinformationen zu den L\u00e4ndern USA (7%), \u00d6sterreich (5%), Italien (5%), Island (2%), Kanada (2%), D\u00e4nemark (1%), Spanien (1%), Gro\u00dfbritannien(1%) und Frankreich (1%).<\/p> <p>Regional<br \/> Regional verteilte sich das Informationsinteresse in der Reihenfolge f\u00fcr 2012 wie folgt: Bayern (17%), Nordrhein-Westfalen (7%), Baden-W\u00fcrttemberg (6%), Berlin (4%), Sachsen (4%), Schleswig-Holstein (3%), Hessen (3%), Mecklenburg-Vorpommern (3%), Tirol (3%) und Rheinland-Pfalz (3%).<\/p> <p>49% unserer Leser suchten ganz individuell ihr Reiseziel \u00fcber die Funktion der Umkreissuche.<\/p> <p>Der Reisef\u00fchrer Deutsche Donau war 2012 mit 11% der meistgelesene Reisef\u00fchrer der Online-Reisezeitung FineArtReisen, gefolgt von den Reisef\u00fchrern Bodensee (4%), Bayerischer Wald (4%), Island (4%), Nordsee (4%), Eifel (3%), Uckermark (2%), Metropole Ruhr (1%) und Schwarzwald (1%).<\/p> <p>Die meist gelesenen Beitr\u00e4ge des Jahres 2012 sind:<\/p> <p>&#8211; Werbung und Marketing im Internet<br \/> &#8211; La Vialla Casal Duro 2008<br \/> &#8211; Weingut Tirolerhof &#8211; Familie Gratl Merlot Ried Christoph 2006<br \/> &#8211; Die Fattoria La Vialla &#8211; ein gelungenes Familienexperiment<br \/> &#8211; FineArtReisen Reisef\u00fchrer Island<\/p> <p>Wie wird FineArtReisen im World Wide Web gefunden?<\/p> <p>Die Analyse der ermittelbaren Klickpfade zeigt, dass 59% unserer Leser \u00fcber twitter, 13% \u00fcber Google und 6% \u00fcber sonstige Verlinkungen und Verweise auf FineArtReisen aufmerksam werden. Etwas mehr als 50 % der Leser von FineArtReisen lesen die Online-Zeitung zwischen 8 und 17 Uhr. Schwerpunkt der Lesezeit ist der Zeitraum zwischen 11 und 12 Uhr. Daraus kann man ableiten, dass FineArtReisen sehr h\u00e4ufig vom Arbeitsplatz aus gelesen wird.<\/p> <p>Aufgrund des kontinuierlichen und erfolgreichen Einsatzes wirkungsvoller SEO-Ma\u00dfnahmen wird FineArtReisen bei dem Suchbegriff &#8222;reisezeitung&#8220; mehrfach unter den ersten zehn Suchergebnissen gelistet. Insbesondere zu Suchbegriffen, die sich aus den \u00dcberschriften der jeweiligen Beitr\u00e4ge ergeben, befindet sich FineArtReisen auf den Spitzenpl\u00e4tzen der Suchergebnisse. Der &#8222;Reisef\u00fchrer Fairbanks&#8220; eroberte bereits nach wenigen Tagen die vorderen Pl\u00e4tze im Google-Suchergebnis.<\/p> <p>Sie k\u00f6nnen beliebig in den Begriffskombinationen reisezeitung *, reisenachrichten *, sowie reiseangebote *, wechseln &#8211; sehr h\u00e4ufig werden Sie ein bis zehn Eintr\u00e4ge auf der ersten Ergebnisseite von Google finden, die zu FineArtReisen direkt oder indirekt verweisen. Dies gilt nicht nur f\u00fcr Google, sondern auch f\u00fcr die Suchergebnisse in Metasuchmaschinen wie z.B. http:\/\/ixquick.com.<\/p> <p>Bemerkenswert ist, dass die Suchergebnisse allerdings stark variieren k\u00f6nnen, da Google neben seinen Kriterien f\u00fcr die Relevanz inzwischen auch Kriterien aus dem pers\u00f6nlichen Such- und Surfverhalten des jeweiligen User in das Suchergebnis mit einflie\u00dfen l\u00e4sst. Daher kann es vorkommen, dass unterschiedliche User nach der Eingabe eines identischen Begriffes unterschiedliche Suchergebnisse erhalten.<\/p> <p>Insgesamt registriert die Google-Datenbank aktuell \u00fcber 102.000 Eintr\u00e4ge, die direkt oder indirekt auf FineArtReisen verweisen (Stand: 01.01.2013).<\/p> <p>Reisetrends im Dezember 2012 &#8211; Die h\u00e4ufigsten Suchbegriffe im Monat Dezember waren (in dieser Schreibweise): &#8222;reisen&#8220;, &#8222;bahn&#8220; und &#8222;cote a zur&#8220;. Wenn man die Variationen zur Keywordsuche mit betrachtet, dann dreht es sich bei den derzeit h\u00e4ufigsten Suchbegriffen (Keys), mit welchen in den Suchmaschinen, allen voran Google, nach Urlaubsinformationen gesucht wird um ganz allgemeine Urlaubsrecherchen. Die Begriffkombination &#8220; cote a zur&#8220; l\u00e4sst uns annehmen, dass S\u00fcdfrankreich ggf. auch die Kulturhauptstadt 2013, etwas mehr im Fokus des Reiseinteresses der Urlauber im Dezember lag.<\/p> <p>Leider erreichen uns zum Thema Kulturhauptst\u00e4dte 2013 Kosice (Slowakei) und Marseille (Frankreich) sehr wenig Informationen. Diesbez\u00fcglich w\u00fcrden wir uns seitens der Verantwortlichen und der zugeh\u00f6rigen Fremdenverkehrsorganisationen mehr Unterst\u00fctzung in Form von deutschsprachigen Informationen w\u00fcnschen. Aus Gr\u00fcnden der Rechtssicherheit m\u00fcssen wir darum bitten, diese an die eMail-Adresse nachrichten@fineartreisen.de zu senden.<\/p> <p>Der Anfang Oktober ver\u00f6ffentlichten Reiseanalyse der Forschungsgemeinschaft<br \/> Urlaub und Reisen e.V. (FUR) kann man entnehmen, dass 76% der deutschen Bev\u00f6lkerung regelm\u00e4\u00dfig Urlaub machen und dabei insgesamt 79 Mrd EUR ausgeben. Das entspricht je Urlauber einem Budget von EUR 1200 je bzw rund EUR 900 je Bundesb\u00fcrger.<\/p> <p>Allerdings findet laut der FUR Studie kein globales Wachstum des deutschen Reisemarktes mehr statt. Was bedeutet, ein Wachstum einzelner Reisedestinationen ist nur noch zu Lasten anderer Destinationen m\u00f6glich. Gleiches gilt f\u00fcr Reiseanbieter.<br \/> Wir sind gespannt , wie sich dies auf Marketing und Kommunikation der Reiseanbieter und Destinationen auswirken wird. Aus unserer Sicht werden die Destinationsvertreter verst\u00e4rkt eine Antwort darauf geben m\u00fcssen, warum man gerade in ihrer Region seinen Urlaub verbringen soll.<\/p> <p>Eine andere Erkenntnis dieser Studie ist, dass 55% der Urlauber (ca. 30 Millionen B\u00fcrger) das Internet als \u00fcberwiegende und entscheidende Informationsquelle zur Entscheidungsfindung f\u00fcr ihr Reiseziel nutzen. Dieses l\u00e4sst uns als Online-Reisezeitung nat\u00fcrlich aufhorchen. Schlie\u00dflich erreichen wir ca. zwei Drittel dieser Urlaubergruppierung.<br \/> Bedenken sollte man bei allen seinen Online-Aktivit\u00e4ten als Reisedestination, dass gerade in Situationen, wenn der Urlauber sich noch nicht f\u00fcr ein Reiseziel entschieden hat, globale \u00fcberregionale Reiseinformationsangebote, wie die der Online-Reisezeitungen, mehr im Fokus des Interesses stehen als die lokalen Online-Informationsangebote der einzelnen Destination.<\/p> <p>Weitere Details finden Sie unter http:\/\/fineartreisen.de\/html\/20130101_81178.php<br \/> fineartreisen.de\/html\/20130101_81178.php (http:\/\/fineartreisen.de\/html\/20130101_81178.php)<\/p> <p>\u00dcber FineArtReisen &#8211; die Reisezeitung im Internet<br \/> FineArtReisen.de, herausgegeben von armini foto &amp; medien verlag in Planegg bei M\u00fcnchen, ist ein innovatives und einzigartiges Zeitungsprojekt im Internet, das aktuelle Veranstaltungshinweise, Nachrichten und Angebote aus der Reisebranche sowie spannende Reisereportagen aus aller Welt pr\u00e4sentiert, die verschiedenste touristische, kulinarische und kulturelle Themen abdecken. Die Redaktion w\u00e4hlt f\u00fcr die Leser von FineArtReisen gezielt nachhaltig n\u00fctzliche Reiseinformationen aus. Dar\u00fcber hinaus werden literarische Neuerscheinungen aus den Themenspektrum Reise, Fotografie, Kulinarik sowie Kunst und Kultur vorgestellt. Mit ihrer sehr hohen Informationsdichte und der t\u00e4glichen Aktualisierung erzielt die Online-Reisezeitung eine gro\u00dfe Reichweite. Jeder ver\u00f6ffentlichte Beitrag ist zu jeder Zeit \u00fcber das FineArtReisen CMS abrufbar. Zeitlich weiter zur\u00fcckliegende Beitr\u00e4ge werden Jahre sp\u00e4ter noch recherchiert und gelesen.<\/p> <p>Kontakt:<br \/> FineArtReisen<br \/> Armin Rohnen<br \/> Thomas-Diewald-Stra\u00dfe 7<br \/> 82152 Planegg bei M\u00fcnchen<br \/> 089 33 98 46 77<br \/> nachrichten@fineartreisen.de<br \/> http:\/\/fineartreisen.de<\/p> <p>Pressekontakt:<br \/> armini foto &amp; medien verlag gbr<br \/> Armin Rohnen<br \/> Thomas-Diewald-Stra\u00dfe 7<br \/> 82152 Planegg bei M\u00fcnchen<br \/> 089 33 98 46 77<br \/> pressetext@der-pr-service.de<br \/> http:\/\/www.der-pr-service.de<\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Die FineArtReisen Web-Statistik z\u00e4hlt aktuell t\u00e4glich rund 49.890 Leser, welches einen monatlichen Durchschnitt von 1.496.850 Leser ergibt. In Summe sind dies f\u00fcr 2012 rund 17.962.000 Leser mit insgesamt 116.834.947 aufgerufenen Seiten; das bedeutet im Jahresdurchschnitt 6,5 Seiten pro Leser. Im Jahresverlauf schwankten die monatlichen Leserzahlen zwischen 832.000 und maximal 2.353.000. Die h\u00f6chsten Leserzahlen wurden im<\/p>\n","protected":false},"author":1,"featured_media":4847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[104],"tags":[134],"class_list":["post-4733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reisen-touristik","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/4733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=4733"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/4733\/revisions"}],"predecessor-version":[{"id":264426,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/4733\/revisions\/264426"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=4733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=4733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=4733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}