{"id":47352,"date":"2013-09-18T14:22:38","date_gmt":"2013-09-18T14:22:38","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=47352"},"modified":"2022-08-23T09:20:53","modified_gmt":"2022-08-23T08:20:53","slug":"gemueseverbrauch-steigt-um-11-kilogramm-pro-kopf","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/gemueseverbrauch-steigt-um-11-kilogramm-pro-kopf-1047352\/","title":{"rendered":"Gem\u00fcseverbrauch steigt um 1,1 Kilogramm pro Kopf"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"fit mit Gem\u00fcse\" alt=\"fit mit Gem\u00fcse\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/09\/191687-150x150.jpg\" width=\"133\" height=\"133\" \/>Von der Beilage zum kulinarischen Shootingstar: Vielfalt aus Gem\u00fcse<\/p> <p>Auf den B\u00fcchertischen des Buchhandels stapeln sich appetitlich aufgemachte Kochb\u00fccher zur vegetarischen und veganen K\u00fcche. Im Fernsehen pr\u00e4sentieren Spitzenk\u00f6che fantasievolle Gem\u00fcsegerichte. Promis wie der Schauspieler Hannes Jaenicke, die Kaulitz-Br\u00fcder von Tokio Hotel oder Thomas D. von den Fantastischen Vier sind bekennende Vegetarier. Der Gem\u00fcseverzehr steigt seit der Jahrtausendwende kontinuierlich an. Was ist dran am Trend hin zum Gem\u00fcse? Anl\u00e4sslich des Weltvegetariertages am 1. Oktober hat die 5 am Tag-Kampagne genauer hingeschaut.<\/p> <p><!--more-->&#8222;Klar freuen wir uns, dass der Gem\u00fcseverbrauch steigt &#8211; um immerhin 1,1 Kilogramm pro Kopf und Jahr seit dem Jahr 2000. Schlie\u00dflich bedeutet das eine bessere Versorgung mit Vitaminen, Mineralstoffen, sekund\u00e4ren Pflanzenstoffen und Ballaststoffen&#8220;, so Dr. Helmut Oberritter von der Deutschen Gesellschaft f\u00fcr Ern\u00e4hrung.<\/p> <p>Ausprobieren: Ein vegetarischer Tag pro Woche<\/p> <p>Viele Deutsche ern\u00e4hren sich inzwischen vegetarisch. Aber: &#8222;Niemand muss gleich Vegetarier werden, um die Vielfalt von Gem\u00fcse f\u00fcr sich zu entdecken. Eine ausgewogene und abwechslungsreiche ovo-lacto-vegetarische Ern\u00e4hrung &#8211; ohne Fleisch und Fisch, aber mit Eiern und Milchprodukten &#8211; kann als Dauerkost empfohlen werden. Wer sich allerdings vegan ern\u00e4hrt und komplett auf tierische Produkte verzichtet, hat das Risiko, nicht ausreichend mit Protein, Eisen, Calcium, Jod, Zink, Vitamin B2, Vitamin B12, Vitamin D kommen und langkettigen n-3 Fetts\u00e4uren versorgt zu sein. Dies gilt vor allem f\u00fcr Kinder&#8220;, so Oberritter weiter.<\/p> <p>F\u00fcr alle machbar: Ein vegetarischer Tag pro Woche ist ein Schritt hin zu mehr Gem\u00fcse und Obst. Ein solcher Tag startet zum Beispiel mit einem Obstsalat mit M\u00fcsli zum Fr\u00fchst\u00fcck. Als zweites Fr\u00fchst\u00fcck folgt ein Vollkornbrot mit Kr\u00e4uterquark oder einem vegetarischen Brotaufstrich. Zu Mittag schmeckt ein Gem\u00fcse-Eintopf oder ein gro\u00dfer Teller mit knackigem Wok-Gem\u00fcse und Reis. Diese &#8222;Gem\u00fcsemahlzeiten&#8220; ohne Fleisch und Fisch liegen im Trend, k\u00f6nnen leicht variiert werden und sind eine echte Bereicherung f\u00fcr den w\u00f6chentlichen Speiseplan. Nachmittags reicht ein St\u00fcck Obst der Saison. Und zum Abendessen gibt es dann einen gro\u00dfen Teller frischer Salate mit verschiedenen K\u00e4sesorten. &#8222;Wer einen fleischlosen Tag pro Woche \u00fcber einen l\u00e4ngeren Zeitraum praktiziert, entdeckt viele neue Rezepte, andere Gem\u00fcsesorten und lernt, sukzessive mehr Gem\u00fcse und Obst in die Mahlzeiten einzubauen. Das ist der einfachste Weg, um es dauerhaft auf die empfohlenen f\u00fcnf Portionen Gem\u00fcse und Obst zu schaffen&#8220;, so die Erfahrung von Oberritter.<\/p> <p>Warenkunde und Rezepte bei 5 am Tag<\/p> <p>Wer Informationen und Rezepte rund um Gem\u00fcse und Obst sucht, ist auf den verschiedenen Webseiten der von der Europ\u00e4ischen Union gef\u00f6rderten 5 am Tag-Kampagne richtig: Von Einkaufstipps \u00fcber Saisonkalender, Warenkunden und Rezepte ist hier alles zu finden. Zudem motivieren die 5 am Tag-Experten dazu, Gem\u00fcse und Kr\u00e4uter selbst anzubauen &#8211; zum Beispiel auf dem Balkon oder einem kleinen Beet im Garten. Gurken, Tomaten, Erdbeeren und vieles anderes w\u00e4chst sehr gut auf kleinem Raum, zum Beispiel in Blumenk\u00e4sten oder Pflanzampeln. Und wer es bunt mag, pflanzt zus\u00e4tzlich bunt bl\u00fchende Kapuzinerkresse, Borretsch oder Blumen mit essbaren Bl\u00fcten.<\/p> <p>Infos aus dem Internet:<\/p> <p>www.machmit-5amtag.de: Hier gibt es Informationen rund um die 5 am Tag-Kampagne, Rezepte, Tipps f\u00fcr Berufst\u00e4tige und f\u00fcr den Einkauf sowie Services f\u00fcr Lehrer und Kinder. Im Downloadbereich gibt es zahlreiche Informationsmaterialien.<\/p> <p>www.5amtag-garten.de: Wissenswertes zum G\u00e4rtnern auf kleinster Fl\u00e4che von A wie Anbau bis Z wie Zubereitungstipps mit Aktionen f\u00fcr Schulklassen und vieles mehr.<\/p> <p>www.frucht-arbeitsplatz.de: Wie k\u00f6nnen sich Berufst\u00e4tige am Arbeitsplatz mit Gem\u00fcse und Obst versorgen? 5 am Tag vernetzt auf dieser Seite Lieferanten und Arbeitnehmer, die bei der Arbeit nicht auf den t\u00e4glichen Vitaminkick verzichten m\u00f6chten.<\/p> <p>Foto: www.machmit-5amtag.de<\/p> <p>Hintergrundinformationen zur 5 am Tag-Kampagne:<br \/> 5 am Tag ist eine Ern\u00e4hrungskampagne, die sich daf\u00fcr engagiert, dass die Menschen t\u00e4glich 5 Portionen Obst und Gem\u00fcse essen &#8211; das entspricht einer Menge von 650 Gramm f\u00fcr Erwachsene. Die deutsche 5 am Tag-Kampagne ist ein gemeinn\u00fctziger eingetragener Verein. Zu den Mitgliedern geh\u00f6ren renommierte wissenschaftliche Fachgesellschaften wie die Deutsche Gesellschaft f\u00fcr Ern\u00e4hrung und die Deutsche Krebsgesellschaft, Krankenkassen, Ministerien, Stiftungen sowie zahlreiche Partner aus der Wirtschaft. Die Kampagne wird seit 2002 von der Europ\u00e4ischen Union mitfinanziert. Die Aussagen der 5 am Tag-Kampagne werden kontinuierlich von einem Expertengremium auf ihre wissenschaftliche Begr\u00fcndung und Richtigkeit \u00fcberwacht. Bundesern\u00e4hrungsministerin Ilse Aigner (Bundesministerium f\u00fcr Ern\u00e4hrung, Landwirtschaft und Verbraucherschutz) und Bundesgesundheitsminister Daniel Bahr (Bundesministerium f\u00fcr Gesundheit) sind derzeit Schirmherren der 5 am Tag-Kampagne.<\/p> <p>Kontakt:<br \/> Serviceb\u00fcro 5 am Tag e.V.<br \/> Thomas Erdmann<br \/> Carl-Reuther-Str. 1<br \/> 68305 Mannheim<br \/> 0621 33840-114<br \/> info@machmit-5amtag.de<br \/> http:\/\/www.machmit-5amtag.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Von der Beilage zum kulinarischen Shootingstar: Vielfalt aus Gem\u00fcse Auf den B\u00fcchertischen des Buchhandels stapeln sich appetitlich aufgemachte Kochb\u00fccher zur vegetarischen und veganen K\u00fcche. Im Fernsehen pr\u00e4sentieren Spitzenk\u00f6che fantasievolle Gem\u00fcsegerichte. Promis wie der Schauspieler Hannes Jaenicke, die Kaulitz-Br\u00fcder von Tokio Hotel oder Thomas D. von den Fantastischen Vier sind bekennende Vegetarier. Der Gem\u00fcseverzehr steigt seit<\/p>\n","protected":false},"author":1,"featured_media":153148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[96],"tags":[134],"class_list":["post-47352","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ernaehrung-wellness-gesundheit","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/47352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=47352"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/47352\/revisions"}],"predecessor-version":[{"id":268061,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/47352\/revisions\/268061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/153148"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=47352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=47352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=47352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}