{"id":53503,"date":"2013-10-21T07:25:09","date_gmt":"2013-10-21T07:25:09","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=53503"},"modified":"2015-08-04T09:39:06","modified_gmt":"2015-08-04T08:39:06","slug":"die-herkulesaufgabe-arbeitswelt","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/die-herkulesaufgabe-arbeitswelt-1053503\/","title":{"rendered":"Die Herkulesaufgabe Arbeitswelt"},"content":{"rendered":"<p>Agenda 2020: Braucht Deutschland einen neuen Sozialpakt?<br \/> Die neue Bundesregierung wird vor einer Herkulesaufgabe stehen: Es gilt, die Arbeitswelt neu zu gestalten, denn diese hat sich in den vergangenen Jahrzehnten grundlegend gewandelt, was das Ergebnis unterschiedlicher Einflussfaktoren ist:<\/p> <p>Der demographische Wandel f\u00fchrt zu einer Verl\u00e4ngerung der Lebensarbeitszeit. Auch werden Frauen in der Arbeitswelt respektive F\u00fchrungspositionen verst\u00e4rkt eine wichtige Rolle \u00fcbernehmen m\u00fcssen. Der Bildungssektor, von der Kindergrippe bis zur Universit\u00e4t, muss diesen Ver\u00e4nderungen ebenfalls Rechnung tragen.<\/p> <p><!--more-->Die immer gr\u00f6\u00dfer werdende \u00d6ffnung der Einkommensschere ersch\u00fcttert die Grundlagen unseres Gemeinwesens. Hiervon zeugt auch die Zunahme des Niedriglohnsektors und der Anstieg der Armutsgef\u00e4hrdung. Dies f\u00fchrt unter anderem dazu, dass der Staat durch Transferzahlungen den Lebensunterhalt von immer mehr Menschen sichern muss. Gleichzeitig steigen die Einkommen der oberen 10 Prozent \u00fcberproportional! Die niedrigen Geburtenzahlen m\u00fcssen durch eine verst\u00e4rkte, aber organisierte Einwanderung ausgeglichen werden.<\/p> <p>Die Globalisierung f\u00fchrt auch zu einer verst\u00e4rkten \u00dcbernahme von Unternehmen durch ausl\u00e4ndische Kapitaleigner: Das Management der Unternehmen wird internationaler! Selbst deutsche Traditionsunternehmen werden zwischenzeitlich verst\u00e4rkt durch ausl\u00e4ndische Manager gef\u00fchrt. Dieser Wandel der Unternehmens- und der Arbeitswelt wird noch weiter an Dynamik zunehmen.<\/p> <p>In dem jetzt im Springer-Gabler-Verlag von Andr\u00e9 Papmehl und Hans J. T\u00fcmmers herausgegebenen Buch \u201eDie Arbeitswelt im 21. Jahrhundert\u201c untersuchen anerkannte Autoren aus Wirtschaft, Wissenschaft und Gesellschaft die beschriebenen Herausforderungen und zeigen L\u00f6sungswege mit dem Ziel auf &#8211; eine breite Diskussion anzusto\u00dfen. Nach der mit handwerklichen Fehlern behafteten Agenda 2010 &#8211; vertreten die Herausgeber den Standpunkt, dass eine &#8222;Agenda 2020&#8220; dringend erforderlich ist.<\/p> <p>Link zum Buch: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.amazon.de\/Die-Arbeitswelt-21-Jahrhundert-Herausforderungen\/dp\/3658014156\/ref=sr_1_1?ie=UTF8&amp;qid=1359113262&amp;sr=8-1\" title=\"Die Arbeitswelt im 21. Jahrhundert\" >www.amazon.de\/Die-Arbeitswelt-21-Jahrhundert-Herausforderungen\/dp\/3658014156\/ref=sr_1_1?ie=UTF8&amp;qid=1359113262&amp;sr=8-1<\/a><\/p> <p>Papmehl Management Consulting | Personal- &amp; Organisationsberatung:<\/p> <p>Die lernende Organisation gestalten&#8230;<\/p> <p>Unsere Kunden unterst\u00fctzen wir in den Bereichen Interim Management, Personal- und Organisationsentwicklung<\/p> <p>Zielsetzung ist die Realisierung von nachhaltigem Wachstum f\u00fcr Ihre Organisation durch motivierte Menschen<\/p> <p>Ma\u00dfgeschneiderte L\u00f6sungen f\u00fcr Ihren Erfolg<\/p> <p>Kontakt:<br \/> Papmehl Management Consulting<br \/> Andr\u00e9 Papmehl<br \/> Haselweg 7<br \/> 72178 Waldachtal<br \/> 074458523095<br \/> info@papmehl.com<br \/> www.papmehl.com<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Agenda 2020: Braucht Deutschland einen neuen Sozialpakt? Die neue Bundesregierung wird vor einer Herkulesaufgabe stehen: Es gilt, die Arbeitswelt neu zu gestalten, denn diese hat sich in den vergangenen Jahrzehnten grundlegend gewandelt, was das Ergebnis unterschiedlicher Einflussfaktoren ist: Der demographische Wandel f\u00fchrt zu einer Verl\u00e4ngerung der Lebensarbeitszeit. Auch werden Frauen in der Arbeitswelt respektive F\u00fchrungspositionen<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85],"tags":[134],"class_list":["post-53503","post","type-post","status-publish","format-standard","hentry","category-politik-administratives","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/53503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=53503"}],"version-history":[{"count":2,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/53503\/revisions"}],"predecessor-version":[{"id":152500,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/53503\/revisions\/152500"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=53503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=53503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=53503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}