{"id":591,"date":"2010-07-22T11:40:57","date_gmt":"2010-07-22T10:40:57","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=591"},"modified":"2015-01-02T09:10:58","modified_gmt":"2015-01-02T08:10:58","slug":"sicheres-buero","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/sicheres-buero-10591\/","title":{"rendered":"Das sichere B\u00fcro"},"content":{"rendered":"<p>Das B\u00fcro ist nicht nur der Arbeitsplatz von Millionen Menschen, es beherbergt in vielen F\u00e4llen auch wichtige Akten mit manchmal brisanten Inhalten, welche f\u00fcr Dritte interessant sein k\u00f6nnten. Dar\u00fcber hinaus k\u00f6nnen sich Wertgegenst\u00e4nde oder gr\u00f6\u00dfere Geldmengen in einem B\u00fcro befinden. Aus diesen Gr\u00fcnden muss ein B\u00fcro optimal gesichert werden, um Einbrechern keine Chance zu geben.<!--more--><\/p> <p>Grundlegende M\u00f6glichkeiten der Einbruchsicherung f\u00fcr B\u00fcros<\/p> <p>Je nach Lage und Ausstattung hat ein B\u00fcro unterschiedliche Anforderungen an die perfekte Absicherung. Es kommen dem Grunde nach die gleichen M\u00f6glichkeiten infrage wie bei der Sicherung von H\u00e4usern, Gesch\u00e4ften und anderen Geb\u00e4uden. Gerade kleine B\u00fcros haben jedoch einen erh\u00f6hten Sicherheitsbedarf. Sie sind f\u00fcr Einbrecher ein beliebtes und einfaches Angriffsziel. B\u00fcros in gro\u00dfen Geb\u00e4udekomplexen sind aufgrund eines Sicherheitsdienstes weniger angriffsf\u00e4llig. Wer sich ein solches B\u00fcro nicht leisten kann, greift auf traditionelle Sicherheitstechniken wie eine Alarmanlage, ein Querriegelschloss beziehungsweise die \u00dcberwachung durch Sensoren oder eine Minikamera zur\u00fcck. Zus\u00e4tzlich sind Sicherheitst\u00fcren sehr effizient und sch\u00fctzt zudem noch vor Feuer. Die Realisierung ist jedoch nicht immer einfach und bedarf vorheriger Beratung durch eine Sicherheitsfirma. Letztlich h\u00e4ngt viel vom erforderten Sicherheitsstandart und den baulichen Gegebenheiten ab.<\/p> <p>Die Alarmanlage als flexible Sicherungsmethode<\/p> <p>Eine Alarmanlage besticht durch eine vergleichsweise einfache Installation. Die neuen M\u00f6glichkeiten der drahtlosen Daten\u00fcbertragung in Verbindung mit Monitoren oder einem Computer machen sie zu einer sehr beliebten und h\u00e4ufig eingesetzten Sicherungsmethode. Sie ist sehr flexibel anwendbar und es bedarf keiner gro\u00dfartigen, baulichen Ver\u00e4nderungen. Eine gute Alarmanlage verbindet drei grunds\u00e4tzliche Sicherungstechniken: Sie wird an einer sichtbaren Stelle angebracht, um die T\u00e4ter abzuschrecken. Sobald ein Dieb probiert in ein B\u00fcro einzubrechen ert\u00f6nt ein lautes Alarmsignal. Zus\u00e4tzlich wird automatisch ein Sicherheitsdienst oder die Polizei alarmiert. Diese Ma\u00dfnahme kostet extra, ist aber besonders dann sinnvoll, wenn sie Wertgegenst\u00e4nde im B\u00fcro befinden. Die Aktivierung erfolgt mittels einer Schaltzentrale oder Fernbedienung und wird durch permanentes Blinken einer Leuchte angezeigt. Ein angeschlossener Computer zeichnet alle Geschehnisse minuti\u00f6s auf. Die Sicherungsm\u00f6glichkeiten durch eine Alarmanlage k\u00f6nnen sehr vielschichtig sein. In der Regel werden T\u00fcren und Fenster einbezogen, auch ein Bewegungsmelder im Inneren des B\u00fcros ist sinnvoll. Empfehlenswerte Hersteller sind beispielsweise ABUS-Secvest und Secutek.<\/p> <p>Eine Minikamera als kleine Schwester der Alarmanlage<\/p> <p>\u00dcberwachung ohne Alarm bieten die Minikamera, welche unsichtbar an einer Stelle im B\u00fcro platziert wird. Auch sie ist an einen Computer angeschlossen, welcher f\u00fcr einen optimalen Schutz permanent eingeschaltet sein sollte. Dies bietet sich demnach nur f\u00fcr kleine B\u00fcros an, da sonst der technische Aufwand an Computern und Vernagelungen nicht im Verh\u00e4ltnis stehen w\u00fcrde. Die Firma AVWare ist mit einem weitreichenden Spektrum an Ger\u00e4te f\u00fcr die B\u00fcroabsicherung einer der weltweit f\u00fchrenden Hersteller von Minikameras.<\/p> <p>Die Sicherheitst\u00fcr verhindert unbefugtes Eindringen und sch\u00fctzt vor Feuer<\/p> <p>Bei einer Sicherheitst\u00fcr handelt es sich um eine bauliche Ver\u00e4nderung, welche nicht in allen Geb\u00e4uden durchgef\u00fchrt werden kann oder darf. Vor allem in B\u00fcros mit Publikumsverkehr ist die Installation einer Sicherheitst\u00fcr ausgeschlossen. In Gro\u00dfraumb\u00fcros befindet sich die Sicherheitst\u00fcr in der Regel vor R\u00e4umen, in denen sich Geld oder andere Wertgegenst\u00e4nde befinden. Dabei sind die T\u00fcren von au\u00dfen nicht gleich als Sicherheitst\u00fcren zu erkennen, wodurch sie sich besser in die bestehende B\u00fcroumgebung eingliedern. Sogar T\u00fcren mit Holzfurnier im Altbau-Stil sind keine Seltenheit. Zudem sind Sicherheitst\u00fcren in unterschiedlichen Widerstandsklassen erh\u00e4ltlich. Somit ist gew\u00e4hrleistet, dass f\u00fcr jeden Einsatzweck eine passende T\u00fcr gefunden werden kann. Die Firma Biffar geh\u00f6rt neben Secustar zu den gr\u00f6\u00dften Herstellern f\u00fcr Sicherheitst\u00fcren.<\/p> <p>Das Querriegelschloss f\u00fcr kleine B\u00fcros<\/p> <p>Ein Querriegelschloss kann ohne gro\u00dfen baulichen Aufwand an allen T\u00fcren angebracht werden. Durch die im Mauerwerk verankerten Schlie\u00dfk\u00e4sten wird das Aufsperren der T\u00fcr erheblich erschwert. Hochwertige Querriegelschl\u00f6sser der Marke Abus gibt es schon ab circa 160,- Euro. Das Querriegelschloss hat von allen vorgestellten Sicherungsm\u00f6glichkeiten das beste Preis- \/ Leistungsverh\u00e4ltnis und sollte daher in jedes neue B\u00fcro eingebaut werden.<\/p> <p>&#8212;&#8212;&#8212;&#8212;-<br \/> Netbird Ltd.<br \/> Schlo\u00dfstra\u00dfe 107<br \/> 12163 Berlin<br \/> +49 30 577 087 04 9<br \/> www.storebird.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Das B\u00fcro ist nicht nur der Arbeitsplatz von Millionen Menschen, es beherbergt in vielen F\u00e4llen auch wichtige Akten mit manchmal brisanten Inhalten, welche f\u00fcr Dritte interessant sein k\u00f6nnten. Dar\u00fcber hinaus k\u00f6nnen sich Wertgegenst\u00e4nde oder gr\u00f6\u00dfere Geldmengen in einem B\u00fcro befinden. Aus diesen Gr\u00fcnden muss ein B\u00fcro optimal gesichert werden, um Einbrechern keine Chance zu geben.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91],"tags":[],"class_list":["post-591","post","type-post","status-publish","format-standard","hentry","category-technik"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=591"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/591\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}