{"id":5972,"date":"2013-01-09T07:40:33","date_gmt":"2013-01-09T07:40:33","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=5972"},"modified":"2013-01-09T16:48:15","modified_gmt":"2013-01-09T15:48:15","slug":"wissensschatz-fuer-die-produktentwicklung","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wissensschatz-fuer-die-produktentwicklung-105972\/","title":{"rendered":"Wissensschatz f\u00fcr die Produktentwicklung"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"Das Unternehmen wurde Anfang 2000 als Spin-Off des Produktionstechnischen Zentrums (PTZ), einer gemeinschaftlichen Einrichtung des Instituts f\u00fcr Werkzeugmaschinen und Fabrikbetrieb (IWF) der Technischen Universit\u00e4t Berlin (TU Berlin) und des Fraunhofer-Instituts f\u00fcr Produktionsanlagen und Konstruktionstechnik (Fraunhofer-IPK) gegr\u00fcndet.\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/01\/152384-150x42.jpg\" width=\"150\" height=\"42\" \/>Wissensschatz Produktlebenszyklus<\/p> <p>&nbsp;<\/p> <p>Im Januar 2013 startet das Forschungsprojekt LeWiPro &#8211; Akquisition und Nutzung von Lebenszyklus-Wissen f\u00fcr Produktinnovation. Projekttr\u00e4ger ist das DLR (Deutsches Zentrum f\u00fcr Luft- und Raumfahrt e.V.), gef\u00f6rdert wird das Vorhaben vom Bundesministerium f\u00fcr Bildung und Forschung (BMBF). Die Pumacy Technologies \u00fcbernimmt die Konsortialf\u00fchrung im Projekt.<\/p> <p><!--more-->F\u00fcr deutsche Unternehmen ist die F\u00e4higkeit, innovative Produkte zu entwickeln, eine wesentliche Voraussetzung, um im globalen Wettbewerb zu bestehen. Dabei stellt die bedarfsgerechte Bereitstellung und gezielte Ber\u00fccksichtigung von Wissen aus dem Produktlebenszyklus einen entscheidenden Faktor dar. Entsprechend liegt es nahe, die w\u00e4hrend Produktion und Gebrauch eines Produktes entstehenden enormen digitalen Datenmengen nutzbar zu machen.<\/p> <p>Christian Kind, Bereichsleiter Prozessmanagement bei der Pumacy Technologies AG, erl\u00e4utert dazu: &#8222;In den enormen digitalen Datenmengen, wie etwa aus Produktionsleitsystemen (kurz: MES, Manufacturing Execution Systems) oder in Service-Protokollen, verbirgt sich ein wertvoller Wissensschatz, der besonders f\u00fcr die Produktentwicklung nutzbar gemacht werden kann. Bisher verhinderte jedoch der immense Aufwand zur Ableitung von Wissen aus einer Vielzahl sehr unterschiedlicher Datenquellen eine effektive Nutzung.&#8220;<\/p> <p>Ziel des Forschungsvorhabens ist es, zusammen mit weiteren Partnern Methoden und Softwarewerkzeuge zur effizienten Entwicklung innovativer Produkte auf Basis von Wissen aus dem Produktlebenszyklus zu entwickeln. Dabei soll ein Software-Demonstrator entstehen, der die M\u00f6glichkeiten einer automatisierten Erzeugung von Wissen aus Logistik- und Service-Daten aufzeigt. Dazu werden Erfahrungen und Wissen aus den vorhandenen Daten extrahiert und f\u00fcr die Entwicklung von Produkte bereitstellt.<\/p> <p>&#8222;Im Projekt sollen Daten aus dem Produktlebenszyklus durch den Einsatz moderner informationstechnischer Werkzeuge automatisiert ausgewertet werden. Dazu werden beispielsweise Data-Mining-Algorithmen eingesetzt, um in den Daten Muster zu erkennen und auf diese Weise neues, wertvolles Wissen f\u00fcr Herstellung und Nutzung zuk\u00fcnftiger Produkte zu extrahieren. Daten als einer der wichtigsten Rohstoffe des 21. Jahrhunderts werden so nutzbar gemacht&#8220;, f\u00fcgt Christian Kind hinzu.<\/p> <p>Projektlaufzeit von LeWiPro ist insgesamt 30 Monate. Weitere aktive Partner sind die GTT Gesellschaft f\u00fcr Technologie Transfer mbH, das IPH &#8211; Institut f\u00fcr Integrierte Produktion gGmbH und die Paradigma Software GmbH.<\/p> <p>Anmerkung<\/p> <p>Das Forschungsprojekt LeWiPro &#8211; Innovationsabsicherung in Produktentwicklung und Produktion &#8211; wird mit Mitteln des Bundesministeriums f\u00fcr Bildung und Forschung (BMBF) im Rahmen der BMBF-F\u00f6rderma\u00dfnahme KMU-innovativ: IKT gef\u00f6rdert.<\/p> <p>Pumacy Technologies AG<\/p> <p>Pumacy Technologies AG ist ein f\u00fchrender Anbieter f\u00fcr Wissens-, Prozess- und Innovationsmanagement. In Projekten werden Methoden etabliert, um Software erg\u00e4nzt und in die Organisation integriert. Dabei unterst\u00fctzt ein interdisziplin\u00e4rer Ansatz die individuelle Ausgangslage des Kunden.<\/p> <p>Pumacy arbeitet f\u00fcr internationale Hersteller aus der Luftfahrt- und Automobilindustrie, dem Maschinen- und Anlagenbau sowie den Life Sciences und kann auf Referenzen aus bedeutenden internationalen Projekten verweisen. In den letzten Jahren standen verst\u00e4rkt auch kleine und mittelst\u00e4ndische Unternehmen im Fokus, f\u00fcr die sich Pumacy Technologies als Wegbereiter f\u00fcr Innovation und Wachstum etablierte.<\/p> <p>Kontakt:<br \/> Pumacy Technologies AG<br \/> Claudia Philipp<br \/> Bartningallee 27<br \/> 10557 Berlin<br \/> 030 22161280<br \/> claudia.philipp@pumacy.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.pumacy.de\/\" title=\"Die Pumacy Technologies AG ist ein f\u00fchrender Anbieter f\u00fcr Wissens-, Prozess- und Innovationsmanagement. \" >http:\/\/www.pumacy.de\/<\/a><\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Wissensschatz Produktlebenszyklus &nbsp; Im Januar 2013 startet das Forschungsprojekt LeWiPro &#8211; Akquisition und Nutzung von Lebenszyklus-Wissen f\u00fcr Produktinnovation. Projekttr\u00e4ger ist das DLR (Deutsches Zentrum f\u00fcr Luft- und Raumfahrt e.V.), gef\u00f6rdert wird das Vorhaben vom Bundesministerium f\u00fcr Bildung und Forschung (BMBF). Die Pumacy Technologies \u00fcbernimmt die Konsortialf\u00fchrung im Projekt.<\/p>\n","protected":false},"author":1,"featured_media":152791,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[134],"class_list":["post-5972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wirtschaft-industrie","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/5972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=5972"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/5972\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152791"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=5972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=5972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=5972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}