{"id":7136,"date":"2013-01-14T14:02:35","date_gmt":"2013-01-14T14:02:35","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=7136"},"modified":"2013-01-14T16:38:19","modified_gmt":"2013-01-14T15:38:19","slug":"der-sonnenblume-abgeschaut","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/der-sonnenblume-abgeschaut-107136\/","title":{"rendered":"Der Sonnenblume abgeschaut"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"attachment alighnleft alignleft\" title=\"DEGERenergie ist einer der Pioniere und Technologief\u00fchrer f\u00fcr intelligente Solarnachf\u00fchrsysteme.\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/01\/153050-150x136.jpg\" width=\"123\" height=\"112\" \/>DEGER zeigt auf der CEB in Stuttgart sein neues System zur Eigenversorgung mit Solarenergie<\/p> <p>Die europ\u00e4ischen Verbraucher sollten in Solaranlagen investieren, um sich gegen steigende Energiepreise zu wappnen. Dies empfiehlt das britische Marktforschungsunternehmen GlobalData. DEGER zeigt seine eigens daf\u00fcr entwickelten Systeme auf der Messe Clean Energy Building (CEB) vom 07. bis 09. Februar 2013 in Stuttgart. DEGER ist Weltmarktf\u00fchrer f\u00fcr solare Nachf\u00fchrung und mit seiner Technologie in 51 L\u00e4ndern vertreten.<\/p> <p><!--more-->Die Energiewende ist machbar &#8211; und sie ist erschwinglich. Schon heute k\u00f6nnen sich Privatverbraucher und mittelst\u00e4ndische Unternehmen von \u00f6ffentlichen Netzen und steigenden Strompreisen abkoppeln. M\u00f6glich wird das durch Komplettsysteme, mit denen sich Solarstrom produzieren, speichern und selbst nutzen l\u00e4sst. Auch nachts und an bew\u00f6lkten Tagen. Das ist nicht nur ein aktiver Beitrag zum Umweltschutz, es schont auch den Geldbeutel. Denn wer ein solches System einsetzt, profitiert davon, dass sein Strompreis f\u00fcr die n\u00e4chsten 25 Jahre auf heutigem Niveau bleibt und nicht weiter steigt.<\/p> <p>Die Besucher der CEB in Stuttgart k\u00f6nnen sich selbst davon \u00fcberzeugen, wie einfach und zuverl\u00e4ssig das MSS-Komplettsystem funktioniert, das DEGER seit kurzem auf dem deutschen Markt anbietet. Das System kombiniert leistungsf\u00e4hige Solarmodule mit der von DEGER entwickelten MLD-Nachf\u00fchrtechnologie und einem Akkusystem inklusive Batteriemanagement. (Das K\u00fcrzel MSS steht f\u00fcr &#8222;Maximum Solarpower Storage&#8220;, MLD steht f\u00fcr &#8222;Maximum Light Detection&#8220;).<\/p> <p>Komplettversorgung von Haus und B\u00fcro<br \/> Testanlage liefert rund 7.500 Kilowattstunden im Jahr<\/p> <p>Mit dieser Technologie lassen sich mit einer Modulfl\u00e4che von 22 Quadratmetern in Deutschland rund 6.000 Kilowattstunden Strom im Jahr produzieren. Das gen\u00fcgt, um ein Einfamilienhaus mit B\u00fcro und Elektrofahrzeugen zu versorgen und sich weitgehend vom Strombezug aus dem \u00f6ffentlichen Netz unabh\u00e4ngig zu machen.<\/p> <p>Die Testanlage von DEGER l\u00e4uft seit Herbst 2011. Sie brachte im ersten vollen Kalenderjahr sogar deutlich mehr Ertrag als die genannten 6.000 Kilowattstunden. Dort sind 18 Module vom Typ Sanyo 240 mit einer Gesamtleistung von 4.320 Watt peak installiert. Sie lieferten im Jahr 2012 stolze 7.525 Kilowattstunden Solarstrom.<\/p> <p>DEGER-Gesch\u00e4ftsf\u00fchrer Artur Deger: &#8222;Das ist ein sensationelles Ergebnis, das unsere Erwartungen deutlich \u00fcbertrifft. Nat\u00fcrlich haben wir einen Teil davon wohl auch unserem Standort zu verdanken: Das System hat freie Sicht vom \u00f6stlichen bis zum westlichen Horizont. Und es ist in dieser Region sehr selten neblig.&#8220; Damit liefert die Anlage nicht nur gen\u00fcgend Solarstrom f\u00fcr den Eigenverbrauch, sie unterst\u00fctzt auch die Warmwasseraufbereitung des Hauses in durchaus nennenswertem Umfang.<\/p> <p>Weitere Anlagen sind seit Herbst vergangenen Jahres in Betrieb. Und auch sie zeigen: Die Rechnung geht auf. Der Nutzer einer solchen Anlage bezahlt ab dem ersten Tag f\u00fcr seinen selbst produzierten Solarstrom nicht mehr als f\u00fcr Strom aus dem \u00f6ffentlichen Netz. In diese Kalkulation sind s\u00e4mtliche Installations- und Wartungskosten eingerechnet. Und das Beste: Dieser Strompreis gilt f\u00fcr die von DEGER prognostizierte Lebensdauer des Systems von 25 Jahren. Ein unsch\u00e4tzbarer Vorteil angesichts stetig steigender Energiepreise.<\/p> <p>Der Sonnenblume abgeschaut<\/p> <p>Die MLD-Nachf\u00fchrung richtet die Solarmodule nach dem Prinzip der Sonnenblume immer an der hellsten Stelle aus. Dadurch erzeugt sie nachweislich rund 45 Prozent mehr Solarstrom als starr installierte Systeme. Und nicht nur das: Anders als starre Module liefern nachgef\u00fchrte Systeme gleichm\u00e4\u00dfig \u00fcber den Tag hinweg Solarstrom.<\/p> <p>Entscheidender Vorteil: Der gr\u00f6\u00dfte Teil des Energiebedarfs im Haus oder im Betrieb l\u00e4sst sich sofort und ohne Zwischenspeicherung decken &#8211; der Strom flie\u00dft vom Solarmodul direkt in die Steckdose. Dadurch ben\u00f6tigt der Nutzer deutlich geringere Batteriekapazit\u00e4ten. Und die Batterien werden durch den gleichm\u00e4\u00dfigen Stromfluss sehr schonend aufgeladen. Beides wirkt sich auf die positiv auf die Wirtschaftlichkeit des Gesamtsystems aus.<\/p> <p>&#8222;Die Nachfrage nach solchen L\u00f6sungen, die sich unabh\u00e4ngig von staatlichen Subventionen rechnen und finanzielle Sicherheit f\u00fcr die Zukunft bieten, ist schon jetzt hoch. Und der Bedarf steigt sicher mit jeder Strompreiserh\u00f6hung weiter&#8220;, so Artur Deger.<\/p> <p>DEGER ist Weltmarktf\u00fchrer f\u00fcr solare Nachf\u00fchrsysteme. Weltweit sind rund 50.000 DEGER-Systeme in \u00fcber 51 L\u00e4ndern installiert. Das Unternehmen ist in Spanien, Griechenland, Australien und Nordamerika mit eigenen Niederlassungen vertreten und arbeitet in vielen L\u00e4ndern der Welt mit \u00f6rtlichen Vertriebs- und Service-Partnern zusammen. Die von DEGER patentierte MLD-Technologie erlaubt es, mit Solaranlagen durchschnittlich 45 Prozent Mehrertrag im Vergleich zu starr installierten Systemen zu erzielen.<\/p> <p>DEGER auf der<br \/> Clean Energy Building (CEB)<br \/> Landesmesse Stuttgart<br \/> 07. bis 09. Februar 2013<br \/> Stand Nr. 4D16<\/p> <p>Hinweis f\u00fcr die Redaktion:<br \/> Druckf\u00e4higes Bildmaterial steht hier (http:\/\/www.degerenergie.de\/news-presse\/newsdetails\/article\/deger-zeigt-auf-der-ceb-in-stuttgart-sein-neues-system-zur-eigenversorgung-mit-solarenergie.html?tx_ttnews[backPid]=31&amp;cHash=8db6d0b0894e7b4314840d333cb4907e) am Ende des Pressetextes zum Download bereit. Selbstverst\u00e4ndlich erhalten Sie Bildmaterial auch gerne auf Anfrage an Herbert Grab, Tel.: 07127-5707-10, Mail: herbert.grab@digitmedia-online.de.<\/p> <p>\u00dcber DEGER (<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.DEGERenergie.com\" title=\"solar tracking systems\" >www.DEGERenergie.com<\/a>):<\/p> <p>DEGER ist der f\u00fchrende Hersteller mit dem weltweit gr\u00f6\u00dften Produktportfolio f\u00fcr ein- und zweiachsige solare Nachf\u00fchrsysteme. Seine Marktstellung basiert auf der einzigartigen, von Artur Deger entwickelten, patentierten &#8222;Maximum Light Detection&#8220;- oder MLD-Technologie. Sie erm\u00f6glicht es, die Ertr\u00e4ge von solaren Kraftwerken durch &#8222;intelligente&#8220; Steuerung zu maximieren. Dabei werden die Solarmodule unter Einsatz des MLD-Sensors immer am energiereichsten Punkt am Himmel ausgerichtet. So erzielen MLD-gef\u00fchrte Solaranlagen durchschnittlich 45 Prozent mehr Ertrag als starr installierte Systeme &#8211; in Spitzen liegt dieser Wert sogar noch deutlich h\u00f6her. Mit rund 50.000 installierten Systemen in \u00fcber 51 L\u00e4ndern ist DEGER Weltmarkt- und Technologief\u00fchrer. Das Unternehmen bietet alle produktrelevanten L\u00f6sungen &#8211; von Entwicklung und Planung \u00fcber Produktion und Vertrieb bis hin zu Wartung und Instandhaltung.<\/p> <p>DEGER besch\u00e4ftigt derzeit am Hauptsitz in Horb, in seinen Niederlassungen und bei Zulieferern fast 400 Mitarbeiter. Das Unternehmen wurde 1999 gegr\u00fcndet und erhielt im Jahr 2001 den Erfinderpreis des Landes Baden-W\u00fcrttemberg f\u00fcr den MLD-Sensor. 2005 er\u00f6ffnete DEGER in Spanien seine erste Niederlassung, 2009 folgten Niederlassungen in den USA und Griechenland, seit Sommer 2011 l\u00e4uft die Produktion in Australien. Produziert wird in Deutschland, Australien, Kanada und den USA. Die Gesch\u00e4fte f\u00fchrt Artur Deger.<\/p> <p>Auf das Wetter ist nicht immer Verlass. Auf ein intelligentes Steuerungssystem von DEGER schon.<\/p> <p>Kontakt:<br \/> DEGER<br \/> Anita Deger<br \/> Industriestra\u00dfe 70<br \/> 72160 Horb<br \/> +49 (0) 7451-539 14-0<br \/> sales@DEGERenergie.com<br \/> http:\/\/www.DEGERenergie.com<\/p> <p>Pressekontakt:<br \/> digit media<br \/> Herbert Grab<br \/> Schulberg 5<br \/> 72124 Pliezhausen<br \/> +49 (0)7127-570710<br \/> herbert.grab@digitmedia-online.de<br \/> http:\/\/www.digitmedia-online.de<\/p> <p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>DEGER zeigt auf der CEB in Stuttgart sein neues System zur Eigenversorgung mit Solarenergie Die europ\u00e4ischen Verbraucher sollten in Solaranlagen investieren, um sich gegen steigende Energiepreise zu wappnen. Dies empfiehlt das britische Marktforschungsunternehmen GlobalData. DEGER zeigt seine eigens daf\u00fcr entwickelten Systeme auf der Messe Clean Energy Building (CEB) vom 07. bis 09. Februar 2013 in<\/p>\n","protected":false},"author":1,"featured_media":152772,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[134],"class_list":["post-7136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-umwelt-klima-energie","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/7136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=7136"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/7136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media\/152772"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=7136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=7136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=7136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}