{"id":8946,"date":"2013-01-21T16:36:07","date_gmt":"2013-01-21T16:36:07","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/fachbeitraege\/?p=8946"},"modified":"2015-08-18T09:57:08","modified_gmt":"2015-08-18T08:57:08","slug":"medizinische-ebooks-im-epub-format","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/medizinische-ebooks-im-epub-format-108946\/","title":{"rendered":"Medizinische eBooks im EPUB-Format"},"content":{"rendered":"<div> <p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9231\" title=\"eBooks - bis zu 30% billiger als print\" alt=\"\" src=\"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-content\/uploads\/2013\/01\/Screenshot_34.jpg\" width=\"216\" height=\"136\" \/>Effektiver Lesen, Lernen und Nachschlagen mit eBooks<\/p> <p>Wissenschaftsverlag Elsevier setzt auf Medizinfachwissen im EPUB-Format<\/p> <p>Elsevier, das f\u00fchrende Verlagshaus f\u00fcr Wissenschaftsliteratur und Informationen f\u00fcr medizinische Fachberufe, publiziert jetzt sein gesamtes eBook-Sortiment im EPUB-Format und gilt damit als Vorreiter in der Branche. EPUB bietet im Gegensatz zum bei eBooks verbreiteten PDF-Format gerade f\u00fcr lernintensive Fachbereiche zahlreiche Vorteile. So tragen hilfreiche Inhaltsverlinkungen und eine dynamische Textdarstellung zu einer effektiven Wissensaufnahme und Pr\u00fcfungsvorbereitung bei.<\/p> <p><!--more-->Erfolgreiche Wissensvermittlung im Fokus<br \/> \u00c4hnlich wie bei Musik- und Audiodateien gibt es auch f\u00fcr eBooks unterschiedliche Formate. G\u00e4ngig ist beispielsweise das leicht herzustellende PDF-Format, das jedoch in der praktischen Anwendung relativ unflexibel ist. F\u00fcr seine mehr als 500 eBooks verwendet Elsevier daher das EPUB-Format, das auf einer komplexen Programmierung basiert. Dadurch ist es einfach zu nutzen und verf\u00fcgt \u00fcber eine Reihe an Funktionen, die den Lernerfolg unterst\u00fctzen.<\/p> <p>Kapitel\u00fcbergreifende Verlinkungen erm\u00f6glichen, Inhalte \u00fcber die Suchfunktion schnell zu finden. Dabei k\u00f6nnen oft Zusammenh\u00e4nge deutlich werden, die beim Lesen eines eBooks in der PDF-Version bzw. eines gedruckten Buches nicht sofort ins Auge fallen. Mit Hilfe digitaler Lesezeichen ist der Leser in der Lage, wichtige Fachbegriffe zu markieren und f\u00fcr ihn relevante Textpassagen unkompliziert wiederzufinden. Zudem kann flexibel zwischen den Buchkapiteln navigiert werden. Diese Funktionen helfen dem Studierenden zum Beispiel, sich auf seine Lerninhalte zu konzentrieren, ohne wertvolle Zeit beim Suchen bestimmter Begriffe oder Seiten zu verlieren.<\/p> <p>Im Vergleich zu eBooks in der PDF-Version passt das EPUB-Format Textgr\u00f6\u00dfe und Seitenumbr\u00fcche dynamisch an das jeweilige Ausgabeger\u00e4t an und ist so auf einer Vielzahl von eBook-Readern und Tablet-PCs lesbar. Diese sind leicht, platzsparend und verf\u00fcgen \u00fcber Speicherkapazit\u00e4t f\u00fcr mehrere hundert B\u00fccher. Studierenden und Auszubildenden bietet sich damit die M\u00f6glichkeit, die ben\u00f6tigte Fachliteratur problemlos zu transportieren und stets auf medizinisches Expertenwissen zugreifen zu k\u00f6nnen.<\/p> <p>Bereits seit 2011 produziert Elsevier seine eBooks f\u00fcr Mediziner, Pfleger und Heilpraktiker im EPUB-Format: &#8222;Wir haben uns ganz bewusst daf\u00fcr entschieden, unsere eBooks im EPUB-Standard herauszugeben, obwohl dies in der Herstellung wesentlich aufw\u00e4ndiger ist. Uns ist es wichtig, unseren Kunden besten Service zu bieten. eBooks bringen f\u00fcr das Lernen viele Vorz\u00fcge mit sich, die wir den Nutzern nicht vorenthalten m\u00f6chten. Dabei spielt das Format eine entscheidende Rolle&#8220;, erkl\u00e4rt Martin Beck, Finance Director bei Elsevier.<\/p> <p>G\u00fcnstiger als gedruckte B\u00fccher: Medizinische eBooks im EPUB-Format<br \/> Elsevier ver\u00f6ffentlicht das gr\u00f6\u00dfte Sortiment an eBooks im EPUB-Format, die im Preis bis zu 30% unter den Printbuch-Preisen liegen. Darunter befinden sich u.a. renommierte Lexika, Klinikleitf\u00e4den und Repetitorien f\u00fcr Medizinstudenten, Pflegesch\u00fcler und Heilpraktikeranw\u00e4rter. Eine vollst\u00e4ndige \u00dcbersicht finden Sie unter www.elsevier.de\/ebook-deal.<\/p> <p>Elsevier GmbH<br \/> Elsevier ist ein weltweit f\u00fchrender Anbieter von Wissenschaftsliteratur und Informationen rund um die Gesundheit. Das Unternehmen entwickelt Online-Informations-L\u00f6sungen zur Pr\u00fcfungsvorbereitung und publiziert etwa 2.000 Zeitschriften, 20.000 B\u00fccher print und digital sowie wichtige Nachschlagewerke. Der Hauptsitz von Elsevier befindet sich im niederl\u00e4ndischen Amsterdam. Weltweit besch\u00e4ftigt das Unternehmen mehr als 7.000 Mitarbeiter in 24 L\u00e4ndern. Der Verlag blickt auf eine 125j\u00e4hrige Geschichte zur\u00fcck und gilt heute als Innovationstreiber, der seinen Kunden Weltklasse-Informationen mit modernsten Technologien zur Verf\u00fcgung stellt.<\/p> <p>Kontakt:<br \/> Maisberger GmbH<br \/> Jennifer Appel<br \/> Claudius-Keller-Str. 3c<br \/> 81669 M\u00fcnchen<br \/> 089 41 95 99 77<br \/> elsevier@maisberger.com<br \/> http:\/\/www.elsevier.de\/ebook-deal<\/p> <p>&nbsp;<\/p> <\/div>","protected":false},"excerpt":{"rendered":"<p>Effektiver Lesen, Lernen und Nachschlagen mit eBooks Wissenschaftsverlag Elsevier setzt auf Medizinfachwissen im EPUB-Format Elsevier, das f\u00fchrende Verlagshaus f\u00fcr Wissenschaftsliteratur und Informationen f\u00fcr medizinische Fachberufe, publiziert jetzt sein gesamtes eBook-Sortiment im EPUB-Format und gilt damit als Vorreiter in der Branche. EPUB bietet im Gegensatz zum bei eBooks verbreiteten PDF-Format gerade f\u00fcr lernintensive Fachbereiche zahlreiche Vorteile.<\/p>\n","protected":false},"author":1,"featured_media":9231,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128],"tags":[134],"class_list":["post-8946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wissenschaftliche-publikationen","tag-default"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/8946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/comments?post=8946"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/8946\/revisions"}],"predecessor-version":[{"id":160928,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/posts\/8946\/revisions\/160928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/media?parent=8946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/categories?post=8946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/fachbeitraege\/wp-json\/wp\/v2\/tags?post=8946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}