{"id":10145,"date":"2010-09-15T16:17:11","date_gmt":"2010-09-15T15:17:11","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=10145"},"modified":"2018-07-13T12:12:24","modified_gmt":"2018-07-13T11:12:24","slug":"agentur-produktsuche","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/agentur-produktsuche-1010145\/","title":{"rendered":"Deutschlands erste Agentur f\u00fcr die Google Produktsuche"},"content":{"rendered":"<table style=\"float: left; height: 109px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"130\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-10148\" title=\"logo-products-up-200.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/10145\/logo-products-up-200.jpg\" alt=\"\" width=\"116\" height=\"116\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/10145\/logo-products-up-200.jpg 200w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/10145\/logo-products-up-200-150x150.jpg 150w\" sizes=\"auto, (max-width: 116px) 100vw, 116px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Products-Up, die W\u00fcrzburger Spezialisten f\u00fcr die Optimierung der Google Produktsuche, sorgen ab sofort daf\u00fcr, dass die Kunden des Berliner Online-Brillenh\u00e4ndlers Mister Spex noch mehr Durchblick beim Suchen nach der passenden Brille haben.<\/p> <p>Der Online-Handel in Deutschland boomt und hat laut Aussage des Bundesverbandes des Deutschen Versandhandels (BVH) 2009 erstmals den Umsatz des klassischen Versandhandels \u00fcbertroffen. Immer mehr H\u00e4ndler erkennen die Chancen des Absatzkanales Internet und dr\u00e4ngen auf den Markt, der dadurch immer umfangreicher, aber auch un\u00fcbersichtlicher wird. Durch diese F\u00fclle an Angeboten werden viele Produkte in Google nur schlecht oder gar nicht gefunden. An diesem Punkt setzen die Experten von Products-Up an.<!--more--><\/p> <p>\u201eRund 36 Millionen Deutsche \u00fcber 14 Jahre, Tendenz steigend, haben im letzten Jahr online eingekauft (Stand 2009, Quelle: AGOF &#8211; Arbeitsgemeinschaft Online Forschung e.V.). Diese gilt es, mittels gezielter Positionierung der Produkte in Google Shopping, zu informieren und zu einer Aktion zu animieren. Wir unterst\u00fctzen unsere Kunden dabei und sorgen durch die gezielte Anreicherung der Daten daf\u00fcr, dass die Produkte bei den Ergebnislisten der Google Produktsuche ganz oben angezeigt werden\u201c, erkl\u00e4rt Volker Schmidt, Gesch\u00e4ftsf\u00fchrer der Agentur Products-Up.<\/p> <p>\u201eWir freuen uns sehr, dass wir mit Mister Spex eine der aufstrebenden deutschen Versandmarken im Bereich Augenoptik als neuen Partner gewonnen haben. Wir sehen f\u00fcr die Marke in der Produktsuche ein starkes Wachstumspotenzial und sind schon jetzt sehr gespannt auf die kommenden Monate der Zusammenarbeit. Dabei werden wir als Full Service Provider alle notwendigen Schritte rund um Google Universal Search und die Produktsuche vornehmen. Zus\u00e4tzlich erh\u00f6hen wir durch die Pr\u00e4senz in der Produktsuche den Bekanntheitsgrad des Shops.\u201c<\/p> <p>\u201eMister Spex ist schon heute der gr\u00f6\u00dfte Online-Versandh\u00e4ndler f\u00fcr Markenbrillen in Deutschland. Mit interaktiven Beratungsdienstleistungen auf der Website und pers\u00f6nlicher Unterst\u00fctzung durch ein kompetentes Augenoptiker-Team helfen wir unseren Kunden, die richtige Brille zu finden\u201c, so Dirk Graber, Gesch\u00e4ftsf\u00fchrer der Mister Spex GmbH. \u201eUm eine m\u00f6glichst breite Zielgruppe zu erreichen und diese im Internet an den richtigen Stellen abzuholen, setzen wir bei der Kommunikation neben TV-Werbung in erster Linie auf Online-Marketing wie Suchmaschinenoptimierung. Products-Up hat uns mit ihrem Know-how im Bereich der Google Universal Search und Produktsuche \u00fcberzeugt. Wir freuen uns auf die Kooperation und hoffen, dass wir unsere Positionierungen in Google durch die Optimierungserfahrung von Products-Up wesentlich verbessern werden. Dies ist ein wichtiger Pfeiler f\u00fcr unsere Marketingstrategie und damit f\u00fcr das weitere Wachstum von Mister Spex.\u201c<\/p> <p>Weitere Informationen \u00fcber den Online-Brillenh\u00e4ndler Mister Spex sind unter http:\/\/misterspex.de erh\u00e4ltlich. Ausf\u00fchrliche Informationen \u00fcber die Agentur Products-Up sowie zu den aktuellen Dienstleistungen der Google Base Agentur sind im Internet unter http:\/\/www.products-up.de abrufbar.<\/p> <p>Verwendung honorarfrei, Beleghinweis erbeten<br \/> 431 W\u00f6rter, 3.194 Zeichen mit Leerzeichen<\/p> <p>Ansprechpartner f\u00fcr R\u00fcckfragen zu dieser Pressemitteilung:<\/p> <p>(1) Products-Up GmbH<\/p> <p>Ansprechpartner: Volker Schmidt<\/p> <p>Products-Up GmbH<br \/> Neutorstr. 12<br \/> D-97070 W\u00fcrzburg<\/p> <p>Telefon: +49 (0) 800 \u2013 10 80 50 04 01<br \/> Fax: +49 (0) 180 5 33 50 11 &#8211; 5 56<br \/> E-Mail: vs@products-up.de<br \/> Internet: http:\/\/www.products-up.de<\/p> <p>(2) PR-Agentur PR4YOU<\/p> <p>Ansprechpartner: Marko Homann, Holger Ballwanz<\/p> <p>PR-Agentur PR4YOU<br \/> Schonensche Stra\u00dfe 43<br \/> D-13189 Berlin<\/p> <p>Telefon: +49 (0) 30 43 73 43 43<br \/> Fax: +49 (0) 30 44 67 73 99<br \/> E-Mail: presse@pr4you.de<br \/> Internet: http:\/\/www.pr4you.de<\/p> <p>\u00dcber die Products-Up GmbH<\/p> <p>Die Agentur Products-Up wurde als Deutschlands erste Google Base Agentur im M\u00e4rz 2010 gegr\u00fcndet. Sie bietet Onlineshops und Unternehmen aus dem Bereich E-Commerce als Full Service Provider die M\u00f6glichkeit, ohne zus\u00e4tzlichen Aufwand sofort mehr Traffic auf den Onlineshop oder die Website zu generieren. Dabei hat sich die Online Marketing Agentur auf den Dienst der Google Produktsuche spezialisiert.<\/p> <p>Products-Up l\u00e4dt die Daten zu den Produkten bei der Google Produktsuche hoch, passt diese an die Richtlinien von Google an, reichert die Daten mit einem eigens daf\u00fcr entwickelten Algorithmus zur Optimierung an und sorgt so f\u00fcr eine Relevanzsteigerung der einzelnen Produkte. Mit Products-Up haben Kunden die M\u00f6glichkeit, ihre Produkte nachhaltig und langfristig bei Google auf die Pole Position zu bringen.<\/p> <p>Weitere Informationen \u00fcber Products-Up sowie zu den aktuellen Dienstleistungen und Preisen der Google Base Agentur sind im Internet unter http:\/\/www.products-up.de abrufbar.<\/p>","protected":false},"excerpt":{"rendered":"<p>Products-Up, die W\u00fcrzburger Spezialisten f\u00fcr die Optimierung der Google Produktsuche, sorgen ab sofort daf\u00fcr, dass die Kunden des Berliner Online-Brillenh\u00e4ndlers Mister Spex noch mehr Durchblick beim Suchen nach der passenden Brille haben. Der Online-Handel in Deutschland boomt und hat laut Aussage des Bundesverbandes des Deutschen Versandhandels (BVH) 2009 erstmals den Umsatz des klassischen Versandhandels \u00fcbertroffen.<\/p>\n","protected":false},"author":291,"featured_media":10148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27],"tags":[],"class_list":["post-10145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-werbung-pr-design"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/10145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=10145"}],"version-history":[{"count":1,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/10145\/revisions"}],"predecessor-version":[{"id":269968,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/10145\/revisions\/269968"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/10148"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=10145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=10145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=10145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}