{"id":104162,"date":"2013-10-29T10:57:32","date_gmt":"2013-10-29T09:57:32","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=104162"},"modified":"2013-10-29T14:47:05","modified_gmt":"2013-10-29T13:47:05","slug":"hamburgs-vogelwelt","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/hamburgs-vogelwelt-10104162\/","title":{"rendered":"Hamburgs Vogelwelt"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" style=\"margin: 0px 10px 10px 0px;\" title=\"Neuerscheinung Buch &quot;Hamburgs V\u00f6gel - Die 77 h\u00e4ufigsten Arten&quot;\" alt=\"Bild\" src=\"http:\/\/pm.connektar.de\/kultur-kunst\/buch-neuerscheinung-hamburgs-voegel-die-77-haeufigsten-arten-16139\/anhang\/hambvoegeltitelkl.jpg?b=200&amp;h=200\" width=\"112\" height=\"165\" \/>Buchautor Harald Vieth ver\u00f6ffentlicht neues Werk \u00fcber Hamburgs Vogelwelt.<\/p> <p>Soeben erschienen: &#8220; Hamburgs V\u00f6gel &#8211; Die 77 h\u00e4ufigsten Arten&#8220; von Harald Vieth<\/p> <p>Nachdem der Hamburger Buchautor Harald Vieth bereits drei sch\u00f6ne B\u00fccher \u00fcber Hamburger B\u00e4ume und eines \u00fcber Berliner\/Potsdamer B\u00e4ume ver\u00f6ffentlicht hat, ist nunmehr sein wohl sch\u00f6nstes Werk erschienen, und zwar \u00fcber Hamburgs Vogelwelt.<\/p> <p><!--more-->Das Buch hat 216 Seiten und 204 zum Teil sehr spektakul\u00e4re farbige Vogelabbildungen von 30 Fotografinnen und Fotografen. Au\u00dfer den 77 h\u00e4ufigsten Arten werden 20 weitere vorgestellt, die nicht zu den h\u00e4ufigsten geh\u00f6ren aber besonders h\u00fcbsch oder anderweitig bemerkenswert sind.<\/p> <p>Alle Vogelnamen erscheinen in sechs Fremdsprachen. Sehr viel erf\u00e4hrt man auch \u00fcber den Ursprung der wissenschaftlichen Benennungen.<br \/> Gesch\u00e4tzte 85% der vorgestellten V\u00f6gel kommen auch in anderen Gro\u00dfst\u00e4dten oder Regionen Deutschlands vor.<\/p> <p>Dieses Buch ist sehr informativ, auch f\u00fcr Laien gut lesbar und wird durch Gedichte, Anekdoten und humorige Einsprengsel aufgelockert. Es kann als Bestimmungsbuch und gleichzeitig als unterhaltsame Einf\u00fchrung in die Vogelkunde verwendet werden.<br \/> Wegen seiner sch\u00f6nen Aufmachung ist es auch bestens als Geschenk geeignet.<br \/> Preis: 19,90 EUR (Bei Postversand zzgl. 2 EUR f\u00fcr Porto und Verpackung).<\/p> <p>Bezug direkt beim Autor: Harald Vieth, Hallerstr. 8, 20146 Hamburg, Tel 040\/45 21 09 oder harald@viethworld.net<img decoding=\"async\" alt=\"\" src=\"http:\/\/connekt.connektar.de\/s\/?3f0b-ba-b180a\" \/><\/p> <p>\u00dcber:<\/p> <p>Selbstverlag Harald Vieth<br \/> Herr Harald Vieth<br \/> Halerstra\u00dfe 8<br \/> 20146 Hamburg<br \/> Deutschland<\/p> <p>fon ..: 040\/452109<br \/> web ..: <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.viethverlag.de\" title=\"B\u00fccher-Beitr\u00e4ge zum Natur-, Umwelt- und Klimaschutz\" target=\"_blank\">http:\/\/www.viethverlag.de<\/a><br \/> email : harald@viethworld.net<\/p> <p>Pressekontakt:<\/p> <p>Selbstverlag Harald Vieth<br \/> Herr Harald Vieth<br \/> Halerstra\u00dfe 8<br \/> 20146 Hamburg<\/p> <p>fon ..: 040\/452109<br \/> web ..: http:\/\/www.viethverlag.de<br \/> email : harald@viethworld.net<\/p>","protected":false},"excerpt":{"rendered":"<p>Buchautor Harald Vieth ver\u00f6ffentlicht neues Werk \u00fcber Hamburgs Vogelwelt.<\/p>\n","protected":false},"author":371,"featured_media":196842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8807],"tags":[4351,4350,4349,4348],"class_list":["post-104162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tiere","tag-die-77-haeufigsten-vogelarten-hamburgs","tag-hamburger-vogelwelt","tag-hamburgs-voegel","tag-neuerscheinung-buch"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/104162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/371"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=104162"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/104162\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/196842"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=104162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=104162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=104162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}