{"id":10874,"date":"2010-10-15T07:23:20","date_gmt":"2010-10-15T06:23:20","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=10874"},"modified":"2010-10-15T07:24:05","modified_gmt":"2010-10-15T06:24:05","slug":"loesung-wlan-kastellaun","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/loesung-wlan-kastellaun-1010874\/","title":{"rendered":"L\u00f6sung f\u00fcr Gratis-WLAN in Kastellaun"},"content":{"rendered":"<table style=\"float: left; height: 34px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\" width=\"209\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-10877\" title=\"Hotsplots-LogoL.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/10874\/Hotsplots-LogoL-300x56.jpg\" alt=\"\" width=\"199\" height=\"37\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/10874\/Hotsplots-LogoL-300x56.jpg 300w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/10874\/Hotsplots-LogoL.jpg 323w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Berlin, 14. Oktober 2010 \u2013 Die im Hunsr\u00fcck gelegene Stadt Kastellaun bietet ihren Einwohnern und G\u00e4sten im Innenstadtbereich kostenloses mobiles Internet und setzt daf\u00fcr auf die Abrechnungs- und Zugangskontroll-L\u00f6sung des Spezialisten HOTSPLOTS. Das Gratis-WLAN von Kastellaun zeigt, dass auch kleine Kommunen schnell, unkompliziert und vor allem zu geringen Kosten eine mobile Internet-L\u00f6sung realisieren k\u00f6nnen.<\/p> <p>In der im vorderen Hunsr\u00fcck zwischen Rhein, Mosel und Nahe gelegenen idyllischen 5000-Einwohner-Stadt Kastellaun beschloss der Stadtrat k\u00fcrzlich, die Innenstadt fl\u00e4chendeckend mit kostenlosem WLAN zu versorgen.<!--more--> Bei der Umsetzung kann die Stadt auf die langj\u00e4hrige Erfahrung von HOTSPLOTS bauen, deren Angebot f\u00fcr Flexibilit\u00e4t, Komfort und Sicherheit bei minimalem Installationsaufwand steht. Auf die L\u00f6sung des Berliner Spezialisten setzt bundesweit eine mittlerweile vierstellige Zahl von Betreibern, vorwiegend aus dem Hotel- und Gastronomiebereich.<\/p> <p>\u201eKastellaun wird mit dieser Installation zum Musterprojekt f\u00fcr andere Gemeinden,\u201c so Dr. Ulrich Meier, Gesch\u00e4ftsf\u00fchrer der hotsplots GmbH. \u201eDie L\u00f6sung zeigt, dass unser flexibel skalierbares System es erm\u00f6glicht, auch in kleineren St\u00e4dten, schnell, kosteng\u00fcnstig, wartungsfreundlich und mit geringem baulichen Aufwand eine WLAN-Infrastruktur zu schaffen.\u201c<\/p> <p>Von dem Gratis-WLAN sollen vor allem Besucher und Gewerbetreibende profitieren, die in der gesamten Innenstadt rund um den Marktplatz und die Fu\u00dfg\u00e4ngerzone High-Speed-WLAN nutzen k\u00f6nnen. Die Installation erfolgt in Kooperation mit der HIT Hahn Informations-Technologie GmbH &amp; Co. KG aus dem Hunsr\u00fcck. F\u00fcr die notwendige Bandbreite sorgen zwei High-Speed DSL-Leitungen. \u00dcber mehrere Hotspots werden die Bereiche Marktplatz, Unterburg, Rathaus, Haus der Geschichte und Zehntscheune mit drahtlosem Internet versorgt.<\/p> <p>Dr. Marlon Br\u00f6hr, B\u00fcrgermeister von Kastellaun, erlebte in seinem letzten Urlaub in Spanien selbst, wie angenehm es ist, als Tourist in einer Innenstadt kostenlos und bequem im Internet surfen zu k\u00f6nnen: \u201e\u00d6ffentliches WLAN bietet unterwegs einen echten Mehrwert, sei es, um auf dem Mobiltelefon oder Notebook E-Mails zu empfangen, Nachrichten zu lesen oder Informationen zu Stadt und Sehensw\u00fcrdigkeiten abzurufen. Wir freuen uns, diesen Service nun auch unseren G\u00e4sten und Einwohnern anbieten und damit die Attraktivit\u00e4t von Kastellaun insgesamt steigern zu k\u00f6nnen.\u201c<\/p> <p>\u00dcber HOTSPLOTS<br \/> Die hotsplots GmbH ist der Spezialist f\u00fcr die Zugangskontrolle und Abrechnung drahtloser Internetzug\u00e4nge (WLAN-Hotspots). Das HOTSPLOTS-System wird bereits erfolgreich in Hotels, Caf\u00e9s, Kliniken, Marinas, Studentenwohnheimen, Jugendherbergen, auf Campingpl\u00e4tzen sowie in Nachbarschaftsnetzen eingesetzt. Mit der innovativen Abrechnungsl\u00f6sung will HOTSPLOTS seine Stellung als eine f\u00fchrende Marke f\u00fcr das Billing mobiler Internetzug\u00e4nge ausbauen. In Deutschland geh\u00f6rt die hotsplots GmbH nach eigenen Recherchen zu den Top 3-Anbietern. Weitere Informationen sind online verf\u00fcgbar unter:<a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.hotsplots.de\"  > www.hotsplots.de<\/a><\/p> <p>F\u00fcr weitere Informationen wenden Sie sich an:<br \/> united communications GmbH<br \/> Rotherstr. 19, 10245 Berlin<br \/> Peter Link, Manfred Gro\u00dfert<br \/> Tel.: + 49 30 78 90 76 &#8211; 0<br \/> E-Mail: hotsplots@united.de<\/p> <p>oder:<\/p> <p>hotsplots GmbH<br \/> Dr. Ulrich Meier, Dr. J\u00f6rg Ontrup<br \/> Tel.: + 49 30 29 77 348-0<br \/> E-Mail: info@hotsplots.de<\/p>","protected":false},"excerpt":{"rendered":"<p>Berlin, 14. Oktober 2010 \u2013 Die im Hunsr\u00fcck gelegene Stadt Kastellaun bietet ihren Einwohnern und G\u00e4sten im Innenstadtbereich kostenloses mobiles Internet und setzt daf\u00fcr auf die Abrechnungs- und Zugangskontroll-L\u00f6sung des Spezialisten HOTSPLOTS. Das Gratis-WLAN von Kastellaun zeigt, dass auch kleine Kommunen schnell, unkompliziert und vor allem zu geringen Kosten eine mobile Internet-L\u00f6sung realisieren k\u00f6nnen. In<\/p>\n","protected":false},"author":291,"featured_media":198669,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,21],"tags":[],"class_list":["post-10874","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein-sonstiges","category-handy-elektronik-telekommunikation"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/10874","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=10874"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/10874\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198669"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=10874"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=10874"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=10874"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}