{"id":11244,"date":"2010-10-29T08:51:07","date_gmt":"2010-10-29T07:51:07","guid":{"rendered":"http:\/\/www.fachzeitungen.de\/pressemeldungen\/?p=11244"},"modified":"2010-10-29T08:51:07","modified_gmt":"2010-10-29T07:51:07","slug":"kulinarische-mecklenburg-vorpommern","status":"publish","type":"post","link":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/kulinarische-mecklenburg-vorpommern-1011244\/","title":{"rendered":"Tillmann Hahn vertritt seine Wahlheimat Mecklenburg-Vorpommern in kulinarischer Sache"},"content":{"rendered":"<table style=\"float: left; width: 100px;\" border=\"0\" cellspacing=\"0\" cellpadding=\"1\"> <tbody> <tr> <td align=\"center\" bgcolor=\"#ffffff\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-11247\" title=\"THDSC04561_JPEG.jpg\" src=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/11244\/THDSC04561_JPEG-300x180.jpg\" alt=\"\" width=\"134\" height=\"80\" srcset=\"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/11244\/THDSC04561_JPEG-300x180.jpg 300w, https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-content\/uploads\/11244\/THDSC04561_JPEG.jpg 448w\" sizes=\"auto, (max-width: 134px) 100vw, 134px\" \/><\/td> <\/tr> <\/tbody> <\/table> <p>Mecklenburg-Vorpommern ist Gastland auf dem Schweizer Medienball<br \/> Am 30. Oktober 2010 findet in Z\u00fcrich der Schweizer Medienball und Z\u00fcricher Presseball statt. Das diesj\u00e4hrige Gastland Deutschland wird vertreten durch Mecklenburg-Vorpommern.  Es ist die erste Region eines Landes, die auf dem 81. Schweizer Medienball als Partner ernannt wurde.  Sternekoch und K\u00fcchenchef der Yachthafenresidenz Hohe D\u00fcne Tillmann Hahn wird als Repr\u00e4sentant des Urlaubslandes kulinarische K\u00f6stlichkeiten kredenzen.<!--more-->Das Bundesland Mecklenburg-Vorpommern, eines der beliebtesten Reiseziele in Deutschland, wird sich mit Mode, Miss MV und Meer pr\u00e4sentieren. Im 5 Sterne Hotel The Dolder Grand wird Tillmann Hahn seine Wahlheimat M-V in kulinarischer Sache vertreten. Die rund 600 geladenen G\u00e4ste erwartet an diesem fulminanten Abend ein 4-G\u00e4nge-Men\u00fc. Der Sternekoch des Luxushotels Yachthafenresidenz Hohe D\u00fcne wird dabei den ersten Gang mit typischen mecklenburgischen Spezialit\u00e4ten zubereiten.<br \/> Der Landestourismusverband Mecklenburg-Vorpommern wird die Gestaltung der R\u00e4umlichkeiten des Veranstaltungsortes \u00fcbernehmen, verschiedene Filmbeitr\u00e4ge \u00fcber das Urlaubsland sowie Strandk\u00f6rbe vom Landesmarketing und des Tourismusverbandes bringen ein St\u00fcck vom flachen Mecklenburg-Vorpommern in die bergige Schweiz.<br \/> W\u00e4hrend des Germany Travel Mart 2009 in Rostock wurden bereits die Beziehungen zwischen Mecklenburg-Vorpommern und der Schweiz gest\u00e4rkt. So wurden Flugstrecken Z\u00fcrich \u2013 Rostock\/ Laage von M\u00e4rz bis Oktober 2011 und Z\u00fcrich \u2013 Heringsdorf ins Leben gerufen, um die Anreisem\u00f6glichkeiten zu optimieren.<br \/> Ins Leben gerufen wurde der Schweizer Medienball vor 81 Jahren, von der Presse f\u00fcr die Presse. Ziel und Zweck der Wohlt\u00e4tigkeitsveranstaltung, an der Ehreng\u00e4ste aus der Schweizer Wirtschaft, Politik, Kultur und Medien teilnehmen, ist die F\u00f6rderung der Organisation &#8222;Reporter ohne Grenzen&#8220; und der Pressefreiheit.<br \/> Yachthafenresidenz Hohe D\u00fcne<br \/> Yachting &amp; Spa Resort<br \/> Am Yachthafen 1<br \/> 18119 Rostock<br \/> Uta Thiele<br \/> Referent Presse- und \u00d6ffentlichkeitsarbeit<br \/> Tel. 0381 \/ 50 40 62 22<br \/> Mail: presse@yhd.de<br \/> <a target=\"_blank\" rel=\"nofollow\" href=\"http:\/\/www.hohe-duene.de\"  >www.hohe-duene.de<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Mecklenburg-Vorpommern ist Gastland auf dem Schweizer Medienball Am 30. Oktober 2010 findet in Z\u00fcrich der Schweizer Medienball und Z\u00fcricher Presseball statt. Das diesj\u00e4hrige Gastland Deutschland wird vertreten durch Mecklenburg-Vorpommern. Es ist die erste Region eines Landes, die auf dem 81. Schweizer Medienball als Partner ernannt wurde. Sternekoch und K\u00fcchenchef der Yachthafenresidenz Hohe D\u00fcne Tillmann Hahn<\/p>\n","protected":false},"author":291,"featured_media":198640,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-11244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein-sonstiges"],"_links":{"self":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/11244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/users\/291"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/comments?post=11244"}],"version-history":[{"count":0,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/posts\/11244\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media\/198640"}],"wp:attachment":[{"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/media?parent=11244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/categories?post=11244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fachzeitungen.de\/pressemeldungen\/wp-json\/wp\/v2\/tags?post=11244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}